{"id":1722726,"date":"2025-09-30T21:40:13","date_gmt":"2025-09-30T18:40:13","guid":{"rendered":"https:\/\/teknomers.com\/fr\/egan-bernal-a-ameliore-sa-position-au-classement-uci-malgre-une-mauvaise-journee-au-championnat-du-monde-de-cyclisme-au-rwanda\/"},"modified":"2025-09-30T21:40:19","modified_gmt":"2025-09-30T18:40:19","slug":"egan-bernal-a-ameliore-sa-position-au-classement-uci-malgre-une-mauvaise-journee-au-championnat-du-monde-de-cyclisme-au-rwanda","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/egan-bernal-a-ameliore-sa-position-au-classement-uci-malgre-une-mauvaise-journee-au-championnat-du-monde-de-cyclisme-au-rwanda\/","title":{"rendered":"Egan Bernal a am\u00e9lior\u00e9 sa position au classement UCI, malgr\u00e9 une mauvaise journ\u00e9e au Championnat du Monde de Cyclisme au Rwanda."},"content":{"rendered":"\n<h2>Le Classement UCI : Nouvelles R\u00e9v\u00e9lations et Performances \u00c9blouissantes<\/h2>\n<div class=\"visual__image image-initial-width\">\n    <picture><source  media=\"(min-width: 1000px)\"\/><source  media=\"(min-width: 768px)\"\/><source  media=\"(min-width: 580px)\"\/><source  media=\"(min-width: 350px)\"\/><source  media=\"(min-width: 80px)\"\/><\/picture><figcaption class=\"article-figcaption-img\">-cr\u00e9dito @eganbernal\/Instagram<\/figcaption><\/div>\n<p class=\"paragraph\">La r\u00e9cente mise \u00e0 jour du \u00a0Ranking UCI\u00a0 a \u00e9t\u00e9 marqu\u00e9e par des performances exceptionnelles, notamment avec \u00a0Tadej Pogacar\u00a0 qui a remport\u00e9 pour la deuxi\u00e8me fois cons\u00e9cutive le titre de \u00a0champion du monde de cyclisme\u00a0, cette fois \u00e0 \u00a0Ruanda\u00a0. Ce triomphe permet \u00e0 Pogacar d\u2019augmenter son avance, car il reste en t\u00eate de la \u00a0classement international\u00a0 avec un total impressionnant de \u00a011 430 points\u00a0. Il d\u00e9fend ainsi les \u00a0900 points\u00a0 obtenus l&#8217;ann\u00e9e pr\u00e9c\u00e9dente, lorsqu&#8217;il avait \u00e9galement \u00e9t\u00e9 couronn\u00e9 \u00e0 \u00a0Zurich, en Suisse\u00a0.<\/p>\n<h2>Des Favoris qui Restent dans la Course<\/h2>\n<p class=\"paragraph\">Le tableau des pr\u00e9tendants reste \u00e0 peu pr\u00e8s inchang\u00e9. Les \u00a0Danois Jonas Vingegaard\u00a0 et \u00a0Mads Pedersen\u00a0 occupent toujours la deuxi\u00e8me et troisi\u00e8me position respectivement. En revanche, le \u00a0Mexicain Isaac Del Toro\u00a0 a r\u00e9alis\u00e9 une belle ascension, grimpant de deux places pour se positionner au quatri\u00e8me rang du classement.<\/p>\n<p class=\"paragraph\"><b>Suivez-nous sur<\/b> <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/infobaecolombia\"><i><b> Facebook<\/b><\/i><\/a> <b>et sur notre<\/b> <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/whatsapp.com\/channel\/0029Va4oNEALikgEL4Y8mb2K\"><i><b> WhatsApp Channel<\/b><\/i><\/a>.<\/p>\n<h2>Les Changements dans le Top 10<\/h2>\n<p class=\"paragraph\">Parmi les modifications, le \u00a0Belge Remco Evenepoel\u00a0, qui a d\u00e9croch\u00e9 le titre mondial de \u00a0contre-la-montre\u00a0, a gagn\u00e9 une place, atteignant la sixi\u00e8me position du classement. En revanche, le \u00a0N\u00e9erlandais Mathieu van der Poel\u00a0 a chut\u00e9 de trois \u00e9chelons, se retrouvant maintenant \u00e0 la septi\u00e8me place.<\/p>\n<h2>Les Performances des Cyclistes Colombiens<\/h2>\n<p class=\"paragraph\"><b>Les cyclistes colombiens<\/b> continuent de briller sur la sc\u00e8ne internationale. Bien qu&#8217;\u00a0Egan Bernal\u00a0 n&#8217;ait pas termin\u00e9 la course \u00e9lite au \u00a0Mondial de Ruanda\u00a0, il r\u00e9ussit n\u00e9anmoins \u00e0 int\u00e9grer le \u00a0Top 50\u00a0 du \u00a0Ranking UCI\u00a0, se classant comme le meilleur Colombien \u00e0 la \u00a049\u00e8me\u00a0 position avec \u00a01 402,5 points\u00a0. \u00a0Santiago Buitrago\u00a0 s&#8217;est \u00e9galement distingu\u00e9 en am\u00e9liorant sa position, atteignant le \u00a068\u00e8me\u00a0 rang apr\u00e8s une progression de trois places.<\/p>\n<p class=\"paragraph\">Un autre fait remarquable est l&#8217;ascension de \u00a0Harold Tejada\u00a0, qui a connu la plus forte mont\u00e9e parmi les coureurs colombiens, s&#8217;\u00e9levant de 15 positions pour se retrouver au \u00a0106\u00e8me\u00a0 rang, gr\u00e2ce \u00e0 sa performance remarquable dans l&#8217;\u00e9preuve \u00e9lite.<\/p>\n<h2>Gains et D\u00e9fis<\/h2>\n<p class=\"paragraph\">En bas du classement, le v\u00e9t\u00e9ran \u00a0Nairo Quintana\u00a0 a montr\u00e9 un l\u00e9ger progr\u00e8s, grimpant d&#8217;une place pour se positionner \u00e0 la \u00a0411\u00e8me\u00a0 place, o\u00f9 il \u00e9galise en points avec le \u00e9galement colombien \u00a0Sergio Higuita\u00a0.<\/p>\n<div class=\"visual__image\">\n    <picture><source  media=\"(min-width: 1000px)\"\/><source  media=\"(min-width: 768px)\"\/><source  media=\"(min-width: 580px)\"\/><source  media=\"(min-width: 350px)\"\/><source  media=\"(min-width: 80px)\"\/><img alt=\"-cr\u00e9dito @eganbernal\/Instagram\" class=\"global-image\" decoding=\"async\" fetchpriority=\"low\" height=\"567\" loading=\"lazy\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2025\/09\/1759257613_209_Egan-Bernal-a-ameliore-sa-position-au-classement-UCI-malgre.jpg\" width=\"1080\"\/>\n    <\/picture><figcaption class=\"article-figcaption-img\">-cr\u00e9dito @eganbernal\/Instagram<\/figcaption><\/div>\n<h2>Classement actuel des cyclistes<\/h2>\n<p class=\"paragraph\">1) Tadej Pogacar (Eslovenia) : <b>11.430 points<\/b>.<\/p>\n<p class=\"paragraph\">2) Jonas Vingegaard (Dinamarca) : <b>5.944,14 points<\/b>.<\/p>\n<p class=\"paragraph\">3) Mads Pedersen (Dinamarca) : <b>5.164,45 points<\/b>.<\/p>\n<p class=\"paragraph\">4) Isaac del Toro (M\u00e9xico) : <b>4.504 points<\/b>.<\/p>\n<p class=\"paragraph\">5) Joao Goncalves (Portugal) : <b>4.331,07 points<\/b>.<\/p>\n<p class=\"paragraph\"><b>49) Egan Bernal (Colombia) : 1.402,5 points.<\/b><\/p>\n<p class=\"paragraph\"><b>68) Santiago Buitrago (Colombia) : 1.077,5 points.<\/b><\/p>\n<p class=\"paragraph\"><b>106) Harold Tejada (Colombia) : 795 points.<\/b><\/p>\n<p class=\"paragraph\"><b>109) Einer Rubio (Colombia) : 786 points.<\/b><\/p>\n<p class=\"paragraph\"><b>411) Nairo Quintana (Colombia) : 205 points.<\/b><\/p>\n<p class=\"paragraph\"><b>411) Sergio Higuita (Colombia) : 205 points.<\/b><\/p>\n<p>Le monde du cyclisme s\u2019emballe avec des comp\u00e9titions pleines de rebondissements et des performances \u00e0 couper le souffle. Le classement UCI continue de refl\u00e9ter l\u2019excellence et la d\u00e9termination des cyclistes du monde entier, alors que nombre d\u2019entre eux se pr\u00e9parent pour les d\u00e9fis \u00e0 venir. Les performances r\u00e9centes annoncent une saison riche en \u00e9motions, tant pour les coureurs de haut niveau que pour les fans du cyclisme.<\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/teknomers.com\/fr\/category\/finance\/\" rel=\"dofollow\">F1-ES<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Classement UCI : Nouvelles R\u00e9v\u00e9lations et Performances \u00c9blouissantes -cr\u00e9dito @eganbernal\/Instagram La r\u00e9cente mise \u00e0 jour du \u00a0Ranking UCI\u00a0 a \u00e9t\u00e9 marqu\u00e9e par des performances exceptionnelles, notamment avec \u00a0Tadej Pogacar\u00a0 qui a remport\u00e9 pour la deuxi\u00e8me fois cons\u00e9cutive le titre de \u00a0champion du monde de cyclisme\u00a0, cette fois \u00e0 \u00a0Ruanda\u00a0. Ce triomphe permet \u00e0 Pogacar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1722727,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[15325,37586,506,59,278,41850,1561,2492,2368,1056,3902,2946,13647,196],"class_list":["post-1722726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-ameliore","tag-bernal","tag-championnat","tag-classement","tag-cyclisme","tag-egan","tag-journee","tag-malgre","tag-mauvaise","tag-monde","tag-position","tag-rwanda","tag-uci","tag-une"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1722726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1722726"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1722726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1722727"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1722726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1722726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1722726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}