{"id":1722333,"date":"2025-09-28T17:41:48","date_gmt":"2025-09-28T14:41:48","guid":{"rendered":"https:\/\/teknomers.com\/fr\/un-ancien-premier-ministre-italien-a-rencontre-poutine-en-chine-et-a-declare-avoir-ete-choque-par-son-etat-il-ressemblait-a-berlusconi-a-la-fin\/"},"modified":"2025-09-28T17:41:54","modified_gmt":"2025-09-28T14:41:54","slug":"un-ancien-premier-ministre-italien-a-rencontre-poutine-en-chine-et-a-declare-avoir-ete-choque-par-son-etat-il-ressemblait-a-berlusconi-a-la-fin","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/un-ancien-premier-ministre-italien-a-rencontre-poutine-en-chine-et-a-declare-avoir-ete-choque-par-son-etat-il-ressemblait-a-berlusconi-a-la-fin\/","title":{"rendered":"Un ancien Premier ministre italien a rencontr\u00e9 Poutine en Chine et a d\u00e9clar\u00e9 avoir \u00e9t\u00e9 \u201cchoqu\u00e9\u201d par son \u00e9tat : \u201cIl ressemblait \u00e0 Berlusconi \u00e0 la fin.\u201d"},"content":{"rendered":"\n<h2>La sant\u00e9 de Vladimir Poutine : R\u00e9v\u00e9lations d&#8217;un ex-premier ministre italien<\/h2>\n<div class=\"visual__image image-initial-width\">\n    <picture><source  media=\"(min-width: 1000px)\"\/><source  media=\"(min-width: 768px)\"\/><source  media=\"(min-width: 580px)\"\/><source  media=\"(min-width: 350px)\"\/><source  media=\"(min-width: 80px)\"\/><\/picture><figcaption class=\"article-figcaption-img\">Le pr\u00e9sident chinois, Xi Jinping, et le pr\u00e9sident russe, Vladimir Poutine, lors d&#8217;une r\u00e9union \u00e0 Beijing.<\/figcaption><\/div>\n<p>Lors d&#8217;une r\u00e9cente entrevue, l&#8217;ex-premier ministre italien <b>Massimo D\u2019Alema<\/b> a livr\u00e9 des commentaires intrigants concernant l&#8217;\u00e9tat de sant\u00e9 de <b>Vladimir Poutine<\/b>. D\u2019apr\u00e8s ses dires, Poutine \u00ab\u00a0\u00a0semblait tr\u00e8s fatigu\u00e9\u00a0\u00a0\u00bb et rappelait \u00ab\u00a0\u00a0le dernier Berlusconi\u00a0\u00a0\u00bb lors d\u2019un rencontre \u00e0 Beijing. Ces remarques, rapport\u00e9es par le quotidien <i>Corriere della Sera<\/i>, ont relanc\u00e9 les <b>sp\u00e9culations<\/b> entourant la sant\u00e9 du leader russe, des rumeurs qui circulent depuis le d\u00e9but de l&#8217;invasion de l&#8217;Ukraine en 2022.<\/p>\n<h2>Des impressions inqui\u00e9tantes<\/h2>\n<p>D\u2019Alema a partag\u00e9 son ressenti avec des amis, affirmant que Poutine \u00ab\u00a0\u00a0\u00e9tait aid\u00e9 par deux personnes\u00a0\u00a0\u00bb pendant leur \u00e9change lors des c\u00e9l\u00e9brations du 80e anniversaire de la fin de la Seconde Guerre mondiale. Le quotidien italien pr\u00e9cise que la description de l\u2019ex-premier ministre, bien que soigneusement formul\u00e9e pour \u00e9viter un diagnostic explicite, a suscit\u00e9 des r\u00e9actions parmi ceux ayant entendu son t\u00e9moignage.<\/p>\n<p>L\u2019ex-premier ministre a d\u00e9clar\u00e9 qu&#8217;il \u00ab\u00a0\u00a0semblait voir Silvio Berlusconi dans ses derniers mois.\u00a0\u00a0\u00bb Cette observation \u00e9voque des sentiments de pr\u00e9occupation non seulement pour la sant\u00e9 physique de Poutine mais aussi pour sa vitalit\u00e9 politique \u00e0 un moment o\u00f9 son pays traverse une p\u00e9riode de tensions internationales.<\/p>\n<h2>Un contexte de rumeurs persistantes<\/h2>\n<p>Les commentaires de D\u2019Alema sont d&#8217;autant plus significatifs dans un contexte o\u00f9 les <b>rumeurs sur la sant\u00e9 de Poutine<\/b> circulent depuis des mois. En mars dernier, le pr\u00e9sident ukrainien <b>Volod\u00edmir Zelensky<\/b> a \u00e9t\u00e9 cit\u00e9 disant que Poutine \u00ab\u00a0\u00a0morait bient\u00f4t\u00a0\u00a0\u00bb, une affirmation qu\u2019il accompagne d\u2019une certaine assurance. Ce climat de sp\u00e9culation a \u00e9t\u00e9 aliment\u00e9 par divers interpr\u00e9tations des signes de sant\u00e9 du pr\u00e9sident, allant de probl\u00e8mes cardiovasculaires pr\u00e9sum\u00e9s \u00e0 des maladies comme le cancer et la maladie de Parkinson.<\/p>\n<h2>R\u00e9actions du Kremlin et des agences de renseignement occidentales<\/h2>\n<p>Face \u00e0 ces sp\u00e9culations, le Kremlin a fermement rejet\u00e9 ces all\u00e9gations. Le porte-parole Dmitri Peskov a qualifi\u00e9 les rumeurs de \u00ab\u00a0\u00a0fake news\u00a0\u00a0\u00bb et a insist\u00e9 sur le fait que Poutine \u00ab\u00a0\u00a0jouit d\u2019une bonne sant\u00e9.\u00a0\u00a0\u00bb De leur c\u00f4t\u00e9, des analyses d\u2019agences de renseignement occidentales telles que celles men\u00e9es par la CIA ont \u00e9galement minimis\u00e9 ces pr\u00e9occupations, affirmant qu&#8217;il n&#8217;y a pas de preuves d\u2019un \u00e9tat de sant\u00e9 grave chez Poutine.<\/p>\n<p>Le directeur de la CIA, <b>William Burns<\/b>, a affirm\u00e9 lors d&#8217;un forum de s\u00e9curit\u00e9 en 2022 que \u00ab\u00a0\u00a0nombre de rumeurs sur la sant\u00e9 de Poutine semblent infond\u00e9es\u00a0.\u00a0\u00bb Le chef du MI6 britannique, <b>Richard Moore<\/b>, a rejoint cette \u00e9valuation, pr\u00e9cisant qu&#8217;\u00ab\u00a0\u00a0il n&#8217;existe aucune preuve d&#8217;une maladie grave.\u00a0\u00a0\u00bb<\/p>\n<h2>Les mesures de confidentialit\u00e9 de Poutine<\/h2>\n<p>Malgr\u00e9 ces d\u00e9mentis, ce que l\u2019on sait des pratiques m\u00e9dicales de Poutine soul\u00e8ve des questions. Il se sait que le leader russe prend des mesures extr\u00eames pour pr\u00e9server sa <b>vie priv\u00e9e m\u00e9dicale<\/b>. Par exemple, lors de ses voyages, des membres de son service de s\u00e9curit\u00e9 collectent ses <b>d\u00e9chets biologiques<\/b> afin d\u2019emp\u00eacher une analyse qui pourrait r\u00e9v\u00e9ler des d\u00e9tails sur sa sant\u00e9 ou les m\u00e9dicaments qu&#8217;il utilise.<\/p>\n<h2>Conversations sur la long\u00e9vit\u00e9<\/h2>\n<p>Un autre aspect intrigant est la conversation capt\u00e9e entre Poutine et <b>Xi Jinping<\/b> \u00e0 Beijing sur les avanc\u00e9es en biotechnologie et le potentiel d\u2019\u00a0immortalit\u00e9\u00a0. Lors de cet \u00e9change, Poutine a propos\u00e9 que gr\u00e2ce \u00e0 la biotechnologie, les humains pourraient bient\u00f4t esp\u00e9rer une long\u00e9vit\u00e9 accrue. Xi a d\u2019ailleurs affirm\u00e9 que \u00ab\u00a0\u00a0dans ce si\u00e8cle, il est possible de vivre jusqu&#8217;\u00e0 150 ans.\u00a0\u00a0\u00bb<\/p>\n<p>Cette discussion pose \u00e9galement la question des dirigeants autoritaires et des rumeurs qui les entourent, similaire \u00e0 celles qui ont touch\u00e9 Kim Jong-un en Cor\u00e9e du Nord.<\/p>\n<div>\n<div class=\"opt-in_validate\" id=\"entry_success\">\n<p>\n            La sant\u00e9 de Vladimir Poutine continue de susciter un vif int\u00e9r\u00eat \u00e0 l&#8217;\u00e9chelle mondiale, non seulement pour ses implications politiques, mais aussi pour l&#8217;avenir de la Russie sur la sc\u00e8ne internationale. La combinaison de t\u00e9moignages, de rumeurs et de d\u00e9n\u00e9gations officielles contribue \u00e0 une atmosph\u00e8re d&#8217;incertitude qui est loin d\u2019\u00eatre close.\n        <\/p>\n<\/p><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/teknomers.com\/fr\/category\/finance\/\" rel=\"dofollow\">F1-ES<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sant\u00e9 de Vladimir Poutine : R\u00e9v\u00e9lations d&#8217;un ex-premier ministre italien Le pr\u00e9sident chinois, Xi Jinping, et le pr\u00e9sident russe, Vladimir Poutine, lors d&#8217;une r\u00e9union \u00e0 Beijing. Lors d&#8217;une r\u00e9cente entrevue, l&#8217;ex-premier ministre italien Massimo D\u2019Alema a livr\u00e9 des commentaires intrigants concernant l&#8217;\u00e9tat de sant\u00e9 de Vladimir Poutine. D\u2019apr\u00e8s ses dires, Poutine \u00ab\u00a0\u00a0semblait tr\u00e8s fatigu\u00e9\u00a0\u00a0\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1722334,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[5342,313570,272,61808,30552,109,163,250,443,162,1389,1793,944,164,452,2497,3077,9667,167],"class_list":["post-1722333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-ancien","tag-asia-pacific","tag-avoir","tag-beijing","tag-berlusconi","tag-chine","tag-choque","tag-declare","tag-etat","tag-ete","tag-fin","tag-italien","tag-ministre","tag-par","tag-poutine","tag-premier","tag-rencontre","tag-ressemblait","tag-son"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1722333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1722333"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1722333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1722334"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1722333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1722333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1722333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}