{"id":1639374,"date":"2025-04-23T15:49:34","date_gmt":"2025-04-23T17:49:34","guid":{"rendered":"https:\/\/teknomers.com\/fr\/alisha-lehmann-et-douglas-luiz-rumeurs-de-separation-malgre-le-reve-de-la-juventus\/"},"modified":"2025-04-23T15:49:39","modified_gmt":"2025-04-23T17:49:39","slug":"alisha-lehmann-et-douglas-luiz-rumeurs-de-separation-malgre-le-reve-de-la-juventus","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/alisha-lehmann-et-douglas-luiz-rumeurs-de-separation-malgre-le-reve-de-la-juventus\/","title":{"rendered":"Alisha Lehmann et Douglas Luiz: Rumeurs de s\u00e9paration malgr\u00e9 le r\u00eave de la Juventus?"},"content":{"rendered":"\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 leading-17\"><strong class=\"font-bold\">Il combine non seulement la passion pour le football &#8211; ils sont \u00e9galement dans le m\u00eame club. Alisha Lehmann et Douglas Luiz sont consid\u00e9r\u00e9es comme une paire de puissance de football.<\/strong><\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">L&#8217;endroit o\u00f9 Alisha Lehmann et son amie Douglas Luiz Soares se sont rencontr\u00e9s peuvent g\u00e9n\u00e9ralement appara\u00eetre en vue de leur profil spectaculaire sur les r\u00e9seaux sociaux de plus de 16 millions de followers. Parce que les professionnels du football se sont rencontr\u00e9s sur le lieu de travail. Mais surtout dans le football, une entreprise en \u00e9volution rapide, il \u00e9tait presque sp\u00e9cial que les chemins des deux en 2021 au club de Premier League Aston Villa se sont crois\u00e9s.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">La Suisse n\u00e9e en 1999 a commenc\u00e9 sa carri\u00e8re de football t\u00f4t. Apr\u00e8s diverses stations dans la r\u00e9gion de la jeunesse, elle est pass\u00e9e \u00e0 la plus haute ligue anglaise \u00e0 West Ham United en 2018 par l&#8217;\u00e9quipe des jeunes gar\u00e7ons de Bernois avant de d\u00e9m\u00e9nager \u00e0 Aston Villa en 2021. Apr\u00e8s son passage \u00e0 Aston Villa, o\u00f9 la relation a commenc\u00e9, Lehmann est all\u00e9e \u00e0 la Juventus Turin en 2024.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Et exactement une semaine apr\u00e8s son petit ami. Juve a pay\u00e9 une somme d\u00e9cente pour le double transfert du couple. Pour Douglas Luiz, l&#8217;association Serie-A a mis 50 millions d&#8217;euros sur la table, environ 50 000 euros pour Lehmann. Apr\u00e8s le changement, Lehmann a d\u00e9clar\u00e9: &#8220;Pour Douglas et moi, c&#8217;est un r\u00eave d&#8217;\u00eatre ensemble dans le m\u00eame club.&#8221;<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Luiz, n\u00e9 \u00e0 Rio en 1998, est pass\u00e9 par l&#8217;Acad\u00e9mie des jeunes du club br\u00e9silien Vasco Da Gama avant de d\u00e9m\u00e9nager en Europe en 2017. Apr\u00e8s des stations \u00e0 Manchester City et au FC Girona, le milieu de terrain central se lance maintenant pour Juve et a termin\u00e9 22 matchs jusqu&#8217;\u00e0 pr\u00e9sent pour le cinqui\u00e8me actuel du tableau.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Enfin, cependant, Douglas Luiz a d\u00fb faire face aux revers encore et encore. Le Br\u00e9silien a \u00e9t\u00e9 bless\u00e9 plusieurs fois cette saison. Il manquait de son club, entre autres, \u00e0 cause de la fatigue musculaire et a \u00e9galement subi une violation du muscle fl\u00e9chisseur des jambes. Il avait disput\u00e9 neuf matchs jusqu&#8217;en d\u00e9cembre de l&#8217;ann\u00e9e derni\u00e8re et n&#8217;a \u00e9t\u00e9 que deux fois dans la formation de d\u00e9part de l&#8217;entra\u00eeneur Thiago Motta.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Lehmann a v\u00e9cu un peu mieux avec son nouveau club par rapport \u00e0 son partenaire. Lors de ses onze premiers matchs pour Juve, elle a marqu\u00e9 deux buts, dont une fin intelligente dans ses d\u00e9buts. Apr\u00e8s ses premiers mois dans le nord de l&#8217;Italie, elle a d\u00e9clar\u00e9: &#8220;Je suis tr\u00e8s heureuse d&#8217;\u00eatre ici. Les filles sont gentilles et nous nous aidons sur le terrain.&#8221; Plus r\u00e9cemment, elle a pu esp\u00e9rer le titre dans Serie A avec l&#8217;\u00e9quipe.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Il n&#8217;est pas clair si Douglas Luiz \u00e9tait satisfait d&#8217;elle. Il y a actuellement des rumeurs de s\u00e9paration autour du couple. La relation entre Lehmann et Luiz avait d\u00e9j\u00e0 \u00e9t\u00e9 de haut en bas. De janvier \u00e0 novembre 2022, ils sortaient fermement jusqu&#8217;\u00e0 ce qu&#8217;une s\u00e9paration suivait. Le &#8220;Soleil&#8221; britannique a rapport\u00e9 \u00e0 l&#8217;\u00e9poque que le Br\u00e9silien avait g\u00ean\u00e9 par les photos du calendrier incitatives de Lehmann.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Selon les m\u00e9dias, ils sont un couple depuis le d\u00e9but de 2024 &#8211; cependant, tous les deux messages &#8211; seule une coop\u00e9ration publicitaire conjointe de f\u00e9vrier est rest\u00e9e en ligne.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/fussball\/international\/id_100689800\/alisha-lehmann-und-douglas-luiz-trennungsgeruechte-trotz-juventus-traum-.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il combine non seulement la passion pour le football &#8211; ils sont \u00e9galement dans le m\u00eame club. Alisha Lehmann et Douglas Luiz sont consid\u00e9r\u00e9es comme une paire de puissance de football. L&#8217;endroit o\u00f9 Alisha Lehmann et son amie Douglas Luiz Soares se sont rencontr\u00e9s peuvent g\u00e9n\u00e9ralement appara\u00eetre en vue de leur profil spectaculaire sur les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1639375,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[274961,109685,224444,18486,1341,32363,72468,1654,91,360,1530,48405,43907,22214,300684,2492,601,1325,3663,5315,10797,300685,53511],"class_list":["post-1639374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-agence-dassurance-des-services-de-location-et-de-pret-premier","tag-alisha","tag-alisha-lehmann","tag-aston-villa","tag-club","tag-douglas","tag-douglas-luiz","tag-europe","tag-football","tag-italie","tag-juventus","tag-juventus-turin","tag-lehmann","tag-luiz","tag-luiz-soares","tag-malgre","tag-manchester-city","tag-reve","tag-rio","tag-rumeurs","tag-separation","tag-vasco-da-gama","tag-west-ham-united-fc"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1639374"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1639375"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1639374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1639374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1639374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}