{"id":1639255,"date":"2025-04-23T13:59:11","date_gmt":"2025-04-23T15:59:11","guid":{"rendered":"https:\/\/teknomers.com\/fr\/hanovre-96-et-lentraineur-breitenreiter-separe-trio-prend-le-dessus\/"},"modified":"2025-04-23T13:59:16","modified_gmt":"2025-04-23T15:59:16","slug":"hanovre-96-et-lentraineur-breitenreiter-separe-trio-prend-le-dessus","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/hanovre-96-et-lentraineur-breitenreiter-separe-trio-prend-le-dessus\/","title":{"rendered":"Hanovre 96 et l&#8217;entra\u00eeneur Breitenreiter s\u00e9par\u00e9: Trio prend le dessus"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>6 points derri\u00e8re le rang de rel\u00e9gation <\/p>\n<div class=\"newsBild\">\n<p>\n                                       <span>\u00a9 imago<\/span>\n                                    <\/p>\n<\/p><\/div>\n<p>Le prochain changement d&#8217;entra\u00eeneur dans la 2e Bundesliga: Hanovre 96 tire le ripcord pour la deuxi\u00e8me fois au cours de la saison et change l&#8217;entra\u00eeneur. Comme l&#8217;a annonc\u00e9 la saxe inf\u00e9rieure, la s\u00e9paration imm\u00e9diate a \u00e9t\u00e9 convenue avec l&#8217;Andr\u00e9 Breitenreiter, qui n&#8217;a \u00e9t\u00e9 renvoy\u00e9 qu&#8217;en laisse en d\u00e9cembre.<\/p>\n<p><\/p>\n<p>Cela a r\u00e9cemment \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9 de quatre matchs sans victoire, dont trois d\u00e9faites, de suite et la rechute de dix. L&#8217;\u00e9cart de la place de promotion de rel\u00e9gation est de six points avant le 31e match. \u00c0 la fin de la saison, l&#8217;entra\u00eeneur adjoint Lars Barlemann, l&#8217;entra\u00eeneur U19 Dirk Lottner et l&#8217;entra\u00eeneur U17 Christian Schulz doivent diriger l&#8217;\u00e9quipe. L&#8217;assistant Thomas Kleine quitte le club avec Breitenreiter. L&#8217;ancien entra\u00eeneur de promotion de Hanover de 13 matchs n&#8217;a remport\u00e9 que 1,23 points en moyenne. Pr\u00e9dire Stefan Leitl \u00e9tait en 89 matchs pour 1,42 points. <\/p>\n<p>&#8220;Andr\u00e9 a commenc\u00e9 la t\u00e2che avec beaucoup de vigueur en hiver. Avec sa fa\u00e7on de s&#8217;adresser \u00e0 la foi et \u00e0 la conviction d&#8217;une seconde moiti\u00e9 r\u00e9ussie de la saison, il a r\u00e9ussi \u00e0 renforcer la foi en interne et en externe&#8221;, a d\u00e9clar\u00e9 le directeur sportif de 96 Marcus Mann dans une annonce de club. &#8220;Nous avons commenc\u00e9 correctement, a parfois apport\u00e9 des performances tr\u00e8s attrayantes sur le terrain &#8211; mais nous avons \u00e9galement laiss\u00e9 trop de points. Malheureusement, le d\u00e9veloppement n&#8217;est pas all\u00e9 dans la bonne direction.<\/p>\n<p><\/p>\n<h2>Breitenreiter \u00e0 propos de la sortie de Hanover: &#8220;logique et coh\u00e9rente&#8221;<\/h2>\n<p>Breitenreiter a d\u00e9clar\u00e9: &#8220;Dans plusieurs phases de la seconde moiti\u00e9 de la saison, nous \u00e9tions au sommet. Malheureusement, dans trop de matchs, nous n&#8217;avons pas r\u00e9ussi \u00e0 convertir de tr\u00e8s bonnes performances en victoires. Parfois, c&#8217;est en football &#8211; apr\u00e8s, il n&#8217;est plus possible de changer. Le club aimerait r\u00e9organiser \u00e0 nouveau de l&#8217;\u00e9t\u00e9.<\/p>\n<p><\/p>\n<p>Dans le &#8220;Bild&#8221;, le chef du conseil de surveillance et directeur de l&#8217;ex-directeur, Martin Kind, a \u00e9galement parl\u00e9: &#8220;Les deux messieurs ont d\u00e9cid\u00e9 de cette fa\u00e7on que j&#8217;aurais pu bien vivre en jouant la saison avec lui. Mais en quelque sorte le d\u00e9sir, en particulier de M. Breitenreiter, il \u00e9tait probablement \u00e9galement possible de justifier la coop\u00e9ration.&#8221;<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/hannover-96-und-breitenreiter-trennen-sich-trio-um-schulz-ubernimmt-bis-saisonende\/view\/news\/452974\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>6 points derri\u00e8re le rang de rel\u00e9gation \u00a9 imago Le prochain changement d&#8217;entra\u00eeneur dans la 2e Bundesliga: Hanovre 96 tire le ripcord pour la deuxi\u00e8me fois au cours de la saison et change l&#8217;entra\u00eeneur. Comme l&#8217;a annonc\u00e9 la saxe inf\u00e9rieure, la s\u00e9paration imm\u00e9diate a \u00e9t\u00e9 convenue avec l&#8217;Andr\u00e9 Breitenreiter, qui n&#8217;a \u00e9t\u00e9 renvoy\u00e9 qu&#8217;en laisse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1639256,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9027,38467,9496,300653,10650,300652,274895,6512,300651,1126,1804,1125,5148],"class_list":["post-1639255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-2-bundesliga","tag-andre-breitenreiter","tag-breitenreiter","tag-christian-schulz","tag-dessus","tag-dirk-lottner","tag-hanover-96","tag-hanovre","tag-lars-barlemann","tag-lentraineur","tag-prend","tag-separe","tag-trio"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1639255"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1639256"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1639255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1639255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1639255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}