{"id":1639166,"date":"2025-04-23T12:56:33","date_gmt":"2025-04-23T14:56:33","guid":{"rendered":"https:\/\/teknomers.com\/fr\/galatasaray-a-celebre-le-23-avril\/"},"modified":"2025-04-23T12:56:38","modified_gmt":"2025-04-23T14:56:38","slug":"galatasaray-a-celebre-le-23-avril","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/galatasaray-a-celebre-le-23-avril\/","title":{"rendered":"Galatasaray a c\u00e9l\u00e9br\u00e9 le 23 avril"},"content":{"rendered":"\n<div id=\"\">\n<p>L&#8217;\u00e9v\u00e9nement a \u00e9t\u00e9 organis\u00e9 dans le champ artificiel \u00e0 l&#8217;entr\u00e9e de la porte C. Les enfants ont eu un moment de plaisir accompagn\u00e9 de groupes, de clowns et de musique. 23 avril Festival, football Une \u00e9quipe a d\u00e9m\u00e9nag\u00e9 dans l&#8217;\u00e9tablissement \u00e9tait \u00e9galement la qualit\u00e9 des adieux.<\/p>\n<p>S&#8217;exprimant au festival, le pr\u00e9sident Dursun \u00d6zbek, 23 avril, la souverainet\u00e9 nationale et la Journ\u00e9e des enfants, faisant r\u00e9f\u00e9rence \u00e0 l&#8217;importance de &#8220;aujourd&#8217;hui le 23 avril la souverainet\u00e9 nationale et de la Journ\u00e9e des enfants. L&#8217;une de nos plus grandes vacances. Il y a 105 ans, la cr\u00e9ation de notre Assembl\u00e9e nationale et le symbole de la transition de la d\u00e9mocratie comme un cadeau pour l&#8217;expression de la fin de la fin de la fin de la fin de la fin de la guerre du CIH. Ce n&#8217;est pas seulement la f\u00eate des enfants de T\u00fcrkiye, mais aussi la c\u00e9l\u00e9bration des enfants du monde comme la f\u00eate du monde.<\/p>\n<p>En parlant du tremblement de terre \u00e0 Istanbul Ozbek, &#8220;un juste avant un tremblement de terre. Ici j&#8217;\u00e9tais ici. Tr\u00e8s balan\u00e7ant. J&#8217;esp\u00e8re qu&#8217;il n&#8217;y a pas de grandes pertes. Nous obtenons de courtes nouvelles, nous entendons de petites choses. J&#8217;esp\u00e8re qu&#8217;il n&#8217;y a pas de perte de vie, je ne rencontre pas trop de d\u00e9g\u00e2ts. Il a dit.<\/p>\n<p><strong>Polat: Un c\u00f4t\u00e9 de nos c\u0153urs est le perdant parce que nous quitterons Florya<\/strong><\/p>\n<p>Adnan Polat, l&#8217;ancien pr\u00e9sident du Galatasaray Club, a d\u00e9clar\u00e9 qu&#8217;ils avaient un bonheur amer pour avoir dit au revoir \u00e0 Florya.<\/p>\n<p>Polat a rappel\u00e9 qu&#8217;il a \u00e9t\u00e9 le directeur et le pr\u00e9sident pendant 11 ans: &#8220;J&#8217;ai officiellement pass\u00e9 mes 11 ans officiels. Nous sommes heureux d&#8217;\u00eatre ici, mais un c\u00f4t\u00e9 de nos c\u0153urs sera le plus perdant parce que nous partirons. Voici quelque chose comme un petit d\u00eener d&#8217;adieu, mais l&#8217;infrastructure de Galatasaray jusqu&#8217;\u00e0 la fin de l&#8217;ann\u00e9e. \u00c9valu\u00e9e.<\/p>\n<p>Adnan Polat, sur le tremblement de terre \u00e0 Istanbul, &#8220;All Istanbul et la r\u00e9gion pour obtenir un pass\u00e9, je souhaite mes souhaits. Nous avons connu un tremblement de terre. J&#8217;esp\u00e8re qu&#8217;il n&#8217;y a pas de d\u00e9g\u00e2ts et ne revient pas.&#8221; Il a dit.<\/p>\n<p>Se r\u00e9f\u00e9rant \u00e0 la Journ\u00e9e nationale de la souverainet\u00e9 nationale du 23 avril, Polat a d\u00e9clar\u00e9: &#8220;Je f\u00e9licite le 23 avril de la souverainet\u00e9 nationale et de la Journ\u00e9e des enfants. J&#8217;esp\u00e8re que nous verrons beaucoup plus de vacances.&#8221; Il a termin\u00e9 ses mots.<\/p>\n<p><strong>Albayrak: J&#8217;esp\u00e8re que nous f\u00e9liciterons la 5e \u00e9toile \u00e0 Kemerburgaz<\/strong><\/p>\n<p>L&#8217;ancien pr\u00e9sident du club jaune-rouge Abdurrahim Albayrak, 5e \u00e9toile Kemerburgaz souhaitait c\u00e9l\u00e9brer.<\/p>\n<p>23 avril La souverainet\u00e9 nationale et la Journ\u00e9e des enfants se sont r\u00e9unies \u00e0 cause du transfert d&#8217;Albayrak, &#8220;ces bonnes vacances ont \u00e9t\u00e9 un grand tremblement de terre \u00e0 Istanbul. J&#8217;esp\u00e8re qu&#8217;il n&#8217;y avait rien de grand. Tout le monde passe.&#8221; Il a dit.<\/p>\n<p>Florya a dit au revoir \u00e0 Florya Albayrak, &#8220;Florya&#8217;dan Tadness, Kemerburgaz Installations, nous sommes heureux de d\u00e9m\u00e9nager. Nous c\u00e9l\u00e9brons toujours les championnats ici. J&#8217;esp\u00e8re que Kemerburgaz, 5e \u00e9toile, c\u00e9l\u00e8bre.&#8221; Il a dit.<\/p>\n<p><strong>Le tremblement de terre du festival<\/strong><\/p>\n<p>Le festival des installations de Florya Metin Oktay a eu lieu en raison du tremblement de terre \u00e0 Istanbul a \u00e9t\u00e9 suspendu.<\/p>\n<p>Environ 12,50 heures \u00e0 Istanbul en raison du tremblement de terre se produisait de panique \u00e0 court terme. Apr\u00e8s le tremblement de terre, la musique et les \u00e9v\u00e9nements ont \u00e9t\u00e9 arr\u00eat\u00e9s.<\/p>\n<p>Apr\u00e8s environ une demi-heure, il n&#8217;y a eu aucune perte de vie ou bless\u00e9 \u00e0 Istanbul apr\u00e8s sa confirmation.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.fotomac.com.tr\/galatasaray\/2025\/04\/23\/galatasaray-23-nisani-kutladi\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-7<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9v\u00e9nement a \u00e9t\u00e9 organis\u00e9 dans le champ artificiel \u00e0 l&#8217;entr\u00e9e de la porte C. Les enfants ont eu un moment de plaisir accompagn\u00e9 de groupes, de clowns et de musique. 23 avril Festival, football Une \u00e9quipe a d\u00e9m\u00e9nag\u00e9 dans l&#8217;\u00e9tablissement \u00e9tait \u00e9galement la qualit\u00e9 des adieux. S&#8217;exprimant au festival, le pr\u00e9sident Dursun \u00d6zbek, 23 avril, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1639167,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[300529,2117,93,183145,602,274617,2751,300622,5417],"class_list":["post-1639166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-23-avril-souvirete-nationale-et-journee-des-enfants","tag-avril","tag-celebre","tag-dursun-ozbek","tag-galatasaray","tag-installations-de-florya-mettin-oktay","tag-istanbul","tag-polat-dadnan","tag-turquie"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1639166"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1639167"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1639166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1639166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1639166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}