{"id":1639154,"date":"2025-04-23T12:37:59","date_gmt":"2025-04-23T14:37:59","guid":{"rendered":"https:\/\/teknomers.com\/fr\/le-geant-automobile-devient-un-fabricant-de-moteurs-f1\/"},"modified":"2025-04-23T12:38:04","modified_gmt":"2025-04-23T14:38:04","slug":"le-geant-automobile-devient-un-fabricant-de-moteurs-f1","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/le-geant-automobile-devient-un-fabricant-de-moteurs-f1\/","title":{"rendered":"Le g\u00e9ant automobile devient un fabricant de moteurs F1"},"content":{"rendered":"\n<div>\n<p>Le g\u00e9ant automobile am\u00e9ricain General Motors a \u00e9t\u00e9 officiellement approuv\u00e9 par la FIA en tant que fabricant de moteurs pour la saison de Formule 1 2029 &#8211; La World Association l&#8217;a annonc\u00e9 mercredi avec une diffusion.<\/p>\n<p>Il y a seulement environ deux mois, Cadillac&#8217;s Square a \u00e9t\u00e9 officiellement confirm\u00e9 en tant que onzi\u00e8me \u00e9quipe dans la Formule 1 Starterfeld pour 2026. Gr\u00e2ce \u00e0 l&#8217;approbation de GM Performance Power Units LLC, il est clair que l&#8217;\u00e9quipe de course peut commencer par des unit\u00e9s de lecteur d\u00e9velopp\u00e9es et produites aux \u00c9tats-Unis \u00e0 partir de 2029.<\/p>\n<p>Au cours des trois premi\u00e8res ann\u00e9es de sa participation, l&#8217;\u00e9quipe rivalisera initialement avec les moteurs Ferrari avant que les unit\u00e9s de lecteur homologu\u00e9es ne soient finalement utilis\u00e9es \u00e0 partir de leur propre d\u00e9veloppement \u00e0 partir de 2029.<\/p>\n<p>&#8220;Avec l&#8217;approbation de la FIA, nous intensifions nos efforts pour faire d\u00e9velopper une unit\u00e9 d&#8217;entra\u00eenement de Formule 1 aux \u00c9tats-Unis&#8221;, a d\u00e9clar\u00e9 Russ O&#8217;Blene, PDG de GM Performance Power Units LLC, dans un communiqu\u00e9 \u00e0 &#8220;Motorsport.com&#8221;.<\/p>\n<p>Les moteurs sont construits dans un nouveau centre de d\u00e9veloppement que General Motors a cr\u00e9\u00e9 avec TWG Motorsports &#8211; la soci\u00e9t\u00e9 m\u00e8re d&#8217;Andretti Global. Au cours de l&#8217;ann\u00e9e \u00e0 venir, un centre technologique sp\u00e9cialement meubl\u00e9 pr\u00e8s de GMS Technical Development Center \u00e0 Charlotte, en Caroline du Nord, sera ouvert.<\/p>\n<h2>Le pr\u00e9sident de la FIA voit un int\u00e9r\u00eat croissant pour la formule 1<\/h2>\n<p>&#8220;L&#8217;inclusion de GM Performance Power Units LLC en tant que fournisseur de drive approuv\u00e9 \u00e0 partir de 2029 est une autre \u00e9tape importante dans l&#8217;expansion mondiale de la formule 1&#8221;, explique le pr\u00e9sident de la FIA, Mohammed Ben Sulayem: &#8220;Il montre l&#8217;int\u00e9r\u00eat croissant des principaux constructeurs automobiles tels que General Motors dans notre classe de premier plan.&#8221;<\/p>\n<p>Le pr\u00e9sident de la FIA loue: &#8220;Votre engagement envers l&#8217;innovation, la durabilit\u00e9 et la concurrence est conforme \u00e0 la vision future de la FIA. En outre, il souligne notre engagement envers un paysage de sport automobile plus ouvert, plus accessible et plus diversifi\u00e9.&#8221;<\/p>\n<p>Avec l&#8217;entr\u00e9e de General Motors, le domaine des fabricants de conduite renomm\u00e9s en Formule 1. \u00c0 partir de 2029, GM concurrencera les moteurs de Ferrari, Mercedes, Audi et Ford &#8211; l&#8217;autre g\u00e9ant am\u00e9ricain coop\u00e8re avec Red Bull pour leur programme de moteurs.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne7707308\/formel-1-automobil-gigant-wird-motorenhersteller\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-8<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le g\u00e9ant automobile am\u00e9ricain General Motors a \u00e9t\u00e9 officiellement approuv\u00e9 par la FIA en tant que fabricant de moteurs pour la saison de Formule 1 2029 &#8211; La World Association l&#8217;a annonc\u00e9 mercredi avec une diffusion. Il y a seulement environ deux mois, Cadillac&#8217;s Square a \u00e9t\u00e9 officiellement confirm\u00e9 en tant que onzi\u00e8me \u00e9quipe dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1639155,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9979,910,483,127,252817,3912,9443,6762,274200],"class_list":["post-1639154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-automobile","tag-devient","tag-fabricant","tag-formule-1","tag-formule-1-2025","tag-geant","tag-moteurs","tag-sport-automobile","tag-sport-en-general"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1639154"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1639154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1639155"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1639154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1639154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1639154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}