{"id":1638826,"date":"2025-04-23T08:13:42","date_gmt":"2025-04-23T10:13:42","guid":{"rendered":"https:\/\/teknomers.com\/fr\/annulation-surprenante-de-la-coupe-du-monde-par-van-gerwen\/"},"modified":"2025-04-23T08:13:47","modified_gmt":"2025-04-23T10:13:47","slug":"annulation-surprenante-de-la-coupe-du-monde-par-van-gerwen","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/annulation-surprenante-de-la-coupe-du-monde-par-van-gerwen\/","title":{"rendered":"Annulation surprenante de la Coupe du monde par Van Gerwen"},"content":{"rendered":"\n<div>\n<p>Une surprise suit apr\u00e8s le premier succ\u00e8s. La superstar de fl\u00e9chettes Michael Van Gerwen a annul\u00e9 sa participation \u00e0 la Coupe du monde de Darts 2025 et ne rivalisera pas pour les Pays-Bas lors de la Coupe du monde de l&#8217;\u00e9quipe que jamais. <\/p>\n<p>Michael Van Gerwen a finalement mis fin \u00e0 sa p\u00e9riode de s\u00e9cheresse. Le lundi de P\u00e2ques, il a gagn\u00e9 au Grand Prix de Darts allemand avec des couleurs volantes.<\/p>\n<p>Il a ensuite d\u00e9clar\u00e9 dans une interview avec &#8220;Dartsnews.de&#8221; qu&#8217;il ne participerait pas \u00e0 la Coupe du monde de Darts 2025 pour les Pays-Bas.<\/p>\n<p>&#8220;Je ne ferai pas partie de l&#8217;\u00e9quipe cette ann\u00e9e &#8211; je suis en vacances&#8221;, a d\u00e9clar\u00e9 le champion du monde \u00e0 trois heures lorsqu&#8217;il a \u00e9t\u00e9 adress\u00e9 \u00e0 une \u00e9ventuelle interaction dans la comp\u00e9tition d&#8217;\u00e9quipe avec l&#8217;adversaire final Gian Van Veen.<\/p>\n<p>Et en outre: &#8220;Peut-\u00eatre que c&#8217;est une option pour l&#8217;avenir &#8211; mais vous ne savez plus jamais ce qui se passe. Peut-\u00eatre que je ne participerai plus jamais \u00e0 la Coupe du monde des fl\u00e9chettes.&#8221;<\/p>\n<p>La Coupe du monde de Darts 2025 se d\u00e9roule \u00e0 Francfort \u00e0 mi-juin. Van Gerwen a remport\u00e9 la comp\u00e9tition de l&#8217;\u00e9quipe PDC trois fois jusqu&#8217;\u00e0 pr\u00e9sent.<\/p>\n<h2>Van Gerwen: &#8220;Le monde signifie-t-il pour moi&#8221;<\/h2>\n<p>Van Gerwen a gagn\u00e9 8: 5 au Grand Prix de Darts allemand le lundi de P\u00e2ques lors de la finale n\u00e9erlandaise contre Van Veen. &#8220;Mighty Mike&#8221; a remport\u00e9 son 38e titre sur la tourn\u00e9e europ\u00e9enne, avec laquelle il a encore \u00e9largi son record.<\/p>\n<p>&#8220;Cela signifie certainement beaucoup pour moi. Je suis dans une phase tr\u00e8s difficile de ma carri\u00e8re. Gagner cet \u00e9v\u00e9nement avec la pression de la semaine apr\u00e8s la semaine pour gagner signifie le monde&#8221;, Van Gerwen a \u00e9t\u00e9 cit\u00e9 par PDC Europe.<\/p>\n<p>Le N\u00e9erlandais a recherch\u00e9 une forme au cours des derni\u00e8res semaines. Entre les deux, les probl\u00e8mes d&#8217;\u00e9paule l&#8217;ont \u00e9galement ralenti. Le Grand Prix de Darts allemand est le premier tournoi de classement que les N\u00e9erlandais ont remport\u00e9 en 2025. La superstar per\u00e7oit un prix de 30 000 \u00a3 (environ 35 000 euros).<\/p>\n<p>Van Gerwen a pr\u00e9valu sur le chemin de la finale contre Kim Huybrechts (6: 5), Ryan Searle (6: 1), Ryan Joyce (6: 4) et Josh Rock (7: 2). Avec duel avec Searle, &#8220;MVG&#8221; a jou\u00e9 un 9-DARTER et a laiss\u00e9 la salle trembler.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne7706717\/darts-ueberraschende-wm-absage-van-gerwen-will-nicht-fuer-die-niederlande-spielen\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-8<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une surprise suit apr\u00e8s le premier succ\u00e8s. La superstar de fl\u00e9chettes Michael Van Gerwen a annul\u00e9 sa participation \u00e0 la Coupe du monde de Darts 2025 et ne rivalisera pas pour les Pays-Bas lors de la Coupe du monde de l&#8217;\u00e9quipe que jamais. Michael Van Gerwen a finalement mis fin \u00e0 sa p\u00e9riode de s\u00e9cheresse. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1638827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[6070,1008,79232,16319,16320,136655,1056,164,274200,9004,2536],"class_list":["post-1638826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-annulation","tag-coupe","tag-coupe-du-monde-de-flechettes","tag-flechettes","tag-gerwen","tag-michael-van-gerwen","tag-monde","tag-par","tag-sport-en-general","tag-surprenante","tag-van"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1638826"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1638827"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1638826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1638826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1638826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}