{"id":1638687,"date":"2025-04-23T06:22:39","date_gmt":"2025-04-23T08:22:39","guid":{"rendered":"https:\/\/teknomers.com\/fr\/2-bundesliga-hsv-avec-le-programme-le-plus-leger-restant-cologne-a-egalement-de-bonnes-cartes\/"},"modified":"2025-04-23T06:22:44","modified_gmt":"2025-04-23T08:22:44","slug":"2-bundesliga-hsv-avec-le-programme-le-plus-leger-restant-cologne-a-egalement-de-bonnes-cartes","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/2-bundesliga-hsv-avec-le-programme-le-plus-leger-restant-cologne-a-egalement-de-bonnes-cartes\/","title":{"rendered":"2. Bundesliga: HSV avec le programme le plus l\u00e9ger restant &#8211; Cologne a \u00e9galement de bonnes cartes"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Personnes en position <\/p>\n<div class=\"newsBild\">\n<p>\n                                       <span>\u00a9 TM \/ Imago<\/span>\n                                    <\/p>\n<\/p><\/div>\n<p>La lutte de promotion dans la 2e Bundesliga promet une tension jusqu&#8217;\u00e0 la fin. Th\u00e9oriquement, dix clubs peuvent se retrouver dans les deux premiers rangs avec quatre matchs exceptionnels. Le 1. FC K\u00f6ln et Hamburger SV ont actuellement les meilleures cartes \u00e0 ces endroits, mais ils se remuent \u00e9galement de temps en temps, comme d&#8217;autres dans le tiers sup\u00e9rieur de la table. Mais m\u00eame \u00e0 l&#8217;autre bout du tableau, aucune d\u00e9cision finale n&#8217;a \u00e9t\u00e9 prise. Le march\u00e9 des transferts donne un aper\u00e7u du programme restant des clubs de deuxi\u00e8me division.<\/p>\n<p><\/p>\n<div class=\"img-news-container\">\n<div class=\"img-news\"><img loading=\"lazy\" decoding=\"async\" class=\"innews\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2025\/04\/1745396558_839_2-Bundesliga-HSV-avec-le-programme-le-plus-leger-restant.jpg\" alt=\"Le programme restant par rang dans la 2e Bundesliga\" width=\"503\" height=\"628\"\/><\/div>\n<\/p><\/div>\n<p>&#8220;Si nous avions jou\u00e9 \u00e0 chaque match de mani\u00e8re convaincante, nous aurions peut-\u00eatre d\u00e9j\u00e0 lev\u00e9 maintenant. Ce n&#8217;\u00e9tait pas le cas, il reste super \u00e9troit et peut \u00eatre \u00e0 nouveau diff\u00e9rent avec le prochain jour de match&#8221;, a d\u00e9clar\u00e9 le capitaine du FC Timo H\u00fcber apr\u00e8s la victoire 3-1 contre la Prussia M\u00fcnster et averti ses co\u00e9quipiers, m\u00eame contre les adversaires apparemment plus faciles. Parce qu&#8217;un regard sur les semaines \u00e0 venir r\u00e9v\u00e8le: les r\u00e9sidents de Domstadt ont le deuxi\u00e8me programme le plus restant du top 10 avec Hanovre 96, Jahn Regensburg, le 1er FC N\u00fcrnberg et le 1. FC Kaiserslautern, qui ont un rang de table moyen de 10,75.<\/p>\n<p><\/p>\n<p>Le calendrier est cens\u00e9 \u00eatre encore mieux avec le HSV (13h00), qui veut enfin grimper dans le septi\u00e8me, avec des duels contre Karlsruher SC, Darmstadt 98, SSV ULM et SPVGG Greuther F\u00fcrth. Mais le 2: 2 \u00e0 Schalke 04 \u00e9tait un nouvel amortisseur apr\u00e8s avoir d\u00e9j\u00e0 perdu contre Eintracht Braunschweig. &#8220;Ils recommencent \u00e0 trembler. Vous l&#8217;avez senti un peu&#8221;, a d\u00e9clar\u00e9 Schalke Ron Schallenberg \u00e0 &#8220;Sky&#8221;.<\/p>\n<p><\/p>\n<p>Jusqu&#8217;\u00e0 Hanover \u00e0 la dixi\u00e8me place pour le 1er FC Magdeburg, SV Elversberg, SC Padersorn, Fortuna D\u00fcsseldorf, Kaisrslautern, Nuremberg et le KSC sont toujours possibles dans les deux premiers endroits qui signifient une ascension directe vers la Bundesliga. Le rang de rel\u00e9gation trois pourrait \u00e9galement atteindre Hertha BSC, l&#8217;\u00e9quipe la plus puissante, Schalke et Darmstadt. De ce cercle, mesur\u00e9 par les rangs moyens des adversaires de Hanover, Hertha et Darmstadt avec une valeur de 10,75 chacun. Les adversaires d&#8217;Elversberg (10,25) se d\u00e9placent \u00e9galement dans ce domaine. Le plus dur, en revanche, est pour Nuremberg (6.50) et Padersborn (7.25).<\/p>\n<div class=\"img-news-container\">\n<div class=\"img-news\"><img loading=\"lazy\" decoding=\"async\" class=\"innews\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/12\/1733058142_171_Lors-de-lachat-de-Hanovre-96-Franca-etait-six-centimetres.jpg\" alt=\"Dans le forum sur les clubs de la 2e Bundesliga, avez leur mot \u00e0 dire!\" width=\"503\" height=\"148\"\/><\/div>\n<\/p><\/div>\n<\/p>\n<p><\/p>\n<h2>Bataille de descente: Braunschweig avec un programme restant un peu plus lourd<\/h2>\n<p>Dans la course \u00e0 la rel\u00e9gation, Jahn Regensburg n&#8217;a pratiquement aucune vue sur un sauvetage. L&#8217;\u00e9cart du 15e Braunschweig est onze points, plus le deuxi\u00e8me programme restant (9,25) dans la table de la table avec un duel contre Cologne. Mais l&#8217;ulm et M\u00fcnster gisant devant lui devraient \u00e9galement rattraper sept ou cinq points sur le BTSV pour un s\u00e9jour en toute s\u00e9curit\u00e9 dans la 2e ligue, qui est actuellement l&#8217;une des \u00e9quipes les plus puissantes de la maison basse. Les autres adversaires pourraient donner un peu d&#8217;espoir pour l&#8217;ULM et les M\u00fcnsteraners attendent un programme restant un peu plus l\u00e9ger avec des rangs moyens de 10,50 et 10,75 que pour le Braunschweig (9,00).<\/p>\n<p><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/aufstieg-im-7-anlauf-hsv-mit-leichtestem-restprogramm-auch-koln-hat-gute-karten\/view\/news\/452918\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personnes en position \u00a9 TM \/ Imago La lutte de promotion dans la 2e Bundesliga promet une tension jusqu&#8217;\u00e0 la fin. Th\u00e9oriquement, dix clubs peuvent se retrouver dans les deux premiers rangs avec quatre matchs exceptionnels. Le 1. FC K\u00f6ln et Hamburger SV ont actuellement les meilleures cartes \u00e0 ces endroits, mais ils se remuent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1638688,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[8305,11787,135681,200614,9027,84,8681,138,5001,2069,1909,18602,1623,9948,1798,274895,7060,1004,50812,710,4802,17832,8574,17368,14962,9417,82742,25150,45238,7745,103329],"class_list":["post-1638687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-1-fc-kaiserslautern","tag-1-fc-cologne","tag-1-fc-magdeburg","tag-1-fc-nuremberg","tag-2-bundesliga","tag-avec","tag-bonnes","tag-bundesliga","tag-cartes","tag-cologne","tag-egalement","tag-eintracht-braunschweig","tag-fc-schalke-04","tag-fortuna-dusseldorf","tag-hamburger-sv","tag-hanover-96","tag-hertha-bsc","tag-hsv","tag-karlsruher-sc","tag-leger","tag-programme","tag-prusse-munster","tag-restant","tag-ron-schallenberg","tag-sc-paderborn-07","tag-spvgg-greuther-furth","tag-ssv-jahn-regensburg","tag-ssv-ulm-1846","tag-sv-07-elversberg","tag-sv-darmstadt-98","tag-timo-hubers"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1638687"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1638688"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1638687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1638687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1638687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}