{"id":1638278,"date":"2025-04-22T22:43:55","date_gmt":"2025-04-23T00:43:55","guid":{"rendered":"https:\/\/teknomers.com\/fr\/fc-bayern-thomas-muller-a-annule-mls-club-qui-a-des-consequences\/"},"modified":"2025-04-22T22:44:00","modified_gmt":"2025-04-23T00:44:00","slug":"fc-bayern-thomas-muller-a-annule-mls-club-qui-a-des-consequences","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/fc-bayern-thomas-muller-a-annule-mls-club-qui-a-des-consequences\/","title":{"rendered":"FC Bayern: Thomas M\u00fcller a annul\u00e9 MLS-Club-qui a des cons\u00e9quences"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div data-testid=\"StageLayout.StreamItem\">\n<h2 class=\"grid gap-8 text-salemsfur\"><span class=\"text-14 md:text-16\" data-external-article-kicker=\"FC Bayern\">FC Bayern <\/span><\/p>\n<p>Thomas M\u00fcller a annul\u00e9 MLS-Club-qui a des cons\u00e9quences<\/p>\n<\/h2>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<div class=\"grid grid-flow-row gap-8 grid-cols-1 pt-8 md:grid-flow-col md:justify-between border-t border-solid border-t-whitelilac\">\n<hr class=\"h-1 min-h-1 bg-whitelilac md:hidden\"\/>\n<p><span class=\"text-manatee text-12 leading-15\">23\/04\/2025 &#8211; 02:01 A.M.<\/span><span class=\"text-manatee text-12 leading-15\">Temps de lecture: 3 min.<\/span><\/p>\n<\/div>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<figure><a rel=\"nofollow\" href=\"#focus-0\" class=\"transition-colors duration-200 focus-within:text-magenta block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><span><picture><source media=\"(prefers-color-scheme:dark)\"  type=\"image\/svg+xml\"\/><img style=\"--width:32;--height:32\" loading=\"lazy\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/11\/Saut-a-ski-lAllemagne-remporte-la-premiere-Coupe-du.svg.svg+xml\" alt=\"Agrandir l'image\" title=\"Agrandir l'image\" class=\"&#10;        block&#10;        h-[calc(var(--height)_\/_16_*_1rem)]&#10;        w-[calc(var(--width)_\/_16_*_1rem)]&#10;        max-w-none&#10;        absolute bottom-8 right-8 rounded-4 bg-snow p-8\" decoding=\"async\"\/><\/picture><\/span><\/a><\/p>\n<p><figcaption class=\"inline-block text-12 leading-15 pt-12\">Au FC Bayern, Thomas M\u00fcller (\u00e0 gauche) est actuellement principalement sur le banc. O\u00f9 va-t-il dans l&#8217;ann\u00e9e \u00e0 venir?<!-- --> (Source: Imago \/ Frank Hoermann \/ Sven Simon)<\/figcaption><\/p>\n<\/figure>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 leading-17\">Quelle est la prochaine \u00e9tape avec le Bayern Clubidol Thomas M\u00fcller? Selon un rapport des m\u00e9dias, l&#8217;attaquant a maintenant annul\u00e9 un club dans l&#8217;American MLS.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">L&#8217;avenir de Thomas M\u00fcller est probablement l&#8217;une des d\u00e9tails personnels les plus visibles de la saison de Bundesliga expir\u00e9e: o\u00f9 est l&#8217;attaquant de Bavi\u00e8re apr\u00e8s son d\u00e9part de son club cardiaque en \u00e9t\u00e9? Une chose est certaine que l&#8217;homme de 35 ans ne pourra pas encore tra\u00eener les chaussures de football, mais dans quel club il change, la sp\u00e9culation tire actuellement dans l&#8217;herbe.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Maintenant, il devrait y avoir un grand int\u00e9r\u00eat dans une obligation M\u00fcller de la s\u00e9rie italienne A. L\u00e0, selon le journal &#8220;Bild&#8221; et l&#8217;expert en transfert Gianluca di Marzio, l&#8217;AC Florence a r\u00e9pandu ses palpeurs apr\u00e8s le champion du monde 2014.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">&#8220;En ce qui concerne Thomas M\u00fcller, je peux confirmer que la Fiorentina a appel\u00e9 son consultant pour en savoir plus. Il n&#8217;y a pas de contrat, mais vous vous avez demand\u00e9 si M\u00fcller voulait passer en Italie parce qu&#8217;aucun club italien ne peut suivre son salaire au Bayern Munich&#8221;. L&#8217;Italien Di Marzio a d\u00e9clar\u00e9 au Portal Internet &#8220;Bettfreunde.net&#8221;.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">L&#8217;agent de M\u00fcller n&#8217;a cens\u00e9 pas avoir r\u00e9pondu &#8220;car il collectera et \u00e9valuera probablement tous les clubs int\u00e9ress\u00e9s, puis parlera \u00e0 Thomas \u00e0 la fin de la saison pour voir s&#8217;il veut rester en Europe, en Arabie saoudite ou en MLS&#8221;.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Comme le rapporte le &#8220;Sport Bild&#8221;, M\u00fcller aurait d\u00e9j\u00e0 rejet\u00e9 une offre du MLS Club FC Cincinnati. L&#8217;association de la First American Professional League avait mis M\u00fcller sur la soi-disant liste de d\u00e9couverte avec des joueurs avec lesquels vous souhaitez n\u00e9gocier un transfert sans l&#8217;int\u00e9r\u00eat du joueur. C&#8217;est une pratique courante aux \u00c9tats-Unis.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Le fait que M\u00fcller ne veuille pas passer \u00e0 l&#8217;Ohio est regrettable pour le FC Cincinnati, mais le club garde maintenant une sorte de juste refus, car il vient de voir M\u00fcller sur cette liste de d\u00e9couverte. Si un autre club de la Major League Soccer (MLS) veut n\u00e9gocier avec la star du Bayern, il doit d&#8217;abord acheter Cincinnati.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Il est donc all\u00e9 au transfert par Los Angeles Galaxy de l&#8217;ex-Dortmunders Marco Reus. Ce dernier avait d\u00fb acheter Charlotte FC le droit d&#8217;acc\u00e9der aux n\u00e9gociations avec Reus. M\u00fcller est \u00e9galement associ\u00e9 \u00e0 LA Galaxy, car le club de l&#8217;American Professional League est en bonne connexion en tant qu&#8217;association partenaire avec le Bayern du FC.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">D\u00e9but avril, le Bayern avait annonc\u00e9 que le contrat d&#8217;expiration de M\u00fcller ne serait pas prolong\u00e9. Le champion du monde 2014 n&#8217;est qu&#8217;une force en temps de partie parmi Munich. Le dernier voyage d&#8217;affaires de M\u00fcller avec le Bayern du FC sera la Coupe du monde du club du 15 juin au 13 juillet aux \u00c9tats-Unis. Ce qu&#8217;il fait par la suite est toujours ouvert.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">Le Bayern veut vraiment l&#8217;int\u00e9grer dans le travail du club plus tard. Le pr\u00e9sident Herbert Hainer a finalement d\u00e9crit M\u00fcller comme \u00abla quintessence d&#8217;une carri\u00e8re de livre d&#8217;images bavarois\u00bb.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 leading-17\">M\u00fcller sp\u00e9cule \u00e9galement sur les int\u00e9r\u00eats des clubs des \u00c9tats-Unis, de l&#8217;Angleterre et de la Turquie. Les anciennes stars de la Bavi\u00e8re ont d\u00e9j\u00e0 emprunt\u00e9 le chemin de Munich \u00e0 Florence. Mario Gomez a jou\u00e9 pour les Italiens de 2013 \u00e0 2015, Franck Rib\u00e9ry de 2019 \u00e0 2021. Florence essaiera de rendre M\u00fcller savoureux &#8220;qu&#8217;il peut jouer librement et profiter d&#8217;une ville qui l&#8217;aimera&#8221;, a d\u00e9clar\u00e9 Di Marzio.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/fussball\/bundesliga\/fc-bayern-muenchen\/id_100689594\/fc-bayern-thomas-mueller-sagt-mls-klub-ab-das-hat-konsequenzen.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FC Bayern Thomas M\u00fcller a annul\u00e9 MLS-Club-qui a des cons\u00e9quences 23\/04\/2025 &#8211; 02:01 A.M.Temps de lecture: 3 min. Au FC Bayern, Thomas M\u00fcller (\u00e0 gauche) est actuellement principalement sur le banc. O\u00f9 va-t-il dans l&#8217;ann\u00e9e \u00e0 venir? (Source: Imago \/ Frank Hoermann \/ Sven Simon) Quelle est la prochaine \u00e9tape avec le Bayern Clubidol Thomas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1638279,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[224647,282446,1388,1745,657,383,311,65915,1341,3202,133,89070,200148,11536,360,276648,5381,300407,8189,1742,4340,11161,2001],"class_list":["post-1638278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-224647","tag-ac-florence","tag-accord","tag-annule","tag-banque","tag-baviere","tag-bayern","tag-cincinnati","tag-club","tag-consequences","tag-des","tag-di-marzio","tag-fc-bayern-munich","tag-franck-ribery","tag-italie","tag-journal-bild","tag-marco-reus","tag-mlsclubqui","tag-muller","tag-munich","tag-thomas","tag-thomas-muller","tag-usa"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1638278"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1638279"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1638278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1638278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1638278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}