{"id":1638272,"date":"2025-04-22T22:36:31","date_gmt":"2025-04-23T00:36:31","guid":{"rendered":"https:\/\/teknomers.com\/fr\/un-voisin-a-crie-la-crise-complete-de-hjk-video-derriere-le-stade\/"},"modified":"2025-04-22T22:36:36","modified_gmt":"2025-04-23T00:36:36","slug":"un-voisin-a-crie-la-crise-complete-de-hjk-video-derriere-le-stade","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/un-voisin-a-crie-la-crise-complete-de-hjk-video-derriere-le-stade\/","title":{"rendered":"Un voisin a cri\u00e9 la crise compl\u00e8te de HJK &#8211; Vid\u00e9o: Derri\u00e8re le stade"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>Le gnistan a remport\u00e9 HJK 1-0.<\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"padding-bottom:66.66666666666666%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2025\/04\/1745368591_133_Un-voisin-a-crie-la-crise-complete-de-HJK.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2025\/04\/1745368591_133_Un-voisin-a-crie-la-crise-complete-de-HJK.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2000\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Joakim Latonen tuuletti Gnistanin voittomaalia. \"\/><span class=\"caption-text\" itemprop=\"description\">Joakim Latonen a ventil\u00e9 le but gagnant du Gnistan. <!-- --> <\/span><span class=\"media-source\">Matti Matikainen<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">HJK s&#8217;est finalement effondr\u00e9 lors de l&#8217;ouverture \u00e0 domicile de la saison en crise.<\/p>\n<p class=\"paragraph\">Le minuscule club voisin Gnistan est all\u00e9 \u00e0 T\u00f6\u00f6l\u00f6 pour trouver une pr\u00e9cieuse victoire \u00e0 l&#8217;ext\u00e9rieur 1-0 <strong>Joakim latosen<\/strong> Rankkari.<\/p>\n<p class=\"paragraph\">Il s&#8217;agit du tube de perte le plus long de l&#8217;histoire de HJK, y compris la fin de la saison derni\u00e8re. Au total, le club a maintenant subi six pertes de ligue cons\u00e9cutives.<\/p>\n<p class=\"paragraph\">SJK et Ilves ont d\u00e9j\u00e0 neuf points au sommet de cette saison Veikkausliiga.<\/p>\n<p class=\"paragraph\">En m\u00eame temps la pression de l&#8217;entra\u00eeneur-chef <strong>Toni du haut comit\u00e9<\/strong> Afin de distinguer.<\/p>\n<p class=\"paragraph\">&#8211; Nous n&#8217;avons pas la d\u00e9termination \u00e0 atteindre ces objectifs. Des situations individuelles se sont retourn\u00e9es contre nous, et il a estim\u00e9 que le coll\u00e8ge avait fait allusion \u00e0 une douceur de taches.<\/p>\n<p class=\"paragraph\">&#8211; Que ce soit appropri\u00e9 ou non, bien s\u00fbr, les moments doivent \u00eatre plus prudents.<\/p>\n<h3 class=\"subheadline\">&#8220;Au-del\u00e0 du bal&#8221;<\/h3>\n<p class=\"paragraph\">Dans le cas d <strong>Daniel O&#8217;Shaughnessy<\/strong> J&#8217;ai un avertissement.<\/p>\n<p class=\"paragraph\">&#8211; L&#8217;attaquant a pass\u00e9 le ballon devant le ballon. Je ne pense pas que je l&#8217;ai frapp\u00e9. Le juge a vu diff\u00e9remment, a d\u00e9clar\u00e9 O&#8217;Shaughnessy \u00e0 Iltalehti.<\/p>\n<p class=\"paragraph\">&#8211; Cependant, le jeu ne l&#8217;a pas r\u00e9solu. Nous n&#8217;\u00e9tions pas assez bons aujourd&#8217;hui. Nous devons clairement am\u00e9liorer et faire avancer les choses.<\/p>\n<p class=\"paragraph\">Le point culminant a \u00e9t\u00e9 \u00e9tonnamment calme apr\u00e8s le match, bien qu&#8217;il y ait certainement eu une temp\u00eate \u00e0 l&#8217;esprit.<\/p>\n<p class=\"paragraph\">&#8211; Nous \u00e9tions les pires ennemis de nous-m\u00eames. M\u00eame les flux faciles ne se sont pas bien comport\u00e9s. Nous n&#8217;avons pas eu un bon rythme \u00e0 jouer.<\/p>\n<p class=\"paragraph\">Directeur sportif <strong>Petri Vuorinen<\/strong> est confront\u00e9 \u00e0 des d\u00e9cisions difficiles. Bien s\u00fbr, bl\u00e2mer l&#8217;Universit\u00e9 de la situation \u00e0 elle seule est \u00e0 court terme, car la crise est due \u00e0 l&#8217;\u00e9chec de toute l&#8217;organisation.<\/p>\n<p class=\"paragraph\">&#8211; La situation est difficile. Nous sommes \u00e0 z\u00e9ro \u00e0 un point apr\u00e8s trois tours. Apr\u00e8s tout, cela ne tourne pas comme le travail, a d\u00e9clar\u00e9 le coll\u00e8ge.<\/p>\n<p class=\"paragraph\">Et le r\u00e9sultat n&#8217;\u00e9tait pas une injustice, car le gnistan a d\u00e9fendu HJK dans la pratique compl\u00e8tement hors du secteur de la peinture.<\/p>\n<p class=\"paragraph\">&#8211; La principale id\u00e9e est que cette victoire historique pour la communaut\u00e9 et le quartier. Doit \u00eatre vraiment heureux, l&#8217;entra\u00eeneur-chef des r\u00e9sidents d&#8217;Oulunkyl\u00e4 <strong>Jussi Lepp\u00e4lahti<\/strong> se r\u00e9jouit.<\/p>\n<h3 class=\"subheadline\">Tires vides<\/h3>\n<p class=\"paragraph\">L&#8217;\u00e9quipe \u00e0 domicile a peut-\u00eatre \u00e9t\u00e9 influenc\u00e9e par le fait que Derby du premier stade de la saison a \u00e9t\u00e9 jou\u00e9 pour les sous-bois. L&#8217;association de football avait puni HJK pour la perturbation des supporters en fermant les deux extr\u00e9mit\u00e9s.<\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/img.ilcdn.fi\/3N5asoL9Wz11cq0APD6N64vkbP0=\/full-fit-in\/920x0\/img-s3.ilcdn.fi\/3e942d4fc5f6f0c2adb018e02be3828208d43d52cf39d969974143ccfc29655d.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2001\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"HJK-fanit protestoivat stadionin ulkopuolella Palloliiton kurinpitorangaistusta vastaan. \"\/><span class=\"caption-text\" itemprop=\"description\">Les fans de HJK ont protest\u00e9 en dehors du stade contre la peine disciplinaire de l&#8217;association de football. <!-- --> <\/span><span class=\"media-source\">Matti Matikainen<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">6 220 spectateurs ont \u00e9t\u00e9 frapp\u00e9s par une catastrophe devant la colline de la souris. En m\u00eame temps aussi <strong>Alex Ringin<\/strong> Les cris \u00e9taient tr\u00e8s bons pour les galeries. Le g\u00e9n\u00e9ral de milieu de terrain a exig\u00e9 plus de ses co\u00e9quipiers.<\/p>\n<div class=\"iltv-embed vertical\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/VideoObject\"><meta itemprop=\"name\" content=\"Klubip\u00e4\u00e4ty piti protestin stadionin ulkopuolella.\"\/><meta itemprop=\"caption\" content=\"Klubip\u00e4\u00e4ty piti protestin stadionin ulkopuolella.\"\/><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/cdn.jwplayer.com\/v2\/media\/pnhWbsmA\/poster.jpg?width=720\"\/><meta itemprop=\"uploadDate\" content=\"2025-04-22T21:48:27+03:00\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Klubip\u00e4\u00e4ty piti protestin stadionin ulkopuolella.\"\/><span class=\"caption-text\" itemprop=\"description\">La fin du club a donn\u00e9 une manifestation \u00e0 l&#8217;ext\u00e9rieur du stade.<!-- --> <\/span><span class=\"media-source\">Janne Palom\u00e4ki<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">&#8211; Cela n&#8217;ira pas au sommet des fans. Nous le quittons et la motivation. Peut-\u00eatre que nous n&#8217;avons pas obtenu ce genre d&#8217;incendie de jeu local, a continu\u00e9 O&#8217;Shaugnessy.<\/p>\n<p class=\"paragraph\">&#8211; Nous n&#8217;avons pas pu cr\u00e9er une menace dans la direction offensive. Il y a un cr\u00e9dit dans les vestiaires que cela tourne encore. Les r\u00e9sultats ne sont pas acceptables.<\/p>\n<p class=\"paragraph\">Bien que les deux gangs se soient d\u00e9roul\u00e9s dans le syst\u00e8me local en tant que Club z\u00e9ro, HJK devait prendre la commande sur le terrain. Le gnistan \u00e9tait lourdement \u00e0 T\u00f6\u00f6l\u00f6 comme une aile -up parce que juste avant le match, il a perdu <strong>Oliver Pettersson<\/strong> et <strong>Jukka Raiala<\/strong> pour les malades.<\/p>\n<p class=\"paragraph\">L&#8217;inverse s&#8217;est produit. L&#8217;agitation du club n&#8217;\u00e9tait accentu\u00e9e que par l&#8217;atmosph\u00e8re d\u00e9vou\u00e9e de Bolt. Des membres du club Head avaient install\u00e9 leur propre ombre sur le rocher au large du stade olympique, mais leur contribution au match \u00e9tait limit\u00e9e aux feux d&#8217;artifice de la deuxi\u00e8me p\u00e9riode.<\/p>\n<p class=\"paragraph\">Plus le match a progress\u00e9, plus <strong>Teemu Pukki<\/strong> Le club \u00e9tait au sommet du club. L&#8217;attaquant v\u00e9t\u00e9ran recherche toujours le premier but de la saison de la ligue, et la frustration d&#8217;un soutien modeste s&#8217;est refl\u00e9t\u00e9e dans sa nervosit\u00e9 exceptionnelle.<\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/img.ilcdn.fi\/X_y5Y8JsgKjy9o_W9MRuCDFuqwo=\/full-fit-in\/920x0\/img-s3.ilcdn.fi\/d82f8cce8ec9411c97d44538f8297f80b60dd99446c07e2be11455e3eb975036.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2000\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Gnistan-puolustus piti Teemu Pukin (vas.) pimennossa. \"\/><span class=\"caption-text\" itemprop=\"description\">La d\u00e9fense du gnistan a gard\u00e9 Teemu Puki (\u00e0 gauche) dans l&#8217;obscurit\u00e9. <!-- --> <\/span><span class=\"media-source\">Matti Matikainen<\/span><\/p>\n<\/div>\n<h3 class=\"subheadline\">Kirii n&#8217;est pas n\u00e9<\/h3>\n<p class=\"paragraph\">Le meilleur endroit pour les h\u00f4tes est venu \u00e0 la toute fin de l&#8217;\u00e9pisode, mais Pukki a tir\u00e9 le Hutipot traditionnel et les cons\u00e9quences du Gnistan Viden <strong>Alex Craninx<\/strong> \u00e9tir\u00e9 <strong>Lucas Swingman<\/strong> devant un pari.<\/p>\n<p class=\"paragraph\">Au cours de la deuxi\u00e8me p\u00e9riode, HJK n&#8217;a m\u00eame pas pass\u00e9 un bon moment. Il n&#8217;a que quelques jours pour ramener les lignes, car les VP viendront dans ce m\u00eame village d&#8217;ar\u00e8ne le samedi prochain.<\/p>\n<p class=\"paragraph\">&#8211; Il est de la responsabilit\u00e9 de chacun de changer cela. Nous devons regarder dans le miroir o\u00f9 nous pouvons gu\u00e9rir, a d\u00e9cid\u00e9 O&#8217;Shaughnessy.<\/p>\n<p class=\"paragraph\">Le gnistan, d&#8217;autre part, obtient un joli vent pour le match d&#8217;ouverture de la Black Pekka Arena, qui attend dimanche. L&#8217;\u00e9tincelle fait face \u00e0 l&#8217;\u00e9quipe champion Kups.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/veikkausliiga\/a\/5c26f9c1-2a1e-4601-80c4-91ac544c45f4\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-49<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gnistan a remport\u00e9 HJK 1-0. Joakim Latonen a ventil\u00e9 le but gagnant du Gnistan. Matti Matikainen HJK s&#8217;est finalement effondr\u00e9 lors de l&#8217;ouverture \u00e0 domicile de la saison en crise. Le minuscule club voisin Gnistan est all\u00e9 \u00e0 T\u00f6\u00f6l\u00f6 pour trouver une pr\u00e9cieuse victoire \u00e0 l&#8217;ext\u00e9rieur 1-0 Joakim latosen Rankkari. Il s&#8217;agit du tube [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1638273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[153,23850,19044,380,4109,267614,267613,91,30157,54711,282481,1378,68,12606],"class_list":["post-1638272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-24h","tag-complete","tag-crie","tag-crise","tag-derriere","tag-especes-basees-sur-le-football","tag-exercice-et-sports","tag-football","tag-football-finlandais","tag-hjk","tag-ligue-de-paris","tag-stade","tag-video","tag-voisin"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1638272"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1638272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1638273"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1638272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1638272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1638272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}