{"id":1613144,"date":"2025-04-06T05:49:35","date_gmt":"2025-04-06T07:49:35","guid":{"rendered":"https:\/\/teknomers.com\/fr\/le-lecteur-de-journal-nos-harmen-siezen-84-sest-considere-comme-un-homme-timide-avec-une-etrange-profession\/"},"modified":"2025-04-06T05:49:40","modified_gmt":"2025-04-06T07:49:40","slug":"le-lecteur-de-journal-nos-harmen-siezen-84-sest-considere-comme-un-homme-timide-avec-une-etrange-profession","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/le-lecteur-de-journal-nos-harmen-siezen-84-sest-considere-comme-un-homme-timide-avec-une-etrange-profession\/","title":{"rendered":"Le lecteur de journal NOS Harmen Siezen (84) s&#8217;est consid\u00e9r\u00e9 comme \u00abun homme timide avec une \u00e9trange profession\u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Harmen Siezen a donn\u00e9 au NOS Journaal un visage humain: &#8220;Toujours un Seigneur et parfois une blague subtile avec un sourire prudent mais de l&#8217;\u00e9tude.&#8221; Par exemple, le ministre Eppo Bruins (Media, NSC) a r\u00e9pondu samedi \u00e0 la mort du lecteur de News.<\/p>\n<p>Harmen Siezen (84) a pr\u00e9sent\u00e9 le NOS Journaal de 1969 \u00e0 2002 et a \u00e9t\u00e9 la personnification des nouvelles t\u00e9l\u00e9vis\u00e9es pour de nombreux t\u00e9l\u00e9spectateurs, qui a \u00e9t\u00e9 diffus\u00e9 simultan\u00e9ment sur les deux filets dans les premi\u00e8res ann\u00e9es. Siezen a commenc\u00e9 \u00e0 l&#8217;\u00e9poque o\u00f9 les lecteurs de nouvelles \u00e9taient toujours \u00abp\u00e9trifi\u00e9s\u00bb derri\u00e8re leur bureau, a-t-il dit dans le livre <em>Les ic\u00f4nes du NOS Achtuurjournaal<\/em> (2012): &#8220;Pas de sourire, rien.&#8221; Le style plus l\u00e2che qui a fait dans les ann\u00e9es 1980 l&#8217;adapte mieux. &#8220;Il avait une sorte de l\u00e9g\u00e8ret\u00e9, une gaiet\u00e9 et aussi l&#8217;autorit\u00e9&#8221;, a tap\u00e9 l&#8217;ancienne coll\u00e8gue Marga van Praag, selon le <em>N \u00b0<\/em>.<\/p>\n<p>Il a \u00e9t\u00e9 r\u00e9guli\u00e8rement \u00e9lu le meilleur lecteur de journal de l&#8217;ann\u00e9e, mais cela n&#8217;a pas fait beaucoup d&#8217;impression sur lui: &#8220;Si je demandais ici qui ils pensent le meilleur lecteur de journaux, ils disent \u00e9galement que je suis&#8221; (&#8220;ic\u00f4nes&#8221;, 2012). C&#8217;\u00e9tait juste un travail, il savait. &#8220;Il ne s&#8217;agit pas de moi, mais des messages. Je suis une trappe. En fait, je suis un homme timide avec une profession \u00e9trange.&#8221;<\/p>\n<p>Bien qu&#8217;il ait pr\u00e9sent\u00e9 plus de dix-sept mille diffusions avec un auto-t\u00e9moignage parfait, il restera \u00e0 rappel qu&#8217;une fois il a ri. Au cours de l&#8217;article de la \u00abdouleur en selle\u00bb en 1991, il n&#8217;a plus pu se limiter, surtout parce qu&#8217;il a vu les techniciens rouler sur le sol de l&#8217;autre c\u00f4t\u00e9 de la fen\u00eatre. Selon Siezen, il a d\u00fb lire que la douleur en selle pouvait conduire \u00e0 &#8220;diminuer l&#8217;int\u00e9r\u00eat sexuel&#8221; (il y avait &#8220;libido&#8221; mais il pensait que c&#8217;\u00e9tait un mot trop difficile) tandis que dans l&#8217;image &#8220;de vieux coqs stupides&#8221; &#8220;par cycl\u00e8re. Il a trouv\u00e9 cette combinaison irr\u00e9sistible.<\/p>\n<h2 class=\"gn4-crosshead article-heading\">P\u00e8re \u00e0 Berlin<\/h2>\n<p>Harmen Siezen est n\u00e9 le lendemain de No\u00ebl au cours de l&#8217;ann\u00e9e de guerre de 1940 \u00e0 l&#8217;h\u00f4pital de Noordgouwe, sur l&#8217;\u00eele Z\u00e9landais de Schouwen-Duivenland. Il a grandi dans le proche village de Ring Dreischor o\u00f9 son p\u00e8re \u00e9tait ministre. En raison de ce travail, la famille a d\u00fb d\u00e9m\u00e9nager plusieurs fois, vers le chagrin du jeune Siezen: Zaltbommel, La Haye, Peize et \u00e9ventuellement Rotterdam. Ils lisent \u00e0 la maison <em>Parool het<\/em>Siezen aimait \u00e9couter les rapports sportifs \u00e0 la radio et les a ensuite imit\u00e9s avec un enregistreur de groupe. Quand il \u00e9tait au gymnase, son p\u00e8re a quitt\u00e9 la famille pour un emploi \u00e0 Berlin: &#8220;Il a dit: Je dois vous dire quelque chose. Je pars maintenant. Je quitte ta m\u00e8re.&#8221; Pour Siezen, c&#8217;\u00e9tait un grand choc: &#8220;Le divorce dans les ann\u00e9es 1950, c&#8217;\u00e9tait quelque chose! J&#8217;en avais honte, j&#8217;ai toujours dit qu&#8217;il \u00e9tait en vacances.&#8221;<\/p>\n<p>Siezen a commenc\u00e9 en 1962 \u00e0 l&#8217;emplacement de Haagse de l&#8217;agence de presse am\u00e9ricaine UPI, est pass\u00e9 en 1963 \u00e0 la radio Pirate Radio Veronica qui diffusait \u00e0 partir d&#8217;un navire sur la mer du Nord. En 1966, il est venu \u00e0 la section des affaires actuelles <em>Tros actua<\/em> Et en 1969, il a commenc\u00e9 comme journaliste \u00e0 la <em>Journal nos<\/em>. Les v\u00e9t\u00e9rans Frits Thors et Rien Huizing lui ont donn\u00e9 des le\u00e7ons dans les nouvelles apr\u00e8s les \u00e9missions. La premi\u00e8re fois \u00e0 la t\u00e9l\u00e9vision, il a eu les nerfs: &#8220;Puis j&#8217;ai pens\u00e9 un instant: Oh, mon Dieu. Vous consid\u00e9rez alors que tous ces gens vous regardent.&#8221; Mais cela a rapidement pass\u00e9 lors de la diffusion.<\/p>\n<p><dmt-image-wrapper><\/p>\n<figure class=\"gn4-inline\" data-source=\"gn4\"><picture><\/picture><figcaption class=\"description\">Harmen Siezen a pr\u00e9sent\u00e9 le NOS Journaal de 1969 \u00e0 2002. Photo Nos<\/figcaption><\/figure>\n<p><\/dmt-image-wrapper><\/p>\n<p>Siezen est rest\u00e9 presque continuellement avec elle pendant 33 ans <em>Journal nos<\/em>. Ce n&#8217;est qu&#8217;en 1989 qu&#8217;il est parti pour TV10, le diffuseur commercial de Joop van den Ende, qui n&#8217;a finalement re\u00e7u aucun permis d&#8217;emploi temporaire, apr\u00e8s quoi le producteur a d\u00fb rejeter tout le monde. Siezen a dit dans les &#8220; ic\u00f4nes &#8221; que Van Den Ende Paternal avait mis un bras autour de son \u00e9paule et a dit: &#8220;Ce n&#8217;\u00e9tait pas pour vous, Harmen, vous \u00eates un gar\u00e7on pour un club solide, avec une retraite.&#8221; Siezen a de nouveau \u00e9t\u00e9 embauch\u00e9e au NOS, mais n&#8217;\u00e9tait plus autoris\u00e9 \u00e0 pr\u00e9senter les huit nouvelles.<\/p>\n<p>Parmi les nombreux incendies mondiaux que Siezen Keieken a fait, la catastrophe de vol sur Tenerife de 1977 &#8211; la plus grande jamais &#8211; est rest\u00e9e le plus avec lui. Il s&#8217;est envol\u00e9 pour l&#8217;\u00eele espagnole en tant que journaliste et a vu plus de cinq cents victimes dans un hangar. Siezen \u00e9tait \u00e9galement l&#8217;homme qui a d\u00fb signaler la mort de Pim Fortuyn aux Pays-Bas le 6 mai 2002, directement dans le journal des six heures. Le politicien radical \u00e0 droite a \u00e9t\u00e9 assassin\u00e9 au coin du studio NOS. &#8220;Ma femme regardait \u00e0 la maison avec notre petite-fille de 4 ans, Pien. Elle a \u00e9galement vu le sanglant FORTUYN. Il a de la douleur au genou, ma femme a dit&#8221; (&#8220;Ic\u00f4nes&#8221;, 2011).<\/p>\n<h2 class=\"gn4-crosshead article-heading\">Rocky sur l&#8217;arc-en-ciel<\/h2>\n<p>En septembre 2002, il a arr\u00eat\u00e9 la nouvelle. Il avait clairement dit qu&#8217;il voulait partir avec du tambour silencieux, mais lors de la derni\u00e8re diffusion, le coll\u00e8gue Philip Freriks est venu dans le d\u00e9cor avec un bouquet de fleurs et un mot d&#8217;adieu. Siezen ne l&#8217;aimait pas: &#8220;J&#8217;ai trouv\u00e9 ces fleurs horribles, j&#8217;\u00e9tais vraiment en col\u00e8re \u00e0 ce sujet.&#8221;<\/p>\n<p>Il n&#8217;a jamais rat\u00e9 le travail par la suite, a-t-il dit plus tard. Il a montr\u00e9 un certain regret qu&#8217;il \u00e9tait toujours rest\u00e9 dans les nouvelles, tandis que son c\u00f4t\u00e9 humoristique et l\u00e2che est devenu le sien, par exemple, le <em>Quiz d&#8217;actualit\u00e9s nationales<\/em> qu&#8217;il a \u00e9galement pr\u00e9sent\u00e9, ou dans le r\u00f4le d&#8217;histoire qu&#8217;il avait dans la parodie musicale <em>Rocky sur l&#8217;arc-en-ciel<\/em> (2001), dans lequel il s&#8217;est pr\u00e9sent\u00e9 avec: &#8220;Vous me connaissez jusqu&#8217;\u00e0 ici. Ce soir, vous pouvez voir que j&#8217;ai aussi des jambes.&#8221;<\/p>\n<p>Siezen a appr\u00e9ci\u00e9 la pension avec sa femme dans le village de Hoevelaken \u00e0 Gelderland o\u00f9 ils ont v\u00e9cu pendant plus d&#8217;un demi-si\u00e8cle. <em\/> &#8220;Je n&#8217;ai plus \u00e0 aller \u00e0 la t\u00e9l\u00e9vision. Lorsque la prochaine g\u00e9n\u00e9ration est oubli\u00e9e, je pense que c&#8217;est bien aussi.&#8221; Ils avaient une maison de vacances sur Schouwen Duivenland. Parfois, il \u00e9tait \u00abreconnu\u00bb l\u00e0-bas, a-t-il dit dans le magazine \u00e2g\u00e9 en 2017 <em>Plus<\/em>. Puis ils ont cri\u00e9: &#8220;Hey Fred Emmer. Tu es toujours \u00e0 la t\u00e9l\u00e9vision?&#8221; Siezen a ensuite r\u00e9pondu: &#8220;Non, je suis Joop van Zijl.&#8221;<\/p>\n<p><dmt-util-bar article=\"4888954\" data-paywall-belowarticle=\"\" headline=\"NOS-nieuwslezer Harmen Siezen (84) zag zichzelf als \u2018een verlegen man met een raar beroep\u2019\" url=\"https:\/\/www.nrc.nl\/nieuws\/2025\/04\/06\/nos-nieuwslezer-harmen-siezen-84-zag-zichzelf-als-een-verlegen-man-met-een-raar-beroep-a4888954\"><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"share\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Partager<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-share-web\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"contact\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Envoyez les \u00e9diteurs<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-email\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<\/dmt-util-bar>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2025\/04\/06\/nos-nieuwslezer-harmen-siezen-84-zag-zichzelf-als-een-verlegen-man-met-een-raar-beroep-a4888954\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Harmen Siezen a donn\u00e9 au NOS Journaal un visage humain: &#8220;Toujours un Seigneur et parfois une blague subtile avec un sourire prudent mais de l&#8217;\u00e9tude.&#8221; Par exemple, le ministre Eppo Bruins (Media, NSC) a r\u00e9pondu samedi \u00e0 la mort du lecteur de News. Harmen Siezen (84) a pr\u00e9sent\u00e9 le NOS Journaal de 1969 \u00e0 2002 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1613145,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[84,1756,3494,17652,234945,569,2425,4380,5839,19318,768,293859,20182,196],"class_list":["post-1613144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-avec","tag-comme","tag-considere","tag-etrange","tag-harmen","tag-homme","tag-journal","tag-lecteur","tag-nos","tag-profession","tag-sest","tag-siezen","tag-timide","tag-une"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1613144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1613144"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1613144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1613145"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1613144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1613144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1613144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}