{"id":1569443,"date":"2025-03-07T12:37:29","date_gmt":"2025-03-07T14:37:29","guid":{"rendered":"https:\/\/teknomers.com\/fr\/caravaggio-2025-aux-chefs-doeuvre-de-palazzo-barberini-du-premier-du-moderne-du-monde-entier\/"},"modified":"2025-03-07T12:37:34","modified_gmt":"2025-03-07T14:37:34","slug":"caravaggio-2025-aux-chefs-doeuvre-de-palazzo-barberini-du-premier-du-moderne-du-monde-entier","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/caravaggio-2025-aux-chefs-doeuvre-de-palazzo-barberini-du-premier-du-moderne-du-monde-entier\/","title":{"rendered":"Caravaggio 2025, aux chefs-d&#8217;\u0153uvre de Palazzo Barberini du &#8220;premier du moderne&#8221; du monde entier"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\" id=\"audioReadingButton\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9coutez la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">&#8220;Il a risqu\u00e9 de devenir une sorte de gardien de but nocturne de la Renaissance.&#8221; Mais non, aux yeux du plus grand \u00e9rudit artistique italien du XXe si\u00e8cle, Roberto Longhi, Caravaggio prendra la place qu&#8217;il m\u00e9rite. Le premier de moderne, un peintre visionnaire et audacieux d&#8217;une force expressive in\u00e9gal\u00e9e en son temps. Il y a vingt-quatre \u0153uvres de collections publiques et priv\u00e9es, \u00e0 la fois italien et internationale &#8211; \u00e0 laquelle s&#8217;ajoute un autre chef-d&#8217;\u0153uvre qui peut \u00eatre admir\u00e9 au Casino Dell&#8217;aurora &#8211; qui composent l&#8217;exposition Caravaggio 2025, cr\u00e9\u00e9e dans le palais de Barberini \u00e0 Rome du 7 mars au 6 juillet, et qui a d\u00e9j\u00e0 vendu 60 milliers de titres.<\/p>\n<p><h2 id=\"U65873235757rOJ\">Les \u00e9l\u00e9ments innovants<\/h2>\n<\/p>\n<p class=\"atext\">Les chefs-d&#8217;\u0153uvre red\u00e9couverts et expos\u00e9s pour la premi\u00e8re fois en Italie qui sont rejoints par des \u0153uvres de collections priv\u00e9es seulement rarement visibles. Des peintures fondamentales telles que le <i>Portrait de Maffeo Barberini<\/i>r\u00e9cemment r\u00e9v\u00e9l\u00e9 au public, et le<i>Sauf homo<\/i>red\u00e9couvert \u00e0 Madrid en 2021, qui revient en Italie apr\u00e8s quatre si\u00e8cles. <span style=\"font-family: inherit; font-size: 1.125rem;\">L&#8217;exposition, organis\u00e9e par Francesca Cappelletti, Maria Cristina Terzaghi et Thomas Clement Salomon, propose une nouvelle r\u00e9flexion sur la r\u00e9volution artistique et culturelle faite par Caravaggio explorant les \u00e9l\u00e9ments innovants qui ont \u00e9t\u00e9 introduits dans le panorama artistique, religieux et social de son \u00e9poque.<\/span><\/p>\n<p><h2 id=\"U80335770651fzn\">Quatre chambres<\/h2>\n<\/p>\n<p class=\"atext\">Avec les grands chefs-d&#8217;\u0153uvre qui peuvent \u00eatre utilis\u00e9s, ils incluent des \u0153uvres tr\u00e8s difficiles \u00e0 voir ou renommer gr\u00e2ce \u00e0 de nouvelles interventions, qui sont compar\u00e9es dans les quatre pi\u00e8ces de mani\u00e8re chronologique. D&#8217;une importance absolue <i>Le martyre de Sant&#8217;orsola<\/i>un chef-d&#8217;\u0153uvre des collections d&#8217;Intesa Sanpaolo, qui a fait l&#8217;objet d&#8217;un travail de nettoyage important qui a mis en lumi\u00e8re trois nouvelles figures qui ont disparu au fil du temps. L&#8217;image est g\u00e9n\u00e9ralement expos\u00e9e \u00e0 Naples dans les galeries d&#8217;Italie de la banque, qui auront pour l&#8217;occasion en pr\u00eat de la Borghese Gallery LA <i>Dama avec Liocorno di Raffaello<\/i>comme l&#8217;a expliqu\u00e9 l&#8217;a expliqu\u00e9 a expliqu\u00e9 l&#8217;a expliqu\u00e9 l&#8217;a expliqu\u00e9 a expliqu\u00e9 l&#8217;a expliqu\u00e9 l&#8217;a expliqu\u00e9 \u00e0 l&#8217;Intesa Sanpaolo et au directeur g\u00e9n\u00e9ral de la Gallerie d&#8217;Italia.<\/p>\n<p><h2 id=\"U11130777862cqP\">Pr\u00eats exceptionnels<\/h2>\n<\/p>\n<p class=\"atext\">Comme l&#8217;a expliqu\u00e9 le directeur de Palazzo Barberini, Thomas Clement Salomon, &#8220;chaque photo du Caravaggio est une star et chaque pr\u00eat est une extradition&#8221;, et cette exposition pour lui &#8220;est de faire un r\u00eave sur le terrain, r\u00e9alis\u00e9 dans le temps record d&#8217;un an&#8221;. Une \u0153uvre chorale en surmontant de grandes difficult\u00e9s, gr\u00e2ce \u00e0 la collaboration \u00e9galement avec la Borghese Gallery et le r\u00e9alisateur Francesca Cappelletti. \u00abEn parlant de r\u00eaves &#8211; explique Cappelletti &#8211; je ne voudrais pas me r\u00e9veiller et l&#8217;important est de le voir. Il y a des pr\u00eats exceptionnels, et trois peintures proviennent des bourgeois qui soutiennent l&#8217;histoire de l&#8217;exposition avec le <i>Bacchino malade<\/i>qui raconte le Caravage d\u00e8s son arriv\u00e9e \u00e0 Rome dans l&#8217;environnement des magasins et du march\u00e9. Alors l&#8217;un des moments fondamentaux est marqu\u00e9 par <i>Davide avec la t\u00eate de Goliath<\/i>. Il y aura sur ce d\u00e9bat, car c&#8217;est aussi une exposition scientifique et nous les avons sorties, mais tout le monde n&#8217;est peut-\u00eatre pas d&#8217;accord. Puis dans la derni\u00e8re pi\u00e8ce la derni\u00e8re p\u00e9riode, avec <i>Le San Giovanni Battista<\/i>compagnon in\u00e9vitable de Sant&#8217;orsola \u00bb.<\/p>\n<aside class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/consigli24.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/11\/Intelligence-artificielle-la-rentree-pour-les-start-up-les-professionnels.png\" alt=\"En savoir plus\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/aside>\n<p><h2 id=\"U50003535600OVn\">Le catalogue et les \u00e9rudits<\/h2>\n<\/p>\n<p class=\"atext\">Il s&#8217;agit donc \u00e9galement d&#8217;une exposition de recherche (et le catalogue publi\u00e9 par Marsilio est une somme d&#8217;\u00e9tudes r\u00e9centes sur Merisi) et ce n&#8217;est pas un hasard si Terzaghi a remerci\u00e9 &#8220;tous les chercheurs qui ont contribu\u00e9 \u00e0 arriver au point o\u00f9 nous sommes aujourd&#8217;hui. L&#8217;exposition voulait illustrer l&#8217;\u00e9tat des affaires des \u00e9tudes sur le Caravage, qui sera \u00e9galement int\u00e9gr\u00e9e par une s\u00e9rie de r\u00e9unions et de d\u00e9bats. Le chemin est traditionnel et chronologique mais des lectures transversales sont possibles \u00bb.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/caravaggio-2025-palazzo-barberini-capolavori-primo-moderni-tutto-mondo-AGQuGtND\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9coutez la version audio de l&#8217;article &#8220;Il a risqu\u00e9 de devenir une sorte de gardien de but nocturne de la Renaissance.&#8221; Mais non, aux yeux du plus grand \u00e9rudit artistique italien du XXe si\u00e8cle, Roberto Longhi, Caravaggio prendra la place qu&#8217;il m\u00e9rite. Le premier de moderne, un peintre visionnaire et audacieux d&#8217;une force expressive in\u00e9gal\u00e9e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1569444,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[507,215302,121077,58206,9682,10887,1056,56536,2497],"class_list":["post-1569443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-aux","tag-barberini","tag-caravaggio","tag-chefsdoeuvre","tag-entier","tag-moderne","tag-monde","tag-palazzo","tag-premier"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1569443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1569443"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1569443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1569444"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1569443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1569443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1569443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}