{"id":1494721,"date":"2025-01-16T03:03:30","date_gmt":"2025-01-16T05:03:30","guid":{"rendered":"https:\/\/teknomers.com\/fr\/zweeloo-veut-faire-bien-plus-avec-leglise-van-gogh\/"},"modified":"2025-01-16T03:03:35","modified_gmt":"2025-01-16T05:03:35","slug":"zweeloo-veut-faire-bien-plus-avec-leglise-van-gogh","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/zweeloo-veut-faire-bien-plus-avec-leglise-van-gogh\/","title":{"rendered":"Zweeloo veut faire bien plus avec \u00ab l&#8217;\u00e9glise Van Gogh \u00bb"},"content":{"rendered":"\n<div __component=\"api.api-text\" type=\"text\" id=\"e5cbdc01-466c-4014-b787-52255b06bd1c\" data-v-156d9736=\"\" data-v-26349d05=\"\">\n<p>Jan de Jong, le voisin d&#8217;en face, en a un peu marre, dit en riant le tr\u00e9sorier de l&#8217;\u00e9glise, Gilbert Mulder. Il montre l&#8217;autre c\u00f4t\u00e9 de la rue, pr\u00e8s de l&#8217;\u00e9glise du XIIIe si\u00e8cle \u00e0 Zweeloo. &#8220;L&#8217;ann\u00e9e derni\u00e8re, cet endroit \u00e9tait central pendant l&#8217;ann\u00e9e Van Gogh. Eh bien, nous le savions.&#8221;<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"90a6b336-dd54-4c0e-b976-2b67f4c64ca8\" data-v-156d9736=\"\" data-v-26349d05=\"\">\n<p>Mulder a soudainement constat\u00e9 un vif int\u00e9r\u00eat pour le petit b\u00e2timent m\u00e9di\u00e9val. &#8220;Pas seulement \u00e0 cause de l&#8217;arriv\u00e9e d&#8217;une piste cyclable Van Gogh devant l&#8217;\u00e9glise. Nous avons vu que de plus en plus de gens du pays et de l&#8217;\u00e9tranger venaient \u00e0 Zweeloo sur mesure pour admirer l&#8217;\u00e9glise Van Gogh. Et puis ils se sont heurt\u00e9s \u00e0 une porte ferm\u00e9e.&#8221;<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"d73d78cf-8f5b-4992-a848-aefc1658beb6\" data-v-156d9736=\"\" data-v-26349d05=\"\">\n<p>Maintenant, De Jong a une cl\u00e9 et il \u00e9tait r\u00e9guli\u00e8rement heureux de laisser entrer les parties int\u00e9ress\u00e9es, Mulder le sait. &#8220;Je lui ai parl\u00e9 r\u00e9cemment, il devient un peu fou maintenant.&#8221; Mulder lui-m\u00eame trouve cela fou, tout comme Jan Seubring de l&#8217;agence touristique ToReCo. &#8220;Zweeloo est connu comme un village d&#8217;artistes&#8221;, explique Seubring. &#8220;Et puis voici un \u00e9difice immortalis\u00e9 par un peintre de renomm\u00e9e mondiale, qui n&#8217;est m\u00eame pas ouvert aux visiteurs. Ce n&#8217;est pas possible, n&#8217;est-ce pas ? Des invit\u00e9s viennent nous demander o\u00f9 est l&#8217;\u00e9glise et reviennent un peu plus tard pour nous dire que la porte est verrouill\u00e9e, asseyez-vous.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"2a7d30a6-0cd1-41b1-b632-b11613ffbcfa\" data-v-156d9736=\"\" data-v-26349d05=\"\">\n<p>Les deux hommes pensent qu\u2019il est grand temps que cela change. Il existe donc un plan ambitieux pour lequel des fonds sont d\u00e9sormais disponibles aupr\u00e8s de la province, des communes et de Marketing Drenthe dans le cadre du projet \u00ab Germes dans le sol de Drentse \u00bb. Il y a un demi-million d\u2019euros en rayon, pour \u00eatre pr\u00e9cis. Mulder : &#8220;C&#8217;est une somme importante, nous pouvons commencer maintenant.&#8221;<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"0982d4b8-d4fa-4d38-8a0c-c5a3fa24b77e\" data-v-156d9736=\"\" data-v-26349d05=\"\">\n<p>Le projet est d\u00e9sormais de revivre la visite de Vincent van Gogh ce jour de novembre 1883 \u00e0 l&#8217;int\u00e9rieur de l&#8217;\u00e9glise en utilisant des effets lumineux et sonores. &#8220;Pensez aux projections d&#8217;images sur les murs de l&#8217;\u00e9glise et \u00e0 toutes sortes d&#8217;effets lumineux et sonores qui fonctionnent sur des capteurs&#8221;, explique Mulder, en d\u00e9signant les espaces blanchis \u00e0 la chaux entre les fen\u00eatres. &#8220;Nous pouvons ensuite assombrir un peu les vitraux de ces \u00e9glises, pour un meilleur effet. Cela devrait vraiment \u00eatre un spectacle.&#8221; Seubring : &#8220;On peut bien s\u00fbr travailler avec des images de l&#8217;artiste, mais aussi avec des passages lus de la lettre que Vincent a \u00e9crite \u00e0 son fr\u00e8re Th\u00e9o, dans laquelle il lui parlait de Zweeloo.&#8221;<\/p>\n<p> <!----><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rtvdrenthe.nl\/nieuws\/17126660\/zweeloo-wil-veel-meer-de-boer-op-met-van-gogh-kerkje\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-41<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jan de Jong, le voisin d&#8217;en face, en a un peu marre, dit en riant le tr\u00e9sorier de l&#8217;\u00e9glise, Gilbert Mulder. Il montre l&#8217;autre c\u00f4t\u00e9 de la rue, pr\u00e8s de l&#8217;\u00e9glise du XIIIe si\u00e8cle \u00e0 Zweeloo. &#8220;L&#8217;ann\u00e9e derni\u00e8re, cet endroit \u00e9tait central pendant l&#8217;ann\u00e9e Van Gogh. Eh bien, nous le savions.&#8221; Mulder a soudainement constat\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1494722,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[84,285,23115,9542,365,20690,7420,2536,1148,53257,53261],"class_list":["post-1494721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-avec","tag-bien","tag-commune-de-coevorden","tag-eglise","tag-faire","tag-gogh","tag-leglise","tag-van","tag-veut","tag-vincent-van-gogh","tag-zweeloo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1494721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1494721"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1494721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1494722"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1494721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1494721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1494721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}