{"id":1319760,"date":"2024-09-11T22:09:28","date_gmt":"2024-09-12T00:09:28","guid":{"rendered":"https:\/\/teknomers.com\/fr\/dave-grohl-cest-la-famille-du-musicien-des-foo-fighters\/"},"modified":"2024-09-11T22:09:32","modified_gmt":"2024-09-12T00:09:32","slug":"dave-grohl-cest-la-famille-du-musicien-des-foo-fighters","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/dave-grohl-cest-la-famille-du-musicien-des-foo-fighters\/","title":{"rendered":"Dave Grohl : C&#8217;est la famille du musicien des \u00ab Foo Fighters \u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Lorsque Dave Grohl lui-m\u00eame a annonc\u00e9 qu&#8217;il avait tromp\u00e9 sa femme et qu&#8217;il avait m\u00eame eu un enfant hors mariage, l&#8217;image du \u00ab gars le plus sympa du rock \u00bb en a pris un coup. Bien qu&#8217;il reconnaisse publiquement son faux pas, cela semble avoir \u00e9t\u00e9 un coup d\u00e9vastateur pour sa femme, Jordyn Blum, et sa famille, d&#8217;apr\u00e8s le libell\u00e9 du message. Grohl veut d\u00e9sormais tout faire pour regagner la confiance de sa famille.<\/p>\n<div class=\"asmb-article-instagram-embed\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e717c8e69966540e4554f05\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu d&#8217;Instagram<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<h2>La femme de Dave Grohl : qui est Jordyn Blum ?<\/h2>\n<p>Jordyn Blum a toujours fait profil bas aux c\u00f4t\u00e9s de Dave Grohl, on sait donc peu de choses sur la femme du musicien des Foo Fighters. Ce qui est s\u00fbr, cependant, c&#8217;est que les deux se sont rencontr\u00e9s en 2001 &#8211; \u00e0 cette \u00e9poque, elle travaillait comme productrice chez MTV et ils se sont parl\u00e9 pour la premi\u00e8re fois au Sunset Marquis Whiskey Bar \u00e0 West Hollywood lorsque Taylor Hawkins et lui y faisaient la f\u00eate.<\/p>\n<p>Il a d\u00e9clar\u00e9 \u00e0 \u00ab Q Magazine \u00bb qu\u2019il la trouvait si int\u00e9ressante qu\u2019il l\u2019a appel\u00e9e \u00ab ma future ex-femme \u00bb. Mais l\u2019int\u00e9r\u00eat n\u2019a apparemment pas dur\u00e9 longtemps. &#8220;Quand j&#8217;ai rencontr\u00e9 ma femme, nous avons eu quelques rendez-vous et j&#8217;ai d\u00e9cid\u00e9 que je n&#8217;\u00e9tais pas pr\u00eat pour une relation s\u00e9rieuse, alors j&#8217;ai arr\u00eat\u00e9 d&#8217;appeler&#8221;, a d\u00e9clar\u00e9 Grohl dans une interview avec Elle en 2007.<\/p>\n<p>Cependant, Grohl a chang\u00e9 d\u2019avis et a r\u00e9v\u00e9l\u00e9 : \u00ab Apr\u00e8s trois mois, j\u2019ai eu une r\u00e9v\u00e9lation et je l\u2019ai rappel\u00e9e. Elle a d\u00e9croch\u00e9 le t\u00e9l\u00e9phone et a dit : \u00ab Oh, je n&#8217;aurais plus jamais pens\u00e9 avoir de vos nouvelles. \u00bb \u00bb Le couple s&#8217;est mari\u00e9 \u00e0 Los Angeles le 2 ao\u00fbt 2003.<\/p>\n<figure id=\"attachment_2805731\" aria-describedby=\"caption-attachment-2805731\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2805731 size-large\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/09\/Dave-Grohl-Cest-la-famille-du-musicien-des.jpg\" alt=\"\" width=\"1024\" height=\"683\"  \/><figcaption id=\"caption-attachment-2805731\" class=\"wp-caption-text\">En juillet 2024, Jordyn Blum et Dave Grohl ont \u00e9t\u00e9 aper\u00e7us ensemble \u00e0 Wimbledon. Ici, elle portait \u00e9galement son alliance, qui manquait sur une photo ult\u00e9rieure des paparazzis de d\u00e9but ao\u00fbt.<\/figcaption><\/figure>\n<p>Avant de rencontrer Dave Grohl, Jordyn Blum aurait travaill\u00e9 comme mannequin : elle aurait \u00e9t\u00e9 d\u00e9couverte dans un supermarch\u00e9 \u00e0 l&#8217;\u00e2ge de douze ans. Elle serait juive, ce qui est \u00e9galement confirm\u00e9 par le fait que sa fille Violet a soulign\u00e9 \u00e0 plusieurs reprises sur Instagram qu&#8217;elle \u00e9tait juive. De plus, Dave Grohl et le producteur Greg Kurstin ont enregistr\u00e9 les sessions de Hanoukka pendant plusieurs ann\u00e9es.<\/p>\n<h2>Les enfants de Dave Grohl avec Jordyn Blum<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2805729\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/09\/1726099768_451_Dave-Grohl-Cest-la-famille-du-musicien-des.jpg\" alt=\"\" width=\"1024\" height=\"813\"  \/><\/p>\n<p>Le couple a trois filles : Violet Maye Grohl est n\u00e9e en 2006 et a aujourd&#8217;hui 18 ans. Elle monte sur sc\u00e8ne avec son p\u00e8re depuis plusieurs ann\u00e9es car elle a apparemment \u00e9galement d\u00e9cid\u00e9 de se lancer dans une carri\u00e8re de chanteuse. Violet Grohl a r\u00e9cemment annonc\u00e9 sur Instagram qu&#8217;elle avait termin\u00e9 ses \u00e9tudes et entamait maintenant une nouvelle phase de sa vie &#8211; qui, selon ses propres d\u00e9clarations, incluait \u00e9galement d&#8217;\u00eatre repr\u00e9sent\u00e9e par une agence artistique.<\/p>\n<div class=\"youtube asmb-responsive-video\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e7ac3fae30e7d1bc1ebf5e8\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu de YouTube<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<p>Harper Willow Grohl est n\u00e9e en 2009. La jeune fille de 15 ans, qui, comme sa grande s\u0153ur, a souvent tourn\u00e9 avec les Foo Fighters, a m\u00eame jou\u00e9 de la batterie devant leur public lors d&#8217;un festival en Islande &#8211; mais elle a d\u00e9j\u00e0 d\u00e9clar\u00e9 \u00e0 plusieurs reprises sur sa cha\u00eene Instagram qu&#8217;elle \u00e9tait ne vise pas une carri\u00e8re musicale. Au lieu de cela, elle pr\u00e9f\u00e8re peindre, dont elle montre des photos sur un compte Instagram priv\u00e9.<\/p>\n<p>Ophelia Saint est le troisi\u00e8me enfant de Dave Grohl et Jordyn Blum. Elle est n\u00e9e en 2014. On ne sait rien de la jeune fille de dix ans car la famille prot\u00e8ge au mieux sa vie priv\u00e9e. La plus jeune fille du couple n&#8217;est vue qu&#8217;occasionnellement en train de sauter au bord de la sc\u00e8ne lors de concerts et elle est \u00e9galement venue \u00e0 certains \u00e9v\u00e9nements.<\/p>\n<h2>Dave Grohl : Apparemment, ce n&#8217;est pas la premi\u00e8re fois qu&#8217;il triche<\/h2>\n<p>M\u00eame si les relations avec qui il couche font partie de la vie priv\u00e9e du musicien, ses ex-partenaires ont fait savoir par le pass\u00e9 qu&#8217;il ne semblait pas prendre la loyaut\u00e9 au s\u00e9rieux. Son premier mariage avec Jennifer Youngblood aurait \u00e9t\u00e9 rompu pour cette raison.<\/p>\n<p>De plus, la snowboardeuse am\u00e9ricaine Tina Basich a d\u00e9clar\u00e9 dans ses m\u00e9moires de 2003 que Grohl sortait secr\u00e8tement avec une autre femme alors qu&#8217;ils \u00e9taient ensemble. \u00ab Je ne sais pas comment quelqu&#8217;un dans sa profession peut avoir une relation normale avec une petite amie\u2026 ou deux, en fin de compte. Je l\u2019ai d\u00e9couvert par moi-m\u00eame, gr\u00e2ce \u00e0 la vigne, alors qu\u2019il semblait que tout le monde dans le monde le savait, sauf moi.<\/p>\n<div class=\"ph-wp-image-credit-list ph-hide--\">\n<p>Karwai Tang WireImage<\/p>\n<p>Archives de photos CBS CBS via Getty Images<\/p>\n<\/div><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/dave-grohl-ehefrau-kinder-die-familie-des-foo-fighters-musikers-2805727\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque Dave Grohl lui-m\u00eame a annonc\u00e9 qu&#8217;il avait tromp\u00e9 sa femme et qu&#8217;il avait m\u00eame eu un enfant hors mariage, l&#8217;image du \u00ab gars le plus sympa du rock \u00bb en a pris un coup. Bien qu&#8217;il reconnaisse publiquement son faux pas, cela semble avoir \u00e9t\u00e9 un coup d\u00e9vastateur pour sa femme, Jordyn Blum, et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1319761,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[1820,974,232667,133,563,8045,33439,163757,975,252689,252692,1564,252690,252691],"class_list":["post-1319760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement","tag-cest","tag-dave","tag-dave-grohl","tag-des","tag-famille","tag-fighters","tag-foo","tag-foo-fighters","tag-grohl","tag-harper-grohl","tag-jordyn-blum","tag-musicien","tag-ophelie-grohl","tag-violette-grohl"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1319760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1319760"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1319760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1319761"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1319760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1319760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1319760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}