{"id":1318673,"date":"2024-09-11T05:44:19","date_gmt":"2024-09-11T07:44:19","guid":{"rendered":"https:\/\/teknomers.com\/fr\/childless-cat-lady-taylor-swift-soutient-kamala-harris\/"},"modified":"2024-09-11T05:44:23","modified_gmt":"2024-09-11T07:44:23","slug":"childless-cat-lady-taylor-swift-soutient-kamala-harris","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/childless-cat-lady-taylor-swift-soutient-kamala-harris\/","title":{"rendered":"&#8220;Childless Cat Lady&#8221; Taylor Swift soutient Kamala Harris"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>\u00c0 peine une heure apr\u00e8s la fin du d\u00e9bat historique entre la vice-pr\u00e9sidente Kamala Harris et l&#8217;ancien pr\u00e9sident Donald Trump, Taylor Swift a annonc\u00e9 qu&#8217;elle voterait pour le candidat d\u00e9mocrate.<\/p>\n<p>Mardi, Swift s&#8217;est prononc\u00e9 contre les faux messages d&#8217;IA dans lesquels la star soutenait Trump. \u00abJ&#8217;ai r\u00e9cemment \u00e9t\u00e9 inform\u00e9 du fait que l&#8217;IA de &#8220;moi&#8221; soutenait \u00e0 tort la candidature de Donald Trump \u00e0 la pr\u00e9sidentielle. &#8220;Cela a fait na\u00eetre mes craintes concernant l&#8217;intelligence artificielle et les dangers de la propagation de la d\u00e9sinformation&#8221;, a expliqu\u00e9 l&#8217;artiste.<\/p>\n<p>\u00ab Cela m\u2019a fait r\u00e9aliser qu\u2019en tant qu\u2019\u00e9lecteur, je dois \u00eatre tr\u00e8s transparent sur mes projets r\u00e9els pour cette \u00e9lection. Le moyen le plus simple de lutter contre la d\u00e9sinformation est de r\u00e9v\u00e9ler la v\u00e9rit\u00e9.<\/p>\n<div class=\"asmb-article-instagram-embed\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e717c8e69966540e4554f05\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu d&#8217;Instagram<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<p>\u00ab Je voterai pour Kamala Harris et Tim Walz \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle de 2024. &#8220;Je vote pour @kamalaharris parce qu&#8217;elle se bat pour les droits et les causes qui, \u00e0 mon avis, ont besoin d&#8217;un combattant pour les repr\u00e9senter&#8221;, a poursuivi Swift.<\/p>\n<h2>\u00ab\u00a0Imprim\u00e9 par Tim Walz\u00a0\u00bb<\/h2>\n<p>\u00ab Je la consid\u00e8re comme une dirigeante r\u00e9fl\u00e9chie et dou\u00e9e et je crois que nous pouvons accomplir bien plus dans ce pays si nous sommes guid\u00e9s par le calme et non par le chaos. J&#8217;ai \u00e9t\u00e9 tellement encourag\u00e9e et impressionn\u00e9e par son choix de candidate @timwalz, qui d\u00e9fend les droits LGBTQ+, la FIV et le droit des femmes \u00e0 leur propre corps depuis des d\u00e9cennies.<\/p>\n<h2>\u00ab\u00a0N&#8217;oubliez pas que vous devez \u00eatre inscrit pour voter\u00a0!\u00a0\u00bb<\/h2>\n<p>Soulignant sa d\u00e9cision, la chanteuse a \u00e9crit : \u00ab J&#8217;ai fait mes recherches et j&#8217;ai pris ma d\u00e9cision. Vous devez faire vos propres recherches et la d\u00e9cision vous appartient. Je veux aussi dire, surtout aux nouveaux \u00e9lecteurs, n\u2019oubliez pas que vous devez \u00eatre inscrit pour voter ! Je trouve aussi qu&#8217;il est beaucoup plus facile de voter t\u00f4t.<\/p>\n<p>Dans mon histoire, je mets un lien o\u00f9 vous pouvez vous inscrire et o\u00f9 se trouvent les rendez-vous et les informations sur le vote anticip\u00e9. \u00bb La 14 fois laur\u00e9ate d&#8217;un Grammy a sign\u00e9 son message avec \u00ab Taylor Swift \u00bb et \u00ab Childless Cat Lady \u00bb.<\/p>\n<p>La signature faisait directement r\u00e9f\u00e9rence au colistier de Trump \u00e0 la vice-pr\u00e9sidence, JD Vance, qui a fait l&#8217;objet de vives critiques pour s&#8217;\u00eatre plaint du fait que l&#8217;Am\u00e9rique est &#8220;dirig\u00e9e par une bande de femmes chats sans enfants qui sont m\u00e9contentes de leur propre vie et des choix qu&#8217;elles ont faits&#8221;. sont \u00bb, faisant r\u00e9f\u00e9rence \u00e0 Harris, qui a deux beaux-enfants issus de son mariage avec le deuxi\u00e8me gentleman Doug Emhoff.<\/p>\n<p>En 2020, Swift a publiquement soutenu Biden et Harris. \u00ab Le changement dont nous avons le plus besoin est d&#8217;\u00e9lire un pr\u00e9sident qui reconna\u00eet que les personnes de couleur m\u00e9ritent de se sentir en s\u00e9curit\u00e9 et repr\u00e9sent\u00e9es, que les femmes m\u00e9ritent le droit de d\u00e9cider de ce qui arrive \u00e0 leur corps et que la communaut\u00e9 LGBTQIA+ m\u00e9rite d&#8217;\u00eatre reconnue et incluse. &#8221; Swift a d\u00e9clar\u00e9 \u00e0 V Magazine \u00e0 l&#8217;\u00e9poque.<\/p>\n<h2>Swifties pour Kamala<\/h2>\n<p>&#8220;Je crois que sous sa direction, l&#8217;Am\u00e9rique a une chance d&#8217;entamer le processus de gu\u00e9rison dont elle a d\u00e9sesp\u00e9r\u00e9ment besoin.&#8221;<\/p>\n<p>Alors que la question de savoir si Swift annoncerait publiquement son soutien a \u00e9t\u00e9 longuement d\u00e9battue dans les m\u00e9dias lors des \u00e9lections de cette ann\u00e9e, ses fans n&#8217;ont pas perdu de temps pour se rallier \u00e0 Harris.<\/p>\n<p>Le jour m\u00eame o\u00f9 le pr\u00e9sident Joe Biden s&#8217;est retir\u00e9 de la course \u00e0 2024 en ao\u00fbt et a apport\u00e9 son soutien au vice-pr\u00e9sident, Swifties for Kamala s&#8217;est mobilis\u00e9 &#8211; une coalition soutenant l&#8217;\u00e9lection de Harris comme 47e pr\u00e9sident des \u00c9tats-Unis.<\/p>\n<p>Le mouvement a depuis gagn\u00e9 des milliers d&#8217;adeptes sur diverses plateformes de m\u00e9dias sociaux et a collect\u00e9 plus de 138 000 $ pour le candidat d\u00e9mocrate lors d&#8217;un rassemblement virtuel mettant en vedette l&#8217;auteure-compositrice-interpr\u00e8te Carole King et les s\u00e9natrices Elizabeth Warren et Kirsten Gillibrand.<\/p>\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e71760b69966540e4554f01\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu de X Corp.<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<p>Le candidat de Harris \u00e0 la vice-pr\u00e9sidence, Tim Walz du Minnesota, a d\u00e9clar\u00e9 mardi \u00e0 MSNBC qu&#8217;il \u00e9tait \u00ab incroyablement reconnaissant \u00bb pour le soutien de Swift. &#8220;Je dis cela aussi en tant que propri\u00e9taire de chat, en tant que propri\u00e9taire de chat&#8221;, a-t-il ajout\u00e9. &#8220;C&#8217;\u00e9tait \u00e9loquent et clair, et c&#8217;est le genre de courage dont nous avons besoin en Am\u00e9rique pour nous lever.&#8221;<\/p>\n<p>&#8220;Nous l&#8217;avons vu avec les R\u00e9publicains qui \u00e9taient au DNC, nous l&#8217;avons vu avec des femmes qui voudraient garder leur vie personnelle pour elles mais sont oblig\u00e9es d&#8217;y aller parce qu&#8217;elles ont failli mourir parce qu&#8217;elles n&#8217;ont pas b\u00e9n\u00e9fici\u00e9 de services d&#8217;avortement pendant leur grossesse&#8221;, \u00bb continua Walz. &#8220;Et maintenant, nous avons quelqu&#8217;un comme Taylor Swift qui s&#8217;exprime et le dit tr\u00e8s clairement.&#8221;<\/p>\n<h2>&#8220;Je n&#8217;en ai aucune id\u00e9e&#8221;, a r\u00e9pondu Trump<\/h2>\n<p>Il a \u00e9galement cri\u00e9 aux fans de Swift : &#8220;Ce sera l&#8217;occasion, Swifties &#8211; KamalaHarris.com &#8211; venez nous aider, faites avancer les choses.&#8221;<\/p>\n<p>Apr\u00e8s la confrontation de mardi, au cours de laquelle Harris a domin\u00e9 Trump (et sa performance a m\u00eame \u00e9t\u00e9 critiqu\u00e9e par d&#8217;\u00e9minents r\u00e9publicains), on a demand\u00e9 \u00e0 l&#8217;ancien pr\u00e9sident dans le Spin Room ce qu&#8217;il pensait du soutien de Swift \u00e0 Harris. &#8220;Je n&#8217;en ai aucune id\u00e9e&#8221;, a r\u00e9pondu Trump.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/kinderlose-katzenlady-taylor-swift-supportet-kamala-harris-2805423\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 peine une heure apr\u00e8s la fin du d\u00e9bat historique entre la vice-pr\u00e9sidente Kamala Harris et l&#8217;ancien pr\u00e9sident Donald Trump, Taylor Swift a annonc\u00e9 qu&#8217;elle voterait pour le candidat d\u00e9mocrate. Mardi, Swift s&#8217;est prononc\u00e9 contre les faux messages d&#8217;IA dans lesquels la star soutenait Trump. \u00abJ&#8217;ai r\u00e9cemment \u00e9t\u00e9 inform\u00e9 du fait que l&#8217;IA de &#8220;moi&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1290180,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[23853,184370,18377,59443,4828,7597,4825,9087],"class_list":["post-1318673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement","tag-cat","tag-childless","tag-harris","tag-kamala","tag-lady","tag-soutient","tag-swift","tag-taylor"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1318673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1318673"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1318673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1290180"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1318673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1318673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1318673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}