{"id":1318378,"date":"2024-09-11T00:44:08","date_gmt":"2024-09-11T02:44:08","guid":{"rendered":"https:\/\/teknomers.com\/fr\/dave-grohl-demande-pardon-il-est-devenu-pere-dun-enfant-illegitime\/"},"modified":"2024-09-11T00:44:13","modified_gmt":"2024-09-11T02:44:13","slug":"dave-grohl-demande-pardon-il-est-devenu-pere-dun-enfant-illegitime","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/dave-grohl-demande-pardon-il-est-devenu-pere-dun-enfant-illegitime\/","title":{"rendered":"Dave Grohl demande pardon : il est devenu p\u00e8re d&#8217;un enfant ill\u00e9gitime"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Dave Grohl a post\u00e9 un message sur Instagram. Une confession et une demande de pardon. Ce qui serait normalement un pur motif de joie \u2013 la paternit\u00e9 \u2013 est d\u00e9sormais devenu une mission :<\/p>\n<p class=\"p1\">\u00abJe suis r\u00e9cemment devenu p\u00e8re d&#8217;une nouvelle petite fille. N\u00e9 hors de mon mariage. J&#8217;ai l&#8217;intention d&#8217;\u00eatre un parent aimant et solidaire pour elle. J&#8217;aime ma femme et mes enfants et je fais tout ce que je peux pour regagner leur confiance et m\u00e9riter leur pardon. Nous sommes reconnaissants de votre consid\u00e9ration envers tous les enfants impliqu\u00e9s, alors que nous avan\u00e7ons ensemble.<\/p>\n<p>En allemand :<\/p>\n<p>\u00abJe suis r\u00e9cemment devenu p\u00e8re d&#8217;une petite fille n\u00e9e hors de mon mariage\u00bb, avoue le patron des Foo Fighters. \u00abEt j&#8217;ai l&#8217;intention d&#8217;\u00eatre un parent aimant et solidaire pour elle. J&#8217;aime ma femme et mes enfants. Et je fais tout ce que je peux pour regagner sa confiance et m\u00e9riter son pardon. Nous sommes reconnaissants de votre consid\u00e9ration envers tous les enfants impliqu\u00e9s alors que nous avan\u00e7ons ensemble.<\/p>\n<h2>Grohl a d\u00e9sactiv\u00e9 les commentaires Instagram<\/h2>\n<p>Il n\u2019y a pas (encore) de d\u00e9claration de son \u00e9pouse Jordan Blum. L&#8217;homme de 55 ans et Blum ont trois filles ensemble : Violet, Harper et Ophelia.<\/p>\n<div class=\"asmb-article-instagram-embed\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e717c8e69966540e4554f05\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu d&#8217;Instagram<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<p>La difficult\u00e9 pour le couple Grohl &#8211; en particulier, bien s\u00fbr, pour Jordan Blum et les enfants &#8211; est d\u00e9montr\u00e9e par le fait que Violet et Harper ont d\u00e9sormais d\u00e9sactiv\u00e9 leurs comptes Instagram.<\/p>\n<p>Violet est la prog\u00e9niture la plus c\u00e9l\u00e8bre des Grohl. Elle part en tourn\u00e9e avec les Foo Fighters aux c\u00f4t\u00e9s de Dave. On peut \u00e9galement l&#8217;entendre sur la chanson 2023 &#8220;Show Me How&#8221; de l&#8217;album &#8220;But Here We Are&#8221;, un hommage au regrett\u00e9 batteur de FF Justin Hawkins.<\/p>\n<p>Alors que Dave Grohl a d\u00e9sactiv\u00e9 la fonction commentaire sur Instagram, les commentaires sont nombreux sur X. Le message de Grohl ne passe pas bien. \u00c0 la fois \u00e0 cause des mots qu\u2019il a choisis et du fait m\u00eame qu\u2019il a eu un enfant avec une autre femme.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/dave-grohl-bittet-um-vergebung-er-ist-vater-eines-unehelichen-kindes-geworden-2805347\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dave Grohl a post\u00e9 un message sur Instagram. Une confession et une demande de pardon. Ce qui serait normalement un pur motif de joie \u2013 la paternit\u00e9 \u2013 est d\u00e9sormais devenu une mission : \u00abJe suis r\u00e9cemment devenu p\u00e8re d&#8217;une nouvelle petite fille. N\u00e9 hors de mon mariage. J&#8217;ai l&#8217;intention d&#8217;\u00eatre un parent aimant et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1318379,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[974,232667,442,1863,74,1758,40,163757,975,53922,49660,760],"class_list":["post-1318378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement","tag-dave","tag-dave-grohl","tag-demande","tag-devenu","tag-dun","tag-enfant","tag-est","tag-foo-fighters","tag-grohl","tag-illegitime","tag-pardon","tag-pere"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1318378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1318378"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1318378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1318379"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1318378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1318378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1318378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}