{"id":1317316,"date":"2024-09-10T08:09:07","date_gmt":"2024-09-10T10:09:07","guid":{"rendered":"https:\/\/teknomers.com\/fr\/linkin-park-cest-ainsi-que-mike-shinoda-soutient-emily-armstrong-pendant-la-crise-2\/"},"modified":"2024-09-10T08:09:12","modified_gmt":"2024-09-10T10:09:12","slug":"linkin-park-cest-ainsi-que-mike-shinoda-soutient-emily-armstrong-pendant-la-crise-2","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/linkin-park-cest-ainsi-que-mike-shinoda-soutient-emily-armstrong-pendant-la-crise-2\/","title":{"rendered":"Linkin Park : C&#8217;est ainsi que Mike Shinoda soutient Emily Armstrong pendant la crise"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Linkin Park aurait certainement aim\u00e9 \u00e9viter ce tapage. Le groupe avait \u00e0 peine annonc\u00e9 ses retrouvailles vendredi (6 septembre 2024) que les premi\u00e8res voix critiques se faisaient d\u00e9j\u00e0 entendre. Mike Shinoda a non seulement annonc\u00e9 un nouvel album (\u00ab From Zero \u00bb), mais a \u00e9galement imm\u00e9diatement pr\u00e9sent\u00e9 le rempla\u00e7ant de feu Chester Bennington lors du concert du groupe \u00e0 Los Angeles. Emily Armstrong reprendra son r\u00f4le \u00e0 l&#8217;avenir.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/09\/Vous-pouvez-me-dire-que-vous-etes-toujours-en-Scientologie.gif\" alt=\"\" width=\"1\" height=\"1\"\/><\/p>\n<p>Alors que la veuve de Chester, Talinda Bennington, est enthousiasm\u00e9e par son successeur, Armstrong lui-m\u00eame est pris entre deux feux.<\/p>\n<h2>Emily Armstrong est-elle (encore) scientologue ?<\/h2>\n<p>Les fans et les critiques ont remarqu\u00e9 qu&#8217;Armstrong avait soutenu le d\u00e9linquant sexuel condamn\u00e9 Danny Masterson dans le pass\u00e9. On dit \u00e9galement qu\u2019elle est \u2013 ou a \u00e9t\u00e9 \u2013 membre de la Scientologie.<\/p>\n<p>Armstrong a pris ses distances avec Masterson dans une d\u00e9claration samedi (sans mentionner son nom), mais n&#8217;a pas dit un mot sur son appartenance pr\u00e9sum\u00e9e \u00e0 la Scientologie. La religion ou \u00ab religion \u00bb est une affaire priv\u00e9e, mais il semble impossible que leur silence sur le sujet puisse assurer le calme n\u00e9cessaire dans le camp de Linkin Park. On ne peut pas exclure que des gens manifestent contre la Scientologie, au moins devant les salles des concerts.<\/p>\n<p>Linkin Park lui-m\u00eame est jusqu\u2019\u00e0 pr\u00e9sent rest\u00e9 silencieux. Mais il y a eu une br\u00e8ve r\u00e9action de Mike Shinoda \u00e0 la temp\u00eate de merde qu&#8217;Armstrong doit endurer.<\/p>\n<div class=\"asmb-article-instagram-embed\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e717c8e69966540e4554f05\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu d&#8217;Instagram<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<p>Sous une publication Instagram de Linkin Park du groupe interpr\u00e9tant &#8220;Numb&#8221;, Shinoda a post\u00e9 trois petits mots avec un grand impact dimanche, apr\u00e8s que les liens d&#8217;Armstrong avec Danny Masterson aient \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9s : &#8220;Emily Appreciation Button&#8221;, avec une fl\u00e8che pointant vers une \u00e9motic\u00f4ne \u00e0 c\u00f4t\u00e9 de il. Cela signifie : si vous voulez les soutenir, appuyez simplement sur votre c\u0153ur.<\/p>\n<p>Lundi apr\u00e8s-midi (9 septembre), Linkin Park avait recueilli environ 38 000 approbations. La page Instagram de LP semble \u00e9galement \u00eatre soigneusement mod\u00e9r\u00e9e. Parmi les quelque 600 commentaires sur le soutien de Shinoda, il n&#8217;y a pas une seule contribution critique \u00e0 l&#8217;\u00e9gard du nouveau chanteur.<\/p>\n<p>Bien s\u00fbr, il se pourrait aussi que les fans de Linkin Park soient inconditionnellement fid\u00e8les \u00e0 leur groupe. Tout le monde attend probablement encore un v\u00e9ritable commentaire du chef du groupe Shinoda sur le cas scientologue du successeur de Bennington.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/linkin-park-so-supportet-mike-shinoda-emily-armstrong-in-der-krise-2804831\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Linkin Park aurait certainement aim\u00e9 \u00e9viter ce tapage. Le groupe avait \u00e0 peine annonc\u00e9 ses retrouvailles vendredi (6 septembre 2024) que les premi\u00e8res voix critiques se faisaient d\u00e9j\u00e0 entendre. Mike Shinoda a non seulement annonc\u00e9 un nouvel album (\u00ab From Zero \u00bb), mais a \u00e9galement imm\u00e9diatement pr\u00e9sent\u00e9 le rempla\u00e7ant de feu Chester Bennington lors du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1317317,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[1821,46676,1820,380,251686,8535,55594,8760,249735,249733,13501,275,55595,7597],"class_list":["post-1317316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement","tag-ainsi","tag-armstrong","tag-cest","tag-crise","tag-emilie-armstrong","tag-emily","tag-linkin","tag-mike","tag-mike-shinoda","tag-parc-linkin","tag-park","tag-pendant","tag-shinoda","tag-soutient"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1317316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1317316"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1317316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1317317"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1317316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1317316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1317316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}