{"id":1315398,"date":"2024-09-08T23:17:06","date_gmt":"2024-09-09T01:17:06","guid":{"rendered":"https:\/\/teknomers.com\/fr\/guildo-horn-critique-luke-mockridge-tu-es-un-pauvre-saucisson\/"},"modified":"2024-09-08T23:17:11","modified_gmt":"2024-09-09T01:17:11","slug":"guildo-horn-critique-luke-mockridge-tu-es-un-pauvre-saucisson","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/guildo-horn-critique-luke-mockridge-tu-es-un-pauvre-saucisson\/","title":{"rendered":"Guildo Horn critique Luke Mockridge : \u00ab Tu es un pauvre saucisson \u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Bien que Luke Mockridge ait maintenant pr\u00e9sent\u00e9 ses excuses pour ses commentaires insipides et blessants sur les Jeux Paralympiques, il doit encore accepter les critiques. Guildo Horn s&#8217;est \u00e9galement senti appel\u00e9 \u00e0 exprimer son opinion sur le sujet sur Instagram.<\/p>\n<p>\u00ab Presque aucun \u00e9v\u00e9nement sportif majeur de ces derni\u00e8res ann\u00e9es ne m\u2019a autant captiv\u00e9 que les Jeux Paralympiques qui se d\u00e9roulent actuellement \u00e0 Paris. Des comp\u00e9titions tr\u00e8s dramatiques, organis\u00e9es par des athl\u00e8tes avec un parcours de vie particulier, une volont\u00e9 indomptable et de grandes capacit\u00e9s ! Cela se voit : je suis compl\u00e8tement ravie&#8221;, a d\u00e9clar\u00e9 la chanteuse, qui a beaucoup d&#8217;exp\u00e9rience dans le travail avec des personnes handicap\u00e9es en tant qu&#8217;\u00e9ducatrice qualifi\u00e9e et musicoth\u00e9rapeute.<\/p>\n<div class=\"asmb-article-instagram-embed\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e717c8e69966540e4554f05\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu d&#8217;Instagram<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<p>\u00ab Ce que j\u2019ai vu et entendu aujourd\u2019hui sur les r\u00e9seaux sociaux de la part de Luke Mockridge et de deux autres Kaspar dans le podcast me fait d\u2019autant plus secouer la t\u00eate. Normalement, je ne r\u00e9agis pas publiquement \u00e0 quelque chose comme \u00e7a. Mais je suis tellement abasourdie qu&#8217;il faut simplement que cela ressorte : Ma question : Est-ce le r\u00e9sultat du fait de dire trop souvent \u00e0 votre enfant qu&#8217;il est quelque chose de tr\u00e8s sp\u00e9cial : particuli\u00e8rement divertissant, particuli\u00e8rement dr\u00f4le, particuli\u00e8rement espi\u00e8glement charmant&#8230; qu&#8217;est-ce que j&#8217;en sais ?! Luke, ce n&#8217;est pas toi ! Tu n&#8217;es qu&#8217;un pauvre saucisson !<\/p>\n<p>Guildo Horn adresse \u00e9galement quelques mots aux athl\u00e8tes qui font de leur mieux aux Jeux Paralympiques : \u00ab Meilleures salutations \u00e0 tous les athl\u00e8tes de Paris !!!! Prenez-le pour ce que c\u2019est : des paroles stupides !<\/p>\n<h2>Luke Mockridge : Sat 1 ne diffuse pas sa nouvelle \u00e9mission<\/h2>\n<p>Compte tenu des critiques justifi\u00e9es, les responsables de Sat 1 ont d\u00e9cid\u00e9 de ne pas diffuser le nouveau format de l&#8217;\u00e9mission \u00ab What&#8217;s in the Box avec Luke Mockridge ? La cha\u00eene n&#8217;avait gu\u00e8re d&#8217;autre choix, car les d\u00e9clarations inhumaines sur les athl\u00e8tes handicap\u00e9s jetaient une mauvaise lumi\u00e8re sur l&#8217;humoriste et son personnage. Le porte-parole de la cha\u00eene, Christoph K\u00f6rfer, a expliqu\u00e9 qu&#8217;ils avaient d\u00e9cid\u00e9 de ne pas d\u00e9marrer l&#8217;\u00e9mission, pr\u00e9vue le 12 septembre. Les d\u00e9clarations de Mockridge \u00ab ne correspondent pas \u00e0 nos valeurs \u00bb.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/guildo-horn-kritisiert-luke-mockridge-du-bist-ein-armes-wuerstchen-2804665\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bien que Luke Mockridge ait maintenant pr\u00e9sent\u00e9 ses excuses pour ses commentaires insipides et blessants sur les Jeux Paralympiques, il doit encore accepter les critiques. Guildo Horn s&#8217;est \u00e9galement senti appel\u00e9 \u00e0 exprimer son opinion sur le sujet sur Instagram. \u00ab Presque aucun \u00e9v\u00e9nement sportif majeur de ces derni\u00e8res ann\u00e9es ne m\u2019a autant captiv\u00e9 que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1315399,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[252185,22,144658,8353,162503,251980,16646,67647,18358,97956],"class_list":["post-1315398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement","tag-corne-de-guildo","tag-critique","tag-guildo","tag-horn","tag-jeux-paralympiques","tag-luc-mockridge","tag-luke","tag-mockridge","tag-pauvre","tag-saucisson"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1315398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1315398"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1315398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1315399"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1315398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1315398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1315398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}