{"id":1315338,"date":"2024-09-08T21:39:15","date_gmt":"2024-09-08T23:39:15","guid":{"rendered":"https:\/\/teknomers.com\/fr\/vous-pouvez-me-dire-que-vous-etes-toujours-en-scientologie-lettre-de-colere-a-emily-armstrong\/"},"modified":"2024-09-08T21:39:19","modified_gmt":"2024-09-08T23:39:19","slug":"vous-pouvez-me-dire-que-vous-etes-toujours-en-scientologie-lettre-de-colere-a-emily-armstrong","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/vous-pouvez-me-dire-que-vous-etes-toujours-en-scientologie-lettre-de-colere-a-emily-armstrong\/","title":{"rendered":"\u00ab\u00a0Vous pouvez me dire que vous \u00eates toujours en Scientologie\u00a0\u00bb\u00a0: lettre de col\u00e8re \u00e0 Emily Armstrong"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Linkin Park aurait certainement aim\u00e9 \u00e9viter ce tapage. Le groupe avait \u00e0 peine annonc\u00e9 ses retrouvailles vendredi (6 septembre 2024) que les premi\u00e8res voix critiques se faisaient d\u00e9j\u00e0 entendre. Mike Shinoda a non seulement annonc\u00e9 un nouvel album (\u00ab From Zero \u00bb), mais a \u00e9galement imm\u00e9diatement pr\u00e9sent\u00e9 le rempla\u00e7ant de feu Chester Bennington lors du concert du groupe \u00e0 Los Angeles. Emily Armstrong reprendra son r\u00f4le \u00e0 l&#8217;avenir.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/09\/Vous-pouvez-me-dire-que-vous-etes-toujours-en-Scientologie.gif\" alt=\"\" width=\"1\" height=\"1\"\/><\/p>\n<p>Alors que la veuve de Chester, Talinda Bennington, est enthousiasm\u00e9e par son successeur, Armstrong lui-m\u00eame est pris entre deux feux.<\/p>\n<h2>Emily Armstrong est-elle (encore) scientologue ?<\/h2>\n<p>Les fans et les critiques ont remarqu\u00e9 qu&#8217;Armstrong avait soutenu le d\u00e9linquant sexuel condamn\u00e9 Danny Masterson dans le pass\u00e9. On dit \u00e9galement qu\u2019elle est \u2013 ou a \u00e9t\u00e9 \u2013 membre de la Scientologie.<\/p>\n<p>Armstrong a pris ses distances avec Masterson dans une d\u00e9claration samedi (sans mentionner son nom), mais n&#8217;a pas dit un mot sur son appartenance pr\u00e9sum\u00e9e \u00e0 la Scientologie. La religion ou \u00ab religion \u00bb est une affaire priv\u00e9e, mais il semble impossible que leur silence sur le sujet puisse assurer le calme n\u00e9cessaire dans le camp de Linkin Park. On ne peut pas exclure que des gens manifestent contre la Scientologie, au moins devant les salles des concerts.<\/p>\n<p>La d\u00e9cision de confier \u00e0 Armstrong le remplacement de Chester Bennington a \u00e9t\u00e9 critiqu\u00e9e de plusieurs c\u00f4t\u00e9s, notamment <u>C\u00e9dric Bixler Zavala<\/u> par Mars Volta\/Au Drive-In. Son \u00e9pouse, Chrissie Carnell-Bixler, \u00e9tait l&#8217;une des quatre femmes qui ont port\u00e9 des all\u00e9gations de viol contre Masterson. Aujourd\u2019hui, elle s\u2019est \u00e9galement prononc\u00e9e contre Armstrong \u2013 et aussi contre Linkin Park.<\/p>\n<p>Bien que Carnell-Bixler ne fasse pas partie des deux &#8220;Jane Does&#8221; Masterson reconnues coupables d&#8217;abus sexuels, elle fait partie du proc\u00e8s civil en cours contre lui, qui devrait \u00eatre jug\u00e9 en septembre 2025 suite \u00e0 son appel. Les Bixler sont d\u2019anciens scientologues et critiquent l\u2019\u00c9glise depuis leur d\u00e9part. Ils disent que depuis qu\u2019ils ont d\u00e9nonc\u00e9 Masterson, ils ont \u00e9t\u00e9 soumis \u00e0 un harc\u00e8lement massif de la part de ses partisans qui sont membres de l\u2019\u00c9glise.<\/p>\n<h2>Carnell-Bixler s&#8217;exprime contre Armstrong sur Instagram avec des mots clairs\u00a0:<\/h2>\n<p>Ch\u00e8re \u00c9milie,<\/p>\n<p>Si vous ne d\u00e9noncez pas la secte du trafic d\u2019\u00eatres humains et d\u2019enfants \u00e0 laquelle vous appartenez et que vous favorisez par votre silence sur les crimes dont vous avez connaissance, alors vous n\u2019avez pas le droit de suivre les traces de Chester Bennington, un v\u00e9ritable d\u00e9fenseur.<\/p>\n<p>Je m&#8217;en fous que tu sois vraiment proche du violeur en s\u00e9rie. Je m&#8217;en fous que vous ayez menti \u00e0 propos de vos &#8220;excuses&#8221; sur votre story Instagram.<\/p>\n<p>Peu m&#8217;importe que, apr\u00e8s avoir \u00e9t\u00e9 interrog\u00e9, vous ayez particip\u00e9 \u00e0 la cruelle intimidation de Jane Doe 1 avec vos amis sectaires au tribunal. Peu m&#8217;importe que vous n&#8217;ayez pas mentionn\u00e9 une seule fois que vous \u00eates membre d&#8217;une secte de traite d&#8217;enfants et d&#8217;\u00eatres humains qui dissimule les abus et les viols d&#8217;ENFANTS et d&#8217;adultes.<\/p>\n<h2>\u00ab Honte \u00e0 Linkin Park \u00bb<\/h2>\n<p>Peu m&#8217;importe que vos parents travaillent pour l&#8217;OSA (Bureau des affaires sp\u00e9ciales) de la secte de Scientologie, qui a ordonn\u00e9 des attaques contre moi et ma famille, y compris le meurtre de mes chiens de mani\u00e8re inhumaine et vicieuse.<\/p>\n<p>Je m&#8217;en fiche que vous ayez attaqu\u00e9 et harcel\u00e9 mes camarades qui ont surv\u00e9cu. Vous ne dites rien contre la Scientologie, pas parce que vous en avez peur. Vous ne le dites pas parce que vous en faites partie. Honte \u00e0 Linkin Park. Tu peux me parler.<\/p>\n<p>C\u00e9dric Bixler-Zavala, son mari, a ajout\u00e9 ses r\u00e9flexions :<\/p>\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e717c8e69966540e4554f05\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu d&#8217;Instagram<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<p>\u00ab Un message de ma femme \u00e0 l&#8217;\u00e9tage. Un message de ma part\ud83d\udc49\ud83c\udffc Emily, saviez-vous qu&#8217;apr\u00e8s une journ\u00e9e de contre-interrogatoire merdique, votre ami Chris Wadhams et Danny sont pass\u00e9s tr\u00e8s lentement devant l&#8217;une des Jane Does et l&#8217;ont suivie dans sa voiture, la fixant pour l&#8217;intimider ? Moi, oui.<\/p>\n<p>Saviez-vous qu&#8217;Alana Masterson s&#8217;est cach\u00e9e dans les toilettes apr\u00e8s qu&#8217;un des inconnus \u00e0 la barre des t\u00e9moins ait eu une crise de panique massive et l&#8217;ait harcel\u00e9e dans la salle de bain, la traitant de menteuse ?<\/p>\n<p>Quoi, tu n&#8217;en as pas entendu parler ? Vos parents vous ont-ils prot\u00e9g\u00e9 de cela ? Vos parents atteints d&#8217;AOS. Ou tu pensais que \u00e7a allait ? Votre \u00e9glise n\u2019appelle-t-elle pas cela une \u00ab politique du fair-play \u00bb ? Ne sortiez-vous pas avec Nasal Queef lui-m\u00eame (Bijoux Phillips) il y a quelques jours \u00e0 peine ?<\/p>\n<p>Oh attends, elle va bien maintenant parce qu&#8217;elle a divorc\u00e9 de Danny ? Elle s&#8217;est \u00e9clat\u00e9e en lisant le rapport de police de ma femme dans un message moqueur. Tu te souviens comment elle a cri\u00e9 quand ils ont emmen\u00e9 Danny ? En ce moment, je me baigne tous les jours. Fais attention mon pote, la mal\u00e9diction Phillips est contagieuse, il suffit de lire le livre de Mackenzie Phillips.<\/p>\n<p>Tu devrais aussi te renseigner sur le comportement de ce foutu idiot. Bien s\u00fbr, seulement si l&#8217;\u00e9glise vous permet d&#8217;en lire davantage. Ils ont une politique qui interdit de lire quoi que ce soit de critique \u00e0 l&#8217;\u00e9gard de l&#8217;\u00c9glise et de ses membres. Votre \u00e9glise a \u00e9galement une vile culture de calomnie dans laquelle vous \u00e9crivez des reportages sur d\u2019autres membres qui ne \u00ab suivent \u00bb pas les enseignements de L. Ron Hubbard. Tout comme la Stasi est-allemande l\u2019a impos\u00e9 \u00e0 ses citoyens. Est-ce votre \u00e9glise ?<\/p>\n<p>Aujourd&#8217;hui, c&#8217;est le premier anniversaire de l&#8217;incarc\u00e9ration de cet enfoir\u00e9 que vous pensiez \u00eatre un &#8220;bon gars&#8221;. Vous ne pouvez m\u00eame pas vous excuser correctement aupr\u00e8s de Jane Does, n&#8217;est-ce pas ? Vos excuses sont formul\u00e9es comme si vous aviez engag\u00e9 une \u00e9quipe de crise en mati\u00e8re de relations publiques pour vous aider. Quant \u00e0 toi <a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/linkinpark\/\" target=\"_blank\">@linkinpark<\/a>\u2026. Vous devriez licencier toute votre \u00e9quipe pour ne pas avoir soigneusement examin\u00e9 ses choix. Vous \u00eates une marque de niveau Disney qui essaie de faire son retour et vous n&#8217;avez pas pens\u00e9 \u00e0 d\u00e9penser un peu d&#8217;argent pour le d\u00e9couvrir ? Arr\u00eatez de diffuser la musique du drive-in sur votre liste de lecture d&#8217;avant-spectacle.<\/p>\n<\/p><\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/du-kannst-mich-mal-du-bist-noch-bei-scientology-wutbrief-an-emily-armstrong-2804663\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Linkin Park aurait certainement aim\u00e9 \u00e9viter ce tapage. Le groupe avait \u00e0 peine annonc\u00e9 ses retrouvailles vendredi (6 septembre 2024) que les premi\u00e8res voix critiques se faisaient d\u00e9j\u00e0 entendre. Mike Shinoda a non seulement annonc\u00e9 un nouvel album (\u00ab From Zero \u00bb), mais a \u00e9galement imm\u00e9diatement pr\u00e9sent\u00e9 le rempla\u00e7ant de feu Chester Bennington lors du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1314445,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[46676,252183,2186,3992,8535,252182,6563,4489,249733,4293,77467,220,188],"class_list":["post-1315338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement","tag-armstrong","tag-chrissie-carnellbixler","tag-colere","tag-dire","tag-emily","tag-emily-amstrong","tag-etes","tag-lettre","tag-parc-linkin","tag-pouvez","tag-scientologie","tag-toujours","tag-vous"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1315338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1315338"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1315338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1314445"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1315338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1315338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1315338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}