{"id":1313035,"date":"2024-09-07T02:42:06","date_gmt":"2024-09-07T04:42:06","guid":{"rendered":"https:\/\/teknomers.com\/fr\/madison-square-garden-pearl-jam-joue-avec-steve-van-zandt\/"},"modified":"2024-09-07T02:42:11","modified_gmt":"2024-09-07T04:42:11","slug":"madison-square-garden-pearl-jam-joue-avec-steve-van-zandt","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/madison-square-garden-pearl-jam-joue-avec-steve-van-zandt\/","title":{"rendered":"Madison Square Garden : Pearl Jam joue avec Steve Van Zandt"},"content":{"rendered":"\n<div>\n<p>Pearl Jam a termin\u00e9 mercredi soir (4 septembre) son deuxi\u00e8me concert de son spectacle de deux jours au Madison Square Garden. Il y a eu des apparitions de Steve Van Zandt, Andrew Watt et Glen Hansard, qui ont jou\u00e9 &#8220;Rockin&#8217; In The Free World&#8221; de Neil Young avec le groupe.<\/p>\n<p>Cette chanson est jou\u00e9e r\u00e9guli\u00e8rement par Pearl Jam depuis 1992 et est la reprise la plus fr\u00e9quemment jou\u00e9e du groupe. Mais ils n\u2019ont jamais interpr\u00e9t\u00e9 la chanson avec Van Zandt. Le guitariste avait d\u00e9j\u00e0 particip\u00e9 \u00e0 la tourn\u00e9e \u00ab Vote For Change \u00bb avec Bruce Springsteen et Neil Young en 2004.<\/p>\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e7f6927b8e05c111d01b40f\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu de Spotify Ltd.<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<p>La setlist comprenait \u00e9galement six chansons de leur nouvel album \u00ab Dark Matter \u00bb, r\u00e9cemment sorti. Les fans ont \u00e9galement eu droit \u00e0 plusieurs classiques de leur premier album de 1991, \u00ab Ten \u00bb. Le groupe a \u00e9galement repris &#8220;Gimme Some Truth&#8221; de John Lennon, &#8220;Sonic R\u00e9ducteur&#8221; des Dead Boys et la propre chanson de Van Zandt &#8220;I Am A Patriot&#8221;.<\/p>\n<h2>Moments sp\u00e9ciaux pour les fans<\/h2>\n<p>Eddie Vedder, le leader de Pearl Jam, a fait une pause pendant le concert pour souligner l&#8217;anniversaire sp\u00e9cial du groupe : \u00ab\u00a0C&#8217;est notre 50e concert \u00e0 New York. Il est difficile de croire qu\u2019un petit groupe de Seattle puisse investir ce lieu l\u00e9gendaire pour une nuit \u00bb, a d\u00e9clar\u00e9 Vedder. \u00ab\u00a0En 1991, nous avons jou\u00e9 \u00e0 Wetlands, plus tard cette ann\u00e9e-l\u00e0, nous avons jou\u00e9 au CBGB, et maintenant nous voici au Madison Square Garden, l&#8217;une des plus grandes salles du monde. Mais ce sont les gens qui rendent cet endroit vraiment sp\u00e9cial. Vous nous avez fait sentir comme les gens les plus heureux du monde. Nous vous en sommes \u00e9ternellement reconnaissants.<\/p>\n<div class=\"asmb-article-instagram-embed\">\n<div class=\"embed-placeholder__container\" data-purpose-id=\"65b625cee4ef7506ad964bcd\" vendor=\"5e717c8e69966540e4554f05\" data-nosnippet=\"true\">\n<p>Vous trouverez ici du contenu d&#8217;Instagram<\/p>\n<p>Afin d&#8217;interagir avec ou d&#8217;afficher du contenu des r\u00e9seaux sociaux, nous avons besoin de votre consentement.<\/p>\n<p>\t<button class=\"embed-placeholder__button social\">Activer les r\u00e9seaux sociaux<\/button><\/p>\n<\/div>\n<\/div>\n<p>Le producteur Andrew Watt, partisan de longue date du groupe, a \u00e9galement eu un moment sp\u00e9cial ce soir-l\u00e0. Il a \u00e9t\u00e9 autoris\u00e9 \u00e0 monter sur sc\u00e8ne pour les chansons \u00ab Waiting For Stevie \u00bb et \u00ab Rearviewmirror \u00bb. Pour Watt, qui a vu Pearl Jam pour la premi\u00e8re fois en tant que fan au Madison Square Garden en 2003, la boucle \u00e9tait boucl\u00e9e.<\/p>\n<p>Il a racont\u00e9 comment il avait attendu \u00e0 l&#8217;ext\u00e9rieur de la salle avec une pancarte disant : &#8220;Laissez-moi jouer le solo de guitare de &#8216;Alive'&#8221;. &#8220;C&#8217;est mon groupe pr\u00e9f\u00e9r\u00e9&#8221;, a d\u00e9clar\u00e9 Watt dans une interview. &#8220;J&#8217;ai assist\u00e9 \u00e0 plus de 40 de leurs concerts, et mon concert pr\u00e9f\u00e9r\u00e9 \u00e9tait celui d&#8217;Halloween 2009 au Spectrum de Philadelphie. Ce concert est toujours consid\u00e9r\u00e9 comme le plus long de l&#8217;histoire de Pearl Jam, d&#8217;une dur\u00e9e de trois heures et 21 minutes. &#8220;<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rollingstone.de\/pearl-jam-madison-square-garden-steve-van-zandt-2803703\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-30<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pearl Jam a termin\u00e9 mercredi soir (4 septembre) son deuxi\u00e8me concert de son spectacle de deux jours au Madison Square Garden. Il y a eu des apparitions de Steve Van Zandt, Andrew Watt et Glen Hansard, qui ont jou\u00e9 &#8220;Rockin&#8217; In The Free World&#8221; de Neil Young avec le groupe. Cette chanson est jou\u00e9e r\u00e9guli\u00e8rement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1313036,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[249209,84,93114,143294,7333,251823,4994,4119,13614,33910,634,10991,251824,2536,86511],"class_list":["post-1313035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divertissement","tag-andrew-watts","tag-avec","tag-confiture-de-perles","tag-en-direct","tag-garden","tag-glen-hansard","tag-jam","tag-joue","tag-madison","tag-pearl","tag-square","tag-steve","tag-steve-van-zandt","tag-van","tag-zandt"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1313035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1313035"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1313035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1313036"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1313035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1313035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1313035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}