{"id":128056,"date":"2022-05-05T02:37:25","date_gmt":"2022-05-05T04:37:25","guid":{"rendered":"https:\/\/teknomers.com\/fr\/etude-les-acheteurs-en-ligne-preferent-payer-par-facture-ou-par-paypal\/"},"modified":"2022-05-05T02:37:37","modified_gmt":"2022-05-05T04:37:37","slug":"etude-les-acheteurs-en-ligne-preferent-payer-par-facture-ou-par-paypal","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/etude-les-acheteurs-en-ligne-preferent-payer-par-facture-ou-par-paypal\/","title":{"rendered":"\u00c9tude\u00a0: les acheteurs en ligne pr\u00e9f\u00e8rent payer par facture ou par Paypal"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>L&#8217;achat sur facture reste le mode de paiement le plus populaire pour les achats en ligne en Allemagne, mais avec une tendance \u00e0 la baisse.  Alors que 30,4 % de tous les achats en ligne \u00e9taient encore pay\u00e9s par facture en 2020, la proportion est tomb\u00e9e \u00e0 28,3 % en 2021, comme l&#8217;a rapport\u00e9 mercredi l&#8217;institut de recherche sur le commerce de d\u00e9tail de Cologne EHI dans son \u00e9tude &#8220;Online Payment 2022&#8221;.\n<\/p>\n<p>    Payer avec le service de paiement en ligne PayPal \u00e9tait presque aussi populaire parmi les consommateurs.  Il a pu augmenter sa part de march\u00e9 de 24,9 \u00e0 28,2 %.  Selon l&#8217;\u00e9tude EHI, la forte reprise de Paypal est due \u00e0 un changement de comportement de paiement d\u00fb \u00e0 la pand\u00e9mie de corona.  Dans le commerce en ligne qui est en plein essor pendant la pand\u00e9mie, les clients utilisent de plus en plus le service de paiement pour r\u00e9gler leurs factures.\n<\/p>\n<p>    Le pr\u00e9l\u00e8vement automatique occupe la troisi\u00e8me place du classement de popularit\u00e9 des m\u00e9thodes de paiement sur Internet avec une part des ventes de 17,4 %, soit un peu moins que l&#8217;ann\u00e9e pr\u00e9c\u00e9dente.  Les cartes de cr\u00e9dit ont \u00e9t\u00e9 utilis\u00e9es pour 11,4 % des achats &#8211; \u00e9galement un peu moins fr\u00e9quemment que l&#8217;ann\u00e9e pr\u00e9c\u00e9dente.  Tous les autres modes de paiement tels que les achats effectu\u00e9s \u00e0 l&#8217;avance, les virements directs ou le paiement \u00e0 la livraison ont jou\u00e9 un r\u00f4le secondaire.  (dpa)<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/fashionunited.de\/nachrichten\/business\/studie-online-shopper-zahlen-am-liebsten-per-rechnung-oder-paypal\/2022050446398\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-12<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;achat sur facture reste le mode de paiement le plus populaire pour les achats en ligne en Allemagne, mais avec une tendance \u00e0 la baisse. Alors que 30,4 % de tous les achats en ligne \u00e9taient encore pay\u00e9s par facture en 2020, la proportion est tomb\u00e9e \u00e0 28,3 % en 2021, comme l&#8217;a rapport\u00e9 mercredi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":128057,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[9697,323,4530,65,2903,164,1064,11277,2960],"class_list":["post-128056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-acheteurs","tag-etude","tag-facture","tag-les","tag-ligne","tag-par","tag-payer","tag-paypal","tag-preferent"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/128056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=128056"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/128056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/128057"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=128056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=128056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=128056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}