{"id":1234080,"date":"2024-07-11T09:48:14","date_gmt":"2024-07-11T11:48:14","guid":{"rendered":"https:\/\/teknomers.com\/fr\/ajoute-au-groupe-la-nouvelle-fonctionnalite-whatsapp-revele-la-raison\/"},"modified":"2024-07-11T09:48:19","modified_gmt":"2024-07-11T11:48:19","slug":"ajoute-au-groupe-la-nouvelle-fonctionnalite-whatsapp-revele-la-raison","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/ajoute-au-groupe-la-nouvelle-fonctionnalite-whatsapp-revele-la-raison\/","title":{"rendered":"Ajout\u00e9 au groupe\u00a0?  La nouvelle fonctionnalit\u00e9 WhatsApp r\u00e9v\u00e8le la raison"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div style=\"min-width: 70%\">\n<div class=\"d-flex align-items-center mb-3 position-relative font-os\" data-type=\"author\">\n<figure class=\"position-relative flex-shrink-1 flex-grow-0 ratio ratio-1x1 w-85px me-2 mb-0\">\n<\/figure>\n<\/div>\n<p class=\"font-os fw-light small\" data-type=\"timestamp\">11 juillet 2024, 13h19 | <span aria-label=\"read time\"><br \/>\n    Temps de lecture : 3 minutes<\/span>\n<\/p>\n<p class=\"fw-bold\">Le t\u00e9l\u00e9phone s&#8217;allume, une notification de WhatsApp appara\u00eet \u00e0 l&#8217;\u00e9cran &#8211; vous avez \u00e9t\u00e9 ajout\u00e9 \u00e0 un nouveau groupe.  Si cela n\u2019est pas annonc\u00e9, cela entra\u00eene souvent de l\u2019irritation et des questions.  De quel genre de groupe s\u2019agit-il et est-ce que je souhaite en faire partie\u00a0?  Une nouvelle fonction est destin\u00e9e \u00e0 rem\u00e9dier \u00e0 la situation.<\/p>\n<div class=\"w-auto d-flex flex-column-reverse d-lg-block w-mrec\">\n<p>Le messager WhatsApp offre \u00e0 ses utilisateurs de nombreuses fonctionnalit\u00e9s am\u00e9lior\u00e9es et compl\u00e9t\u00e9es par d&#8217;autres.  L&#8217;un d&#8217;eux est la fonction de groupe.  Plus de 1 000 personnes peuvent rejoindre un groupe WhatsApp, qui peuvent ensuite s&#8217;\u00e9crire, s&#8217;appeler ou encore cr\u00e9er des groupes au sein du groupe.  Mais il arrive encore et encore que vous soyez ajout\u00e9 \u00e0 un nouveau groupe WhatsApp sans conna\u00eetre la raison ni le but du groupe.  L\u2019entreprise a d\u00e9sormais introduit une nouvelle fonction qui devrait changer cela.  TECHBOOK explique comment cela fonctionne.<\/p>\n<\/div>\n<h2 class=\"wp-block-heading\" id=\"h-whatsapp-kundigt-neue-funktion-an\">WhatsApp annonce une nouvelle fonction<\/h2>\n<p>Selon un communiqu\u00e9 de WhatsApp, la messagerie lancera prochainement une nouvelle fonctionnalit\u00e9 pour ses groupes.  Ceci est destin\u00e9 \u00e0 fournir des informations sur le contenu du groupe apr\u00e8s que vous ayez \u00e9t\u00e9 invit\u00e9 mais avant de le rejoindre.  \u00c0 l\u2019avenir, de petites fiches d\u2019information seront attach\u00e9es aux discussions partag\u00e9es.  Ceci est particuli\u00e8rement utile si vous ne connaissez pas la personne qui vous a invit\u00e9. <\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"556\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/07\/Ajoute-au-groupe-La-nouvelle-fonctionnalite-WhatsApp-revele-la-raison.png\" alt=\"Nouvelle bo\u00eete d'informations sur le groupe WhatsApp\" loading=\"lazy\"  class=\"img-2434225 size-xl d-inline-block img-fluid w-100 \"\/><figcaption class=\"small fw-bold mt-1\">\n<p>         WhatsApp a annonc\u00e9 la nouvelle fonctionnalit\u00e9 pour les groupes avec un graphique                      <span class=\"fw-normal\">Photo\u00a0: TECHBOOK via WhatsApp<\/span><br \/>\n            <\/figcaption><\/figure>\n<p>Quiconque recevra \u00e0 l\u2019avenir une invitation de groupe verra imm\u00e9diatement un petit aper\u00e7u.  Cela montre qui vous a invit\u00e9 dans le groupe et \u00e9galement qui l&#8217;a cr\u00e9\u00e9.  Vous pouvez \u00e9galement voir la photo de groupe et la description directement sur la fiche d&#8217;information.  Au bas de la carte se trouve un gros bouton qui vous permet de quitter imm\u00e9diatement le groupe WhatsApp s&#8217;il s&#8217;agit simplement de spam.<\/p>\n<section data-type=\"related-posts\" class=\"d-flex flex-column justify-content-between gap-2 pb-2 mb-4 border-bottom border-dark\">\n<p>plus sur le sujet<\/p>\n<article data-id=\"2305262\" data-type=\"teaser-s\" class=\"position-relative d-flex mb-2 gap-2\">\n<figure class=\"position-relative mb-0 overflow-hidden align-self-center col-3\">\n            <img decoding=\"async\" width=\"128\" height=\"72\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/07\/24-applications-payantes-et-gratuites-aujourdhui.svg.svg+xml\" alt=\"L'image n'a pas pu \u00eatre charg\u00e9e\" class=\"img-fallback size-s d-inline-block img-fluid w-100 \" loading=\"lazy\"\/><\/p>\n<\/figure>\n<h3 class=\"m-0 col d-flex flex-column justify-content-center\">\n        <span class=\"d-block fw-normal m-0 mt-1 text-primary h6\">Pour Android<\/span><br \/>\n        Une nouvelle fonction vise \u00e0 \u00e9viter les accidents de photos sur WhatsApp<br \/>\n    <\/h3>\n<\/article>\n<article data-id=\"2402624\" data-type=\"teaser-s\" class=\"position-relative d-flex mb-2 gap-2\">\n<figure class=\"position-relative mb-0 overflow-hidden align-self-center col-3\">\n            <img decoding=\"async\" width=\"128\" height=\"72\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/07\/1720698494_683_Ajoute-au-groupe-La-nouvelle-fonctionnalite-WhatsApp-revele-la-raison.jpg\" alt=\"Logo WhatsApp sur fond noir : symbole pour les discussions vocales en groupe\" loading=\"lazy\"  class=\"img-2402641 size-s d-inline-block img-fluid w-100 bg-fallback \"\/><\/p>\n<\/figure>\n<h3 class=\"m-0 col d-flex flex-column justify-content-center\">\n        <span class=\"d-block fw-normal m-0 mt-1 text-primary h6\">Pour les groupes<\/span><br \/>\n        WhatsApp pr\u00e9voit une toute nouvelle fonction de t\u00e9l\u00e9phonie<br \/>\n    <\/h3>\n<\/article>\n<article data-id=\"2353456\" data-type=\"teaser-s\" class=\"position-relative d-flex mb-2 gap-2\">\n<figure class=\"position-relative mb-0 overflow-hidden align-self-center col-3\">\n            <img decoding=\"async\" width=\"128\" height=\"72\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/07\/1720698494_372_Ajoute-au-groupe-La-nouvelle-fonctionnalite-WhatsApp-revele-la-raison.jpg\" alt=\"WhatsApp sur votre smartphone\" loading=\"lazy\"  class=\"img-2353471 size-s d-inline-block img-fluid w-100 bg-fallback \"\/><\/p>\n<\/figure>\n<h3 class=\"m-0 col d-flex flex-column justify-content-center\">\n        <span class=\"d-block fw-normal m-0 mt-1 text-primary h6\">En d\u00e9veloppement<\/span><br \/>\n        Le statut \u00ab Derni\u00e8re connexion \u00bb sur WhatsApp sera bient\u00f4t personnalis\u00e9 individuellement<br \/>\n    <\/h3>\n<\/article>\n<\/section>\n<h2 class=\"wp-block-heading\" id=\"h-wann-kommt-das-feature-fur-whatsapp-gruppen\">Quand la fonctionnalit\u00e9 de groupe WhatsApp arrivera-t-elle ?<\/h2>\n<p>Au-dessus de ce bouton, vous pouvez \u00e9galement voir le texte vert \u00ab Outils de s\u00e9curit\u00e9 \u00bb.  WhatsApp n\u2019a pas encore r\u00e9v\u00e9l\u00e9 en d\u00e9tail de quoi il s\u2019agit.  Cependant, si vous cliquez dessus, vous obtiendrez probablement l&#8217;aper\u00e7u de s\u00e9curit\u00e9 habituel, qui est \u00e9galement li\u00e9 lorsqu&#8217;une personne inconnue contacte quelqu&#8217;un via un chat individuel.<\/p>\n<p><em>Aussi int\u00e9ressant : Conseils pour les messages vocaux sur WhatsApp<\/em><\/p>\n<p>Avant de prendre contact par \u00e9crit avec cette personne, vous disposez de plusieurs options en quelques clics.  Vous pouvez soit bloquer le contact directement, soit m\u00eame le signaler.  Vous recevrez \u00e9galement quelques informations sur la meilleure fa\u00e7on de proc\u00e9der afin d&#8217;identifier l&#8217;exp\u00e9diteur si n\u00e9cessaire et de d\u00e9terminer s&#8217;il s&#8217;agit d&#8217;une personne r\u00e9put\u00e9e.<\/p>\n<p>WhatsApp n&#8217;a pas donn\u00e9 de date pr\u00e9cise pour le d\u00e9ploiement de la fonctionnalit\u00e9.  Cependant, la fonction pour les groupes WhatsApp devrait \u00eatre d\u00e9ploy\u00e9e \u00e0 partir de la semaine prochaine.  Apparemment, un lancement simultan\u00e9 pour Android et iOS est \u00e9galement pr\u00e9vu.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.techbook.de\/mobile-lifestyle\/apps\/whatsapp-gruppe-hinzugefuegt-feature\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-35<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>11 juillet 2024, 13h19 | Temps de lecture : 3 minutes Le t\u00e9l\u00e9phone s&#8217;allume, une notification de WhatsApp appara\u00eet \u00e0 l&#8217;\u00e9cran &#8211; vous avez \u00e9t\u00e9 ajout\u00e9 \u00e0 un nouveau groupe. Si cela n\u2019est pas annonc\u00e9, cela entra\u00eene souvent de l\u2019irritation et des questions. De quel genre de groupe s\u2019agit-il et est-ce que je souhaite en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1234081,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[12361,13357,681,43341,197,120,253,2178,13553],"class_list":["post-1234080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-ajoute","tag-fonctionnalite","tag-groupe","tag-messager","tag-nouvelle","tag-nouvelles","tag-raison","tag-revele","tag-whatsapp"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1234080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1234080"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1234080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1234081"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1234080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1234080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1234080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}