{"id":1231777,"date":"2024-07-09T19:00:52","date_gmt":"2024-07-09T21:00:52","guid":{"rendered":"https:\/\/teknomers.com\/fr\/ali-b-ne-suit-pas-sa-declaration-sil-doit-aller-en-prison-il-ne-veut-pas-etre-filme\/"},"modified":"2024-07-09T19:00:57","modified_gmt":"2024-07-09T21:00:57","slug":"ali-b-ne-suit-pas-sa-declaration-sil-doit-aller-en-prison-il-ne-veut-pas-etre-filme","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/ali-b-ne-suit-pas-sa-declaration-sil-doit-aller-en-prison-il-ne-veut-pas-etre-filme\/","title":{"rendered":"Ali B ne suit pas sa d\u00e9claration : &#8220;S&#8217;il doit aller en prison, il ne veut pas \u00eatre film\u00e9&#8221;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"post-449569\">\n<div class=\"entry__content\">\n<p>Ali B a parcouru les couloirs du tribunal pendant trois jours d&#8217;audience, mais il n&#8217;a pas r\u00e9ussi \u00e0 assister au moment supr\u00eame : le rappeur n&#8217;est pas parvenu au verdict.<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9RTL<\/span> <\/div>\n<p>Apparemment, tout cela devient un peu trop chaud sous ses pieds : Ali B ne se pr\u00e9sentera pas vendredi apr\u00e8s-midi au verdict dans l&#8217;affaire d&#8217;infraction sexuelle contre lui, confirme son avocat Bart Swier. <a rel=\"nofollow noopener\" href=\"https:\/\/www.rtl.nl\/boulevard\/crime\/artikel\/5459670\/ali-b-vrijdag-niet-aanwezig-uitspraak-zedenzaak\" target=\"_blank\">Boulevard RTL<\/a>.  Et tout cela alors qu&#8217;il \u00e9tait encore pr\u00e9sent pendant les trois jours de l&#8217;audience, discutant gaiement avec la presse dans les couloirs et autorisant toutes les cam\u00e9ras.<\/p>\n<h2 class=\"wp-block-heading\">Premier plan<\/h2>\n<p>Jermaine Ellenkamp, \u200b\u200bjournaliste policier de RTL Boulevard, est frapp\u00e9e par l&#8217;absence d&#8217;Ali, car il en a d\u00e9lib\u00e9r\u00e9ment fait un v\u00e9ritable cirque m\u00e9diatique.  \u00ab Ali s\u2019est mis au premier plan lors du proc\u00e8s.  Cela a commenc\u00e9 d\u00e8s le premier jour, lorsqu\u2019il est sorti du parking avec le sourire et plein de confiance et a donn\u00e9 des interviews.<\/p>\n<p>Il poursuit : \u00ab Ce n&#8217;est qu&#8217;au troisi\u00e8me jour du proc\u00e8s que ses avocats l&#8217;ont ralenti.  Peut-\u00eatre lui ont-ils maintenant conseill\u00e9 de ne pas venir.  Parce que s\u2019il \u00e9tait condamn\u00e9, les entretiens deviendraient tr\u00e8s inconfortables.\u00bb<\/p>\n<h2 class=\"wp-block-heading\">Trois ans<\/h2>\n<p>Il se pourrait qu&#8217;Ali B soit condamn\u00e9 \u00e0 trois ans de prison et s&#8217;il sort, il ne s&#8217;int\u00e9ressera apparemment plus aux journalistes de RTL Boulevard et Shownieuws. <\/p>\n<p>Si le rappeur est reconnu coupable, il a d\u00e9j\u00e0 annonc\u00e9 qu&#8217;il ferait appel.  On ne sait toujours pas si nous le reverrons lors de ces journ\u00e9es d&#8217;audience.<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2024\/07\/ali-b-niet-naar-uitspraak-als-hij-bak-in-moet-wil-hij-niet-op-camera\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ali B a parcouru les couloirs du tribunal pendant trois jours d&#8217;audience, mais il n&#8217;a pas r\u00e9ussi \u00e0 assister au moment supr\u00eame : le rappeur n&#8217;est pas parvenu au verdict. \u00a9RTL Apparemment, tout cela devient un peu trop chaud sous ses pieds : Ali B ne se pr\u00e9sentera pas vendredi apr\u00e8s-midi au verdict dans l&#8217;affaire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1231778,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[1990,221206,1503,946,1626,1643,8005,132,3036,2009,4741,1148],"class_list":["post-1231777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-ali","tag-ali-b","tag-aller","tag-declaration","tag-doit","tag-etre","tag-filme","tag-pas","tag-prison","tag-sil","tag-suit","tag-veut"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1231777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1231777"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1231777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1231778"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1231777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1231777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1231777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}