{"id":1224242,"date":"2024-07-03T20:37:00","date_gmt":"2024-07-03T22:37:00","guid":{"rendered":"https:\/\/teknomers.com\/fr\/la-tension-est-montee-mais-cavendish-en-compte-desormais-35\/"},"modified":"2024-07-03T20:37:05","modified_gmt":"2024-07-03T22:37:05","slug":"la-tension-est-montee-mais-cavendish-en-compte-desormais-35","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/la-tension-est-montee-mais-cavendish-en-compte-desormais-35\/","title":{"rendered":"La tension est mont\u00e9e mais Cavendish en compte d\u00e9sormais 35"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"has-drop-cap\">Et bien s\u00fbr, il l\u2019a fait.  Au cinqui\u00e8me jour du Tour, lors d&#8217;une \u00e9tape qui s&#8217;est termin\u00e9e dans une zone industrielle de la commune de Saint-Vulbas \u00e0 l&#8217;est de Lyon, le sprinter Mark Cavendish a remport\u00e9 le record qu&#8217;il court apr\u00e8s des ann\u00e9es : sa 35e victoire d&#8217;\u00e9tape sur le Tour de France.  Il s&#8217;est habilement fray\u00e9 un chemin vers l&#8217;avant du peloton en passant par quelques \u00e9carts \u00e0 l&#8217;avant et a battu ses concurrents avec presque une diff\u00e9rence de longueur de v\u00e9lo. <\/p>\n<p>\u00ab Cav \u00bb est d\u00e9sormais le coureur avec le plus d&#8217;\u00e9tapes du Tour \u00e0 son actif \u2013 une de plus qu&#8217;Eddy Merckx, consid\u00e9r\u00e9 par beaucoup comme le meilleur cycliste de tous les temps.  Les autres pilotes, y compris ses concurrents directs au sprint, \u00e9taient conscients du moment historique : ils ont f\u00e9licit\u00e9 Cavendish avec exub\u00e9rance apr\u00e8s l&#8217;arriv\u00e9e.<\/p>\n<p>Lors de la conf\u00e9rence de presse qui a suivi, Cavendish (39 ans) a eu du mal \u00e0 contr\u00f4ler ses \u00e9motions.  Par \u00e0-coups, il raconta comment les derniers kilom\u00e8tres du sprint avaient \u00e9t\u00e9 parcourus.  \u00ab Restez calme et faites confiance \u00e0 mes co\u00e9quipiers.  C&#8217;est tout ce que je pouvais faire.  Silence.  \u00abCela venait de mon discours sur la psychologie du sport.  Ce n\u2019est pas formul\u00e9 de mani\u00e8re tr\u00e8s \u00e9loquente.<\/p>\n<h2 class=\"gn4-crosshead article-heading\">Dans le d\u00e9clin<\/h2>\n<p>Le chemin vers le record a \u00e9t\u00e9 long et difficile pour Cavendish \u2013 \u00ab Sir Mark \u00bb pendant plusieurs semaines.  Il a remport\u00e9 sa premi\u00e8re victoire d&#8217;\u00e9tape sur le Tour en 2008, alors que les sprints group\u00e9s \u00e9taient domin\u00e9s par une g\u00e9n\u00e9ration de coureurs d\u00e9sormais \u00e0 la retraite depuis des ann\u00e9es : Oscar Freire, Andr\u00e9 Greipel, Robbie McEwan.  Apr\u00e8s des ann\u00e9es de domination totale, Cavendish s\u2019est effondr\u00e9 au milieu de la derni\u00e8re d\u00e9cennie \u2013 en fin de compte, \u00e0 cause d\u2019une grave d\u00e9pression.  Il est revenu et a de nouveau remport\u00e9 quatre \u00e9tapes du Tour en 2021 apr\u00e8s une s\u00e9cheresse de cinq ans.<\/p>\n<p>L&#8217;ann\u00e9e derni\u00e8re, la poursuite du record de Merckx par Cavendish a \u00e9chou\u00e9 lorsqu&#8217;il s&#8217;est \u00e9cras\u00e9 et a d\u00fb abandonner.  Il a alors d\u00e9cid\u00e9 de reporter d&#8217;un an sa retraite d\u00e9j\u00e0 annonc\u00e9e, mais sur ce Tour aussi, il a vite sembl\u00e9 qu&#8217;il allait mourir pr\u00e9matur\u00e9ment : lors de la premi\u00e8re \u00e9tape, il s&#8217;est senti tellement mal \u00e0 cause de la chaleur qu&#8217;il a vomi sur le v\u00e9lo et a d\u00fb se laisser guider jusqu&#8217;\u00e0 l&#8217;arriv\u00e9e par ses co\u00e9quipiers dans le temps imparti. <\/p>\n<p><dmt-icon class=\"dmt-article-suggestion__icon\" name=\"ic-forward\"\/><\/p>\n<div class=\"dmt-article-suggestion__text\">\n<p>\t\t\t\tLire aussi\n\t\t\t<\/p>\n<p><span>Quand cela suffira-t-il \u00e0 Sir Mark Cavendish ?<\/span>\n<\/div>\n<p>Dans le bus de l&#8217;\u00e9quipe Astana de Cavendish, gar\u00e9 le long d&#8217;un champ de ma\u00efs \u00e0 la p\u00e9riph\u00e9rie de Saint-Vulbas, les membres du staff se tapent sur les \u00e9paules apr\u00e8s la victoire en rugissant.  L&#8217;entra\u00eeneur cycliste grec Vasilis Anastopoulos, qui a jou\u00e9 un r\u00f4le cl\u00e9 dans le retour de Cavendish de la d\u00e9pression, est en larmes.  \u00abNous avons connu tellement de revers\u00bb, dit-il.  \u00ab Nous avons pass\u00e9 trois mois en Gr\u00e8ce.  Form\u00e9 tous les jours.  La semaine derni\u00e8re, nous avons fait quelques bonnes s\u00e9ances et j&#8217;\u00e9tais optimiste.  Et puis est arriv\u00e9e l\u2019insolation. <\/p>\n<h2 class=\"gn4-crosshead article-heading\">Visite familiale<\/h2>\n<p>Un peu plus tard, le N\u00e9erlandais Cees Bol, le principal assistant de Cavendish dans le train sprint, est assis content sur le capot d&#8217;une voiture.  La tension au sein de l&#8217;\u00e9quipe s&#8217;est accrue ces derniers jours, dit-il, apr\u00e8s la journ\u00e9e d&#8217;horreur de Cavendish lors de la premi\u00e8re \u00e9tape et une occasion manqu\u00e9e lors de l&#8217;\u00e9tape de sprint vers Turin lundi.  \u00ab Vous avez remarqu\u00e9 une pr\u00e9f\u00e9rence pour ne parler vraiment du sprint que le matin de l&#8217;\u00e9tape \u00bb, dit-il.  &#8220;C&#8217;est g\u00e9nial que cela ait fonctionn\u00e9 aujourd&#8217;hui.&#8221; <\/p>\n<p>Cavendish a bien chronom\u00e9tr\u00e9 sa victoire record : mardi dernier, sa femme et ses cinq enfants sont arriv\u00e9s d&#8217;Angleterre dans la caravane du Tour.  &#8220;Je pense que j&#8217;\u00e9tais \u00e0 la maison pendant trois semaines cette ann\u00e9e&#8221;, a-t-il d\u00e9clar\u00e9 apr\u00e8s l&#8217;arriv\u00e9e. <\/p>\n<p><dmt-icon class=\"dmt-article-suggestion__icon\" name=\"ic-forward\"\/><\/p>\n<div class=\"dmt-article-suggestion__text\">\n<p>\t\t\t\tLire aussi\n\t\t\t<\/p>\n<p><span>Quand cela suffira-t-il \u00e0 Sir Mark Cavendish ?<\/span>\n<\/div>\n<p><img decoding=\"async\" alt=\"Mark Cavendish samedi lors de la premi\u00e8re \u00e9tape du Tour de France.\" class=\"dmt-article-suggestion__image\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2024\/07\/La-tension-est-montee-mais-Cavendish-en-compte-desormais-35.jpg\"\/><\/p>\n<p><dmt-util-bar article=\"4858627\" headline=\"De spanning nam toe maar  Cavendish heeft er nu 35\" url=\"https:\/\/www.nrc.nl\/nieuws\/2024\/07\/03\/de-spanning-nam-toe-maar-cavendish-heeft-er-nu-35-a4858627\"><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"share\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Partager<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-share-web\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"contact\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Envoyer un email \u00e0 l&#8217;\u00e9diteur<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-email\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<\/dmt-util-bar> <\/p>\n<aside data-article-id=\"4858627\" data-js-topic-preview=\"\" data-topic-id=\"43\" data-topic-name=\"Wielrennen\"\/>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2024\/07\/03\/de-spanning-nam-toe-maar-cavendish-heeft-er-nu-35-a4858627\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et bien s\u00fbr, il l\u2019a fait. Au cinqui\u00e8me jour du Tour, lors d&#8217;une \u00e9tape qui s&#8217;est termin\u00e9e dans une zone industrielle de la commune de Saint-Vulbas \u00e0 l&#8217;est de Lyon, le sprinter Mark Cavendish a remport\u00e9 le record qu&#8217;il court apr\u00e8s des ann\u00e9es : sa 35e victoire d&#8217;\u00e9tape sur le Tour de France. Il s&#8217;est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1224243,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[28436,2205,4300,40,286,16651,4350],"class_list":["post-1224242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-cavendish","tag-compte","tag-desormais","tag-est","tag-mais","tag-montee","tag-tension"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1224242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1224242"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1224242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1224243"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1224242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1224242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1224242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}