{"id":117634,"date":"2022-04-29T11:10:11","date_gmt":"2022-04-29T13:10:11","guid":{"rendered":"https:\/\/teknomers.com\/fr\/nouvelles-sur-la-sante-de-la-reine-elizabeth-le-prince-harry-et-meghan-ont-recu-lordre-de-restez-a-lecart-de-jubilee-car-ils-gacheront-tout\/"},"modified":"2022-04-29T11:10:21","modified_gmt":"2022-04-29T13:10:21","slug":"nouvelles-sur-la-sante-de-la-reine-elizabeth-le-prince-harry-et-meghan-ont-recu-lordre-de-restez-a-lecart-de-jubilee-car-ils-gacheront-tout","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/nouvelles-sur-la-sante-de-la-reine-elizabeth-le-prince-harry-et-meghan-ont-recu-lordre-de-restez-a-lecart-de-jubilee-car-ils-gacheront-tout\/","title":{"rendered":"Nouvelles sur la sant\u00e9 de la reine Elizabeth \u2013 Le prince Harry et Meghan ont re\u00e7u l&#8217;ordre de \u00abRESTEZ \u00c0 L&#8217;\u00c9CART\u00bb de Jubilee car ils \u00abg\u00e2cheront tout\u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<h3 id=\"charles-holds-emotional-meeting-with-ukrainian-refugees\">Charles tient une r\u00e9union &#8220;\u00e9motionnelle&#8221; avec des r\u00e9fugi\u00e9s ukrainiens<\/h3>\n<p>Le prince de Galles a d\u00e9clar\u00e9 qu&#8217;il esp\u00e9rait que la Grande-Bretagne accueillerait les Ukrainiens lors d&#8217;une r\u00e9union &#8220;\u00e9motionnelle&#8221; avec les familles qui ont fui l&#8217;invasion de Vladimir Poutine.<\/p>\n<p>Charles, qui aurait personnellement sugg\u00e9r\u00e9 de rencontrer des r\u00e9fugi\u00e9s d&#8217;Ukraine, a ajout\u00e9 qu&#8217;il priait pour que le conflit se termine rapidement.<\/p>\n<p>Il a fait ces commentaires lors d&#8217;une visite \u00e0 l&#8217;association caritative World Jewish Relief (WJR) dans le nord de Londres, qui a envoy\u00e9 de la nourriture, de l&#8217;argent et des m\u00e9dicaments dans ce pays d\u00e9chir\u00e9 par la guerre.<\/p>\n<p>Charles, m\u00e9c\u00e8ne du groupe depuis 2015, a apport\u00e9 une contribution financi\u00e8re \u00e0 ses efforts bien que la somme n&#8217;ait pas \u00e9t\u00e9 rendue publique.<\/p>\n<p>Le pr\u00e9sident du WJR, Maurice Helfgott, a d\u00e9clar\u00e9 au prince qu&#8217;il \u00e9crirait une lettre pour le remercier du don.  &#8220;Ne vous emb\u00eatez pas avec \u00e7a&#8221;, a r\u00e9pondu le prince, aux rires de la pi\u00e8ce.<\/p>\n<p>Apr\u00e8s avoir parl\u00e9 \u00e0 l&#8217;\u00e9quipe charg\u00e9e de l&#8217;installation des r\u00e9fugi\u00e9s au Royaume-Uni, Charles a rencontr\u00e9 trois femmes ukrainiennes qui avaient fui la guerre, qui ont toutes demand\u00e9 \u00e0 ne pas \u00eatre nomm\u00e9es.<\/p>\n<p>Deux \u00e9taient originaires de Kharkiv, dans le nord-est de l&#8217;Ukraine, tandis que l&#8217;autre venait d&#8217;Odessa, dans le sud.  Les deux villes ont \u00e9t\u00e9 lourdement bombard\u00e9es par les forces russes.<\/p>\n<p>&#8220;Jusqu&#8217;au jour de ma mort, je n&#8217;oublierai jamais le bruit des missiles&#8221;, a d\u00e9clar\u00e9 l&#8217;une des femmes.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/news\/royal\/18381931\/queen-elizabeth-health-meghan-markle-prince-harry-jubilee-latest\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charles tient une r\u00e9union &#8220;\u00e9motionnelle&#8221; avec des r\u00e9fugi\u00e9s ukrainiens Le prince de Galles a d\u00e9clar\u00e9 qu&#8217;il esp\u00e9rait que la Grande-Bretagne accueillerait les Ukrainiens lors d&#8217;une r\u00e9union &#8220;\u00e9motionnelle&#8221; avec les familles qui ont fui l&#8217;invasion de Vladimir Poutine. Charles, qui aurait personnellement sugg\u00e9r\u00e9 de rencontrer des r\u00e9fugi\u00e9s d&#8217;Ukraine, a ajout\u00e9 qu&#8217;il priait pour que le conflit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":117635,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[7210,707,57740,5260,2714,12529,3609,12193,5258,120,249,489,986,706,7901,34,60,2767],"class_list":["post-117634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-car","tag-elizabeth","tag-gacheront","tag-harry","tag-ils","tag-jubilee","tag-lecart","tag-lordre","tag-meghan","tag-nouvelles","tag-ont","tag-prince","tag-recu","tag-reine","tag-restez","tag-sante","tag-sur","tag-tout"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/117634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=117634"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/117634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/117635"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=117634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=117634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=117634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}