{"id":1164633,"date":"2024-02-24T17:06:26","date_gmt":"2024-02-24T19:06:26","guid":{"rendered":"https:\/\/teknomers.com\/fr\/bilan-superieur-aux-attentes-berkshire-hathaway-de-warren-buffett-detient-des-niveaux-de-liquidites-records\/"},"modified":"2024-02-24T17:06:30","modified_gmt":"2024-02-24T19:06:30","slug":"bilan-superieur-aux-attentes-berkshire-hathaway-de-warren-buffett-detient-des-niveaux-de-liquidites-records","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/bilan-superieur-aux-attentes-berkshire-hathaway-de-warren-buffett-detient-des-niveaux-de-liquidites-records\/","title":{"rendered":"Bilan sup\u00e9rieur aux attentes : Berkshire Hathaway de Warren Buffett d\u00e9tient des niveaux de liquidit\u00e9s records"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>La soci\u00e9t\u00e9 holding d&#8217;investissement de Warren Buffett, Berkshire Hathaway, a ouvert ses comptes.<\/p>\n<div>\n<p>Les r\u00e9sultats trimestriels de Berkshire Hathaway sont r\u00e9guli\u00e8rement tr\u00e8s attendus par les investisseurs.  L&#8217;investisseur vedette a d\u00e9sormais ouvert ses livres et a donn\u00e9 un aper\u00e7u de l&#8217;\u00e9volution de l&#8217;entreprise au quatri\u00e8me trimestre 2023.\n<\/p>\n<p>Le b\u00e9n\u00e9fice d&#8217;exploitation s&#8217;est \u00e9lev\u00e9 \u00e0 8,481 milliards de dollars au dernier trimestre 2023, en hausse de 28 % par rapport aux 6,625 milliards de dollars de l&#8217;ann\u00e9e derni\u00e8re.<br \/>\n<!-- sh_cad_2 --><\/p>\n<p>Le b\u00e9n\u00e9fice par action A \u00e9tait de 5\u00a0881 $, contre 4\u00a0116 $ il y a un an.  La soci\u00e9t\u00e9 holding d&#8217;investissement a ainsi r\u00e9alis\u00e9 une performance 30 pour cent sup\u00e9rieure aux attentes au quatri\u00e8me trimestre 2022.  Les analystes avaient pr\u00e9c\u00e9demment estim\u00e9 le BPA \u00e0 5 717 $.\n<\/p>\n<p>La soci\u00e9t\u00e9 holding de Buffett d\u00e9tenait \u00e9galement 167,6 milliards de dollars de liquidit\u00e9s au quatri\u00e8me trimestre, un record qui d\u00e9passe les 157,2 milliards de dollars que le conglom\u00e9rat d\u00e9tenait au trimestre pr\u00e9c\u00e9dent.<br \/>\n<!-- sh_cad_4 --><\/p>\n<h2 class=\"h4\">Bilan annuel de Buffett Holding<\/h2>\n<p>Pour l&#8217;ensemble de l&#8217;ann\u00e9e 2023, Berkshire Hathaway a d\u00e9clar\u00e9 un b\u00e9n\u00e9fice d&#8217;exploitation de 37,35 milliards de dollars, soit \u00e9galement une augmentation de 17 % par rapport au chiffre de 30,853 milliards de dollars de l&#8217;ann\u00e9e pr\u00e9c\u00e9dente.\n<\/p>\n<h2 class=\"h4\">13 F divulgue le d\u00e9p\u00f4t de Berkshire<\/h2>\n<p>Plus r\u00e9cemment, Buffett Holding a d\u00fb divulguer le formulaire 13 \u00e0 la SEC pour le quatri\u00e8me trimestre 2023.  Tous les avoirs du v\u00e9hicule d&#8217;investissement sont r\u00e9pertori\u00e9s ici.  Les actions de Paramount ne figuraient plus dans le top 15 des investisseurs vedettes.<br \/>\n<!-- sh_cad_6 --><\/p>\n<p>Les actions B de Berkshire Hathaway ont baiss\u00e9 de 0,50 pour cent \u00e0 417,22 dollars par rapport aux \u00e9changes au NYSE vendredi, tandis que les actions A ont augment\u00e9 de 0,55 pour cent \u00e0 628 930 dollars.\n<\/p>\n<p>Equipe \u00e9ditoriale finanzen.net<\/p>\n<\/div>\n<div id=\"\">\n<h2 class=\"headline headline--h4\">Produits \u00e0 effet de levier s\u00e9lectionn\u00e9s sur Berkshire Hathaway<\/h2>\n<p>Avec les knock-outs, les investisseurs sp\u00e9culatifs peuvent participer de mani\u00e8re disproportionn\u00e9e aux mouvements de prix.  S\u00e9lectionnez simplement le levier que vous souhaitez et nous vous montrerons les produits ouverts appropri\u00e9s sur Berkshire Hathaway.<\/p>\n<p class=\"font-color-red display-none\" id=\"lvgCustomHandleInfo\">L&#8217;effet de levier doit \u00eatre compris entre 2 et 20<\/p>\n<p><span class=\"ad-hint ad-hint--right display-block\">Publicit\u00e9<\/span><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/investment-profi-mit-zahlen-bilanz-schlaegt-erwartungen-warren-buffetts-berkshire-hathaway-haelt-barmittel-in-rekordhoehe-13285067\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 holding d&#8217;investissement de Warren Buffett, Berkshire Hathaway, a ouvert ses comptes. Les r\u00e9sultats trimestriels de Berkshire Hathaway sont r\u00e9guli\u00e8rement tr\u00e8s attendus par les investisseurs. L&#8217;investisseur vedette a d\u00e9sormais ouvert ses livres et a donn\u00e9 un aper\u00e7u de l&#8217;\u00e9volution de l&#8217;entreprise au quatri\u00e8me trimestre 2023. Le b\u00e9n\u00e9fice d&#8217;exploitation s&#8217;est \u00e9lev\u00e9 \u00e0 8,481 milliards de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1164449,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1608,507,8678,1849,8679,133,50329,11323,47932,7478,1629,2907,11321],"class_list":["post-1164633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance","tag-attentes","tag-aux","tag-berkshire","tag-bilan","tag-buffett","tag-des","tag-detient","tag-hathaway","tag-liquidites","tag-niveaux","tag-records","tag-superieur","tag-warren"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1164633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1164633"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1164633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1164449"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1164633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1164633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1164633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}