{"id":1089540,"date":"2024-01-06T10:04:15","date_gmt":"2024-01-06T12:04:15","guid":{"rendered":"https:\/\/teknomers.com\/fr\/pape-francois-la-vie-seteint-si-nous-restons-les-otages-des-echecs-et-des-regrets\/"},"modified":"2024-01-06T10:04:20","modified_gmt":"2024-01-06T12:04:20","slug":"pape-francois-la-vie-seteint-si-nous-restons-les-otages-des-echecs-et-des-regrets","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/pape-francois-la-vie-seteint-si-nous-restons-les-otages-des-echecs-et-des-regrets\/","title":{"rendered":"Pape Fran\u00e7ois : la vie s&#8217;\u00e9teint si nous restons les otages des \u00e9checs et des regrets"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>\u00c9coutez la version audio de l&#8217;article<\/button><\/p>\n<p class=\"atext\">\u00abNous devons aussi regarder vers le haut pour apprendre \u00e0 voir la r\u00e9alit\u00e9 d&#8217;en haut.  Nous en avons besoin sur le chemin de la vie, d&#8217;\u00eatre accompagn\u00e9s par l&#8217;amiti\u00e9 avec le Seigneur, par son amour qui nous soutient, par la lumi\u00e8re de sa Parole qui nous guide comme une \u00e9toile dans la nuit.  Nous en avons besoin sur le chemin de la foi, pour qu&#8217;elle ne se r\u00e9duise pas \u00e0 un ensemble de pratiques religieuses ou \u00e0 une habitude ext\u00e9rieure, mais qu&#8217;elle devienne un feu qui br\u00fble \u00e0 l&#8217;int\u00e9rieur et qui nous fasse devenir des chercheurs passionn\u00e9s du visage du Seigneur et des t\u00e9moins de son \u00c9vangile. .  Nous en avons besoin dans l&#8217;\u00c9glise, o\u00f9, au lieu de nous diviser selon nos id\u00e9es, nous sommes appel\u00e9s \u00e0 remettre Dieu au centre. \u00bb  Ainsi le pape Fran\u00e7ois dans l&#8217;hom\u00e9lie de la messe de l&#8217;Epiphanie depuis la basilique Saint-Pierre.  pr\u00e8s de 250 cardinaux, \u00e9v\u00eaques et pr\u00eatres ont conc\u00e9l\u00e9br\u00e9 la liturgie avec le Pontife \u00e0 l&#8217;autel central de la confession.<\/p>\n<p><h2 id=\"U501923380291SRB\">La vie s&#8217;efface si nous restons l&#8217;otage des \u00e9checs et des regrets<\/h2>\n<\/p>\n<p class=\"atext\">&#8220;Si nous vivons enferm\u00e9s dans le p\u00e9rim\u00e8tre \u00e9troit des choses terrestres, si nous marchons la t\u00eate baiss\u00e9e, otages de nos \u00e9checs et de nos regrets, si nous avons faim de biens et de consolations terrestres au lieu d&#8217;\u00eatre chercheurs de lumi\u00e8re et d&#8217;amour, notre vie s&#8217;\u00e9teint. &#8220;, a-t-il d\u00e9clar\u00e9. a d\u00e9clar\u00e9 le pape Fran\u00e7ois lors de l&#8217;hom\u00e9lie.<\/p>\n<p><h2 id=\"U501923380291E7\">La pratique religieuse ne peut \u00eatre r\u00e9duite \u00e0 l\u2019habillement ext\u00e9rieur<\/h2>\n<\/p>\n<p class=\"atext\">\u00ab Fr\u00e8res et s\u0153urs, gardez les yeux vers le ciel !  Nous devons \u00e9galement regarder vers le haut pour apprendre \u00e0 voir la r\u00e9alit\u00e9 d\u2019en haut.  Nous en avons besoin sur le chemin de la vie, d&#8217;\u00eatre accompagn\u00e9s par l&#8217;amiti\u00e9 avec le Seigneur, par son amour qui nous soutient, par la lumi\u00e8re de sa Parole qui nous guide comme une \u00e9toile dans la nuit.  Nous en avons besoin sur le chemin de la foi, pour qu&#8217;elle ne se r\u00e9duise pas \u00e0 un ensemble de pratiques religieuses ou \u00e0 une habitude ext\u00e9rieure, mais qu&#8217;elle devienne un feu qui br\u00fble en nous et nous fait devenir des chercheurs passionn\u00e9s du visage du Seigneur et des t\u00e9moins de son \u00c9vangile&#8221;, a-t-il d\u00e9clar\u00e9 lors de l&#8217;hom\u00e9lie du Pape Fran\u00e7ois.<\/p>\n<p><h2 id=\"U50192338029180D\">Comme les Mages, nous marchons sur la terre, mais les yeux lev\u00e9s vers le ciel<br \/><\/h2>\n<\/p>\n<p class=\"atext\">\u00abRepartons de Dieu, cherchons en Lui le courage de ne pas s&#8217;arr\u00eater face aux difficult\u00e9s, la force de surmonter les obstacles, la joie de vivre en communion et en harmonie\u00bb, souligne le Pape. point\u00e9 vers le ciel, les pieds marchant sur la terre et le c\u0153ur en adoration.  Ils sont habit\u00e9s par la nostalgie de l\u2019infini et leur regard est attir\u00e9 par les \u00e9toiles c\u00e9lestes.  Ils ne vivent pas les pieds dans les yeux, repli\u00e9s sur eux-m\u00eames, prisonniers d&#8217;un horizon terrestre, se tra\u00eenant dans la r\u00e9signation ou la plainte.  Ils l\u00e8vent la t\u00eate, pour attendre une lumi\u00e8re qui \u00e9claire le sens de leur vie, un salut qui vient d&#8217;en haut.  C&#8217;est ainsi qu&#8217;ils voient se lever une \u00e9toile, plus brillante que toutes, qui les attire et les met en route&#8221;, a d\u00e9clar\u00e9 le Pontife.<\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/lab24.ilsole24ore.com\/competenze-sfide-demografiche-italia\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/10\/Marelli-suspend-indefiniment-la-fermeture-de-lusine-de-Crevalcore.png\" alt=\"En savoir plus\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<p><h2 id=\"U501923380291OsB\">Nous ne vivons pas enferm\u00e9s dans le p\u00e9rim\u00e8tre des choses terrestres<\/h2>\n<\/p>\n<p class=\"atext\">\u00ab C&#8217;est la cl\u00e9 qui nous r\u00e9v\u00e8le le v\u00e9ritable sens de notre existence : si nous vivons enferm\u00e9s dans le p\u00e9rim\u00e8tre \u00e9troit des choses terrestres, si nous marchons la t\u00eate baiss\u00e9e, otages de nos \u00e9checs et de nos regrets, si nous avons faim des biens et des biens du monde. consolations, qu&#8217;ils sont aujourd&#8217;hui et demain ils ne seront plus l\u00e0, au lieu de chercheurs de lumi\u00e8re et d&#8217;amour, notre vie s&#8217;\u00e9teint.  I Magi, che pure sono stranieri e ancora non hanno incontrato Ges\u00f9, ci insegnano a guardare in alto, ad avere lo sguardo rivolto al cielo, ad alzare gli occhi verso i monti da dove ci verr\u00e0 l&#8217;aiuto, perch\u00e9 il nostro aiuto viene dal Monsieur&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/papa-francesco-vita-si-spegne-se-restiamo-ostaggio-fallimenti-e-rimpianti-AFvETKGC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9coutez la version audio de l&#8217;article \u00abNous devons aussi regarder vers le haut pour apprendre \u00e0 voir la r\u00e9alit\u00e9 d&#8217;en haut. Nous en avons besoin sur le chemin de la vie, d&#8217;\u00eatre accompagn\u00e9s par l&#8217;amiti\u00e9 avec le Seigneur, par son amour qui nous soutient, par la lumi\u00e8re de sa Parole qui nous guide comme une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1089541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[133,6710,28949,65,1266,4439,2220,22131,23166,8564,180],"class_list":["post-1089540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","tag-des","tag-echecs","tag-francois","tag-les","tag-nous","tag-otages","tag-pape","tag-regrets","tag-restons","tag-seteint","tag-vie"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1089540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1089540"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1089540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1089541"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1089540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1089540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1089540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}