{"id":1056615,"date":"2023-12-12T08:42:12","date_gmt":"2023-12-12T10:42:12","guid":{"rendered":"https:\/\/teknomers.com\/fr\/la-mort-dun-membre-a-entraine-la-chute-du-groupe-tarot-marko-hietala-raconte-maintenant-ce-qui-a-pousse-le-groupe-a-revenir-sur-les-scenes-de-concert\/"},"modified":"2023-12-12T08:42:16","modified_gmt":"2023-12-12T10:42:16","slug":"la-mort-dun-membre-a-entraine-la-chute-du-groupe-tarot-marko-hietala-raconte-maintenant-ce-qui-a-pousse-le-groupe-a-revenir-sur-les-scenes-de-concert","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/la-mort-dun-membre-a-entraine-la-chute-du-groupe-tarot-marko-hietala-raconte-maintenant-ce-qui-a-pousse-le-groupe-a-revenir-sur-les-scenes-de-concert\/","title":{"rendered":"La mort d&#8217;un membre a entra\u00een\u00e9 la chute du groupe Tarot &#8211; Marko Hietala raconte maintenant ce qui a pouss\u00e9 le groupe \u00e0 revenir sur les sc\u00e8nes de concert"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>Marko Hietala pense qu&#8217;il est possible que Tarot continue \u00e0 jouer occasionnellement.<\/p>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">C&#8217;\u00e9tait l&#8217;\u00e9t\u00e9 dernier <strong>Marko Hi\u00e9talan<\/strong> exceptionnel sur le plan des concerts.  Apr\u00e8s une longue interruption, le groupe Tarot a fait son retour \u00e0 Kuopio lorsqu&#8217;il a \u00e9t\u00e9 invit\u00e9 \u00e0 se produire au festival Old Farts Rock, dont les b\u00e9n\u00e9fices sont revers\u00e9s \u00e0 une \u0153uvre caritative.<\/p>\n<p class=\"paragraph\">&#8211; C&#8217;\u00e9tait un peu d\u00e9cevant pour nous aussi, d\u00e9crit Hietala dans le d\u00e9fi d&#8217;Iltalehti.<\/p>\n<p class=\"paragraph\">&#8211; On nous a demand\u00e9 s&#8217;il \u00e9tait temps.  Il a \u00e9t\u00e9 conclu que nous pouvions faire un seul concert.  Cela n&#8217;oblige rien et ne met pas le groupe en fuite, justifie le chanteur-bassiste.<\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:66.66666666666666%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/12\/1702377732_951_La-mort-dun-membre-a-entraine-la-chute-du-groupe.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/12\/1702377732_951_La-mort-dun-membre-a-entraine-la-chute-du-groupe.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2000\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Marko Hietalan Tarot-yhtye teki paluun viime kes\u00e4n\u00e4.\"\/><span class=\"caption-text\" itemprop=\"description\">Le groupe Tarot de Marko Hietala a fait son grand retour l&#8217;\u00e9t\u00e9 dernier.<!-- --> <\/span><span class=\"media-source\">Rosa Br\u00f6ijer<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">Il y a eu un grand int\u00e9r\u00eat : les billets ont \u00e9t\u00e9 vendus en une minute.  Un autre concert \u00e9tait demand\u00e9 \u00e0 Tarot.<\/p>\n<p class=\"paragraph\">La veille de leur apparition officielle, Tarot a donn\u00e9 un concert en plein air dans la zone du festival.<\/p>\n<p class=\"paragraph\">&#8211; La moiti\u00e9 des cachets du deuxi\u00e8me concert a \u00e9t\u00e9 revers\u00e9e \u00e0 des \u0153uvres caritatives et nous avons \u00e9galement pr\u00e9lev\u00e9 une petite somme pour la formation, admet Hietala.<\/p>\n<h3 class=\"subheadline\">Plus de concerts ?<\/h3>\n<p class=\"paragraph\">Hietala consid\u00e8re que des concerts de Tarot individuels similaires seraient possibles \u00e0 l&#8217;avenir.  L&#8217;\u00e9t\u00e9 prochain, le groupe sera vu \u00e0 Tuska, Nummirock et Kuopiorock.<\/p>\n<p class=\"paragraph\">Une v\u00e9ritable tourn\u00e9e semble peu probable.  Hietala est le seul des membres du groupe \u00e0 subvenir \u00e0 ses besoins gr\u00e2ce \u00e0 la musique.  D&#8217;autres membres ont leurs occupations civiles et leurs responsabilit\u00e9s personnelles qui les lient au foyer.<\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/img.ilcdn.fi\/RgaWJ7q8ApzVrnOQORf11_H4Dvc=\/full-fit-in\/920x0\/img-s3.ilcdn.fi\/6daac2fe1d01ce901374e4906dae13b4061dff2d254c2d590b8620ff4da37925.jpg\"\/><meta itemprop=\"width\" content=\"900\"\/><meta itemprop=\"height\" content=\"470\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Tarotin ovat muodostaneet Janne Tolsa, Tommi Salmela, Marko Hietala, Pecu Cinnari ja Zachary Hietala.\"\/><span class=\"caption-text\" itemprop=\"description\">Le Tarot a \u00e9t\u00e9 cr\u00e9\u00e9 par Janne Tolsa, Tommi Salmela, Marko Hietala, Pecu Cinnari et Zachary Hietala.<!-- --> <\/span><span class=\"media-source\">Page d&#8217;accueil du Tarot<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">Les performances de l&#8217;\u00e9t\u00e9 dernier \u00e0 Kuopio ont d\u00e9cid\u00e9 que les concerts \u00e9taient m\u00eame d\u00e9sormais envisag\u00e9s.  L&#8217;entra\u00eenement s&#8217;est bien pass\u00e9 avec les vieux amis, mais sur sc\u00e8ne, l&#8217;ancienne attitude et l&#8217;agressivit\u00e9 du groupe m&#8217;ont surpris.<\/p>\n<p class=\"paragraph\">&#8211; Il s&#8217;est \u00e9lev\u00e9 par derri\u00e8re comme un nuage noir.  Tout le monde tire jusqu&#8217;au bout.  Nous nous sommes regard\u00e9s et avons \u00e9t\u00e9 \u00e9tonn\u00e9s de vivre une p\u00e9riode aussi difficile.<\/p>\n<h3 class=\"subheadline\">Chagrin<\/h3>\n<p class=\"paragraph\">Le batteur du tarot <strong>P\u00e9cu Cinnari<\/strong> est d\u00e9c\u00e9d\u00e9 \u00e9puis\u00e9 d&#8217;une longue maladie en 2016. Hietala en t\u00e9moigne dans le livre publi\u00e9 en 2017 <em>Antirouille<\/em>-dans sa biographie, la mort d&#8217;un membre signifie-t-elle aussi la fin de l&#8217;histoire du groupe.<\/p>\n<p class=\"paragraph\">Cinnari et Hietala ont jou\u00e9 ensemble pendant 30 ans.  Pendant longtemps, en d\u00e9marrant la production du Tarot, la premi\u00e8re chose qui m&#8217;est venue \u00e0 l&#8217;esprit a \u00e9t\u00e9 la tristesse.<\/p>\n<p class=\"paragraph\">&#8211; Ce n&#8217;est pas un bon combo.  Jouer du rock devrait \u00eatre amusant.  Maintenant que plusieurs ann\u00e9es ont pass\u00e9, nous avons r\u00e9alis\u00e9 que cela \u00e9tait possible.  Ce n\u2019\u00e9tait plus d\u00e9primant, au contraire, dit maintenant Hietala.<\/p>\n<p class=\"paragraph\">Nous avons essay\u00e9 de respecter le vieil ami en restant fid\u00e8les au groove original du groupe.<\/p>\n<p class=\"paragraph\">&#8211; Oui, cela me vient \u00e0 l&#8217;esprit, mais pas avec une telle tristesse que cela aurait un effet limitant sur ses propres activit\u00e9s.<\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/img.ilcdn.fi\/VW6tg86nSXhZQOr3hs1GrIX2TPo=\/full-fit-in\/920x0\/img-s3.ilcdn.fi\/609e0b3e35394c614efa96b3f201d25d974488d3e5a82f1737ecd42bb4d08635.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"1954\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Marko Hietala keskittyy t\u00e4ll\u00e4 hetkell\u00e4 soolouraansa.\"\/><span class=\"caption-text\" itemprop=\"description\">Marko Hietala se concentre actuellement sur sa carri\u00e8re solo.<!-- --> <\/span><span class=\"media-source\">Rosa Br\u00f6ijer<\/span><\/p>\n<\/div>\n<h3 class=\"subheadline\">Nouveau mat\u00e9riel<\/h3>\n<p class=\"paragraph\">Hietala n&#8217;exclut pas la possibilit\u00e9 d&#8217;une nouvelle production de Tarot.  Il y a des \u00e9chantillons de chansons inachev\u00e9es dans les archives qui pourraient \u00eatre travaill\u00e9es davantage.<\/p>\n<p class=\"paragraph\">Cependant, \u00e9crire des pi\u00e8ces de tarot ne semble pas indispensable \u00e0 ce stade.  Hietala se concentre sur sa carri\u00e8re solo.  Cela semblerait dr\u00f4le d\u2019essayer d\u2019\u00e9crire deux albums diff\u00e9rents en m\u00eame temps.<\/p>\n<p class=\"paragraph\">&#8211; Il faudra voir comment se d\u00e9rouleront les f\u00eates de l&#8217;\u00e9t\u00e9 prochain avec les gar\u00e7ons, pour voir s&#8217;il y aura un quelconque enthousiasme pour aller voir ces d\u00e9mos de disques durs.<\/p>\n<p class=\"paragraph\">Hietala a fond\u00e9 le groupe Tarot au d\u00e9but des ann\u00e9es 80 avec son fr\u00e8re <strong>Zachary Hi\u00e9talan<\/strong> avec.  Le dernier album studio du groupe, <em>Le sortil\u00e8ge du fer<\/em> &#8211; la sortie du 25e anniversaire de l&#8217;album a \u00e9t\u00e9 publi\u00e9e en 2011.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/viihdeuutiset\/a\/2cc78f45-d480-44b9-bb12-97159a460775\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-50<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marko Hietala pense qu&#8217;il est possible que Tarot continue \u00e0 jouer occasionnellement. C&#8217;\u00e9tait l&#8217;\u00e9t\u00e9 dernier Marko Hi\u00e9talan exceptionnel sur le plan des concerts. Apr\u00e8s une longue interruption, le groupe Tarot a fait son retour \u00e0 Kuopio lorsqu&#8217;il a \u00e9t\u00e9 invit\u00e9 \u00e0 se produire au festival Old Farts Rock, dont les b\u00e9n\u00e9fices sont revers\u00e9s \u00e0 une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1056616,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[12884,2798,4233,74,3017,157,681,114042,154,65,617,28082,2218,759,5694,1185,155,14878,364,2936,497,19665,60,44228],"class_list":["post-1056615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-24-heures","tag-chute","tag-concert","tag-dun","tag-entraine","tag-expression-artistique-et-medias","tag-groupe","tag-hietala","tag-laudio","tag-les","tag-maintenant","tag-marko","tag-membre","tag-mort","tag-musiciens-et-groupes","tag-musique","tag-musique-finlandaise","tag-pousse","tag-qui","tag-raconte","tag-revenir","tag-scenes","tag-sur","tag-tarot"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1056615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1056615"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1056615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1056616"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1056615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1056615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1056615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}