{"id":1043340,"date":"2023-12-02T13:23:13","date_gmt":"2023-12-02T15:23:13","guid":{"rendered":"https:\/\/teknomers.com\/fr\/lallemagne-est-championne-du-monde-u17-victoire-contre-la-france-alors-quelle-est-en-inferiorite-numerique\/"},"modified":"2023-12-02T13:23:17","modified_gmt":"2023-12-02T15:23:17","slug":"lallemagne-est-championne-du-monde-u17-victoire-contre-la-france-alors-quelle-est-en-inferiorite-numerique","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/lallemagne-est-championne-du-monde-u17-victoire-contre-la-france-alors-quelle-est-en-inferiorite-numerique\/","title":{"rendered":"L\u2019Allemagne est championne du monde U17 \u2013 victoire contre la France alors qu\u2019elle est en inf\u00e9riorit\u00e9 num\u00e9rique"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Titre de la premi\u00e8re <\/p>\n<p>Les footballeurs allemands U17 sont champions du monde !  L&#8217;\u00e9quipe DFB dirig\u00e9e par l&#8217;entra\u00eeneur Christian W\u00fcck a remport\u00e9 la finale contre la France aux tirs au but apr\u00e8s un match nul 2-2 dans le temps r\u00e9glementaire.  Il s&#8217;agit du premier titre de Coupe du monde dans cette tranche d&#8217;\u00e2ge pour l&#8217;Allemagne. <a rel=\"nofollow noopener\" href=\"https:\/\/fifa.fans\/3QWeIHQ\" target=\"_blank\">Les moments forts du jeu sont visibles gratuitement sur FIFA+<\/a> (<strong>Publicit\u00e9<\/strong>).<\/p>\n<p><\/p>\n<p>Les buts ont \u00e9t\u00e9 marqu\u00e9s par le talent du BVB Paris Brunner sur penalty \u00e0 la 29e minute et par Noah Darvich, pass\u00e9 du SC Fribourg au FC Barcelone pour un montant de 2,5 millions d&#8217;euros, \u00e0 la 51e minute.  Moins de deux minutes plus tard, Sa\u00efmon Bouabr\u00e9 de l&#8217;AS Monaco a marqu\u00e9 le but avant que l&#8217;Allemand Winners Osawe du RB Leipzig ne soit expuls\u00e9 d&#8217;un carton jaune-rouge \u00e0 la 69e minute.<\/p>\n<p><\/p>\n<div class=\"bbcode-newsbox newsGalerie\" data-galerie-id=\"11112\" data-galerie-titel=\"Brunner, Darvich &amp; Co.: Der deutsche U17-Kader f\u00fcr die WM in Indonesien\">\n<p><h2>Brunner, Darvich &#038; Co. : L&#8217;\u00e9quipe allemande U17 pour la Coupe du monde en Indon\u00e9sie<\/h2>\n<\/p>\n<div class=\"swiper-container news-slider\" id=\"swiper-newsGalerie\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" style=\"background-image: url(https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/paris-brunner-borussia-dortmund-u19-2023-1697699313-119828.jpg?lm=1697699323);\">\n<p>\n                        <span class=\"slider-gallery-subline\">Temp\u00eate : Paris Brunner (BVB)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/max-moerstedt-hoffenheim-2022-1698850957-120934.jpg?lm=1698850970\">\n<p>\n                        <span class=\"slider-gallery-subline\">Attaquant : Max Moerstedt (TSG Hoffenheim)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/robert-ramsak-fc-bayern-2023-1698851068-120936.jpg?lm=1698851074\">\n<p>\n                        <span class=\"slider-gallery-subline\">Attaquant : Robert Ramsak (FC Bayern)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/charles-herrmann-dfb-2023-1698850927-120933.jpg?lm=1698850938\">\n<p>\n                        <span class=\"slider-gallery-subline\">Temp\u00eate : Charles Herrmann (BVB)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/eric-da-silva-moreira-st-pauli-2023-1698850592-120921.jpg?lm=1698850598\">\n<p>\n                        <span class=\"slider-gallery-subline\">Attaquant : Eric Emanuel da Silva Moreira (FC St. Pauli)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/bilal-yalcinkaya-hamburger-sv-2023-1700050992-121908.jpg?lm=1700051009\">\n<p>\n                        <span class=\"slider-gallery-subline\">Milieu de terrain : Bilal Yalcinkaya (HSV)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/noah-darvich-fc-barcelona-23-24-1696254416-118198.jpg?lm=1696254440\">\n<p>\n                        <span class=\"slider-gallery-subline\">Milieu de terrain : Noah Darvich (FC Barcelone)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/kurt-ruger-fc-bayern-2023-1698851095-120938.jpg?lm=1698851103\">\n<p>\n                        <span class=\"slider-gallery-subline\">Milieu de terrain : Kurt R\u00fcger (FC Bayern)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/fayssal-harchaoui-1-fc-koln-2023-1698850892-120932.jpg?lm=1698850907\">\n<p>\n                        <span class=\"slider-gallery-subline\">Milieu de terrain : Fayssal Harchaoui (1. FC Cologne)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/winners-osawe-rb-leipzig-2023-1698851029-120935.jpg?lm=1698851048\">\n<p>\n                        <span class=\"slider-gallery-subline\">Milieu de terrain : Vainqueur Osawe (RB Leipzig)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/finn-jeltsch-dfb-2023-1698850733-120927.jpg?lm=1698850738\">\n<p>\n                        <span class=\"slider-gallery-subline\">Milieu de terrain : Finn Jeltsch (1. FC Nuremberg)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/david-odogu-vfl-wolfsburg-2023-1698850787-120929.jpg?lm=1698850795\">\n<p>\n                        <span class=\"slider-gallery-subline\">D\u00e9fenseur : David Odogu (VfL Wolfsburg)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/maximilian-herwerth-vfb-stuttgart-2022-1698850692-120926.jpg?lm=1698850713\">\n<p>\n                        <span class=\"slider-gallery-subline\">D\u00e9fenseur : Maximilian Herwerth (VfB Stuttgart)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/almugera-kabar-bvb-2023-1698850759-120928.jpg?lm=1698850768\">\n<p>\n                        <span class=\"slider-gallery-subline\">D\u00e9fenseur : Almugera Kabar (BVB)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/maximilian-hennig-fc-bayern-2023-1698850658-120924.jpg?lm=1698850670\">\n<p>\n                        <span class=\"slider-gallery-subline\">D\u00e9fenseur : Maximilian Hennig (FC Bayern)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/maxim-dal-mainz-2023-1698850624-120922.jpg?lm=1698850633\">\n<p>\n                        <span class=\"slider-gallery-subline\">D\u00e9fenseur : Maxim Dal (Mayence 05)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/justin-von-der-hitz-1-fc-koln-2023-1698850816-120930.jpg?lm=1698850827\">\n<p>\n                        <span class=\"slider-gallery-subline\">D\u00e9fenseur : Justin von der Hitz (1. FC K\u00f6ln)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/max-schmitt-fc-bayern-2023-1698850492-120917.jpg?lm=1698850506\">\n<p>\n                        <span class=\"slider-gallery-subline\">But : Max Schmitt (FC Bayern)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/konstantin-heide-unterhaching-2023-1698850529-120918.jpg?lm=1698850539\">\n<p>\n                        <span class=\"slider-gallery-subline\">But : Konstantin Heide (SpVgg Unterhaching)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/louis-babatz-mainz-2023-1698850558-120919.jpg?lm=1698850567\">\n<p>\n                        <span class=\"slider-gallery-subline\">But : Louis Babatz (Mayence 05)<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;copie<\/span> IMAGO<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>En cons\u00e9quence, les Fran\u00e7ais ont pris le match en main et ont accru la pression sur les talents de la DFB : \u00e0 la 85e minute, Mathis Amougou de Saint-\u00c9tienne a marqu\u00e9 l&#8217;\u00e9galisation m\u00e9rit\u00e9e.  Les dix minutes d&#8217;arr\u00eat ont cr\u00e9\u00e9 des opportunit\u00e9s pour les deux \u00e9quipes, mais la d\u00e9cision viendrait sur place.  Avec une autre meilleure fin pour la DFB.  Le h\u00e9ros des tirs au but \u00e9tait une fois de plus le gardien Konstantin Heide du SpVgg Unterhaching, qui a brill\u00e9 en demi-finale contre l&#8217;Argentine.  Heide a r\u00e9alis\u00e9 deux arr\u00eats avant qu&#8217;Almugera Kabar du BVB ne marque le penalty d\u00e9cisif.  Brunner a \u00e9galement \u00e9t\u00e9 nomm\u00e9 meilleur joueur du tournoi.<\/p>\n<p><\/p>\n<div class=\"img-news-container\">\n<div class=\"img-news\"><\/div>\n<\/p><\/div>\n<p>Le gardien Heide a r\u00e9alis\u00e9 deux arr\u00eats lors du thriller angoissant contre la France, et une autre tentative a d\u00e9pass\u00e9 le but dans la folie finale.  Apr\u00e8s deux \u00e9checs allemands, Kabar a rachet\u00e9 la F\u00e9d\u00e9ration allemande de football avec une victoire 4-3.  &#8220;Nous sommes champions d&#8217;Europe et du monde&#8221;, a d\u00e9clar\u00e9 W\u00fcck.  &#8220;Je suis incroyablement fier de pouvoir entra\u00eener cette \u00e9quipe.&#8221;<\/p>\n<p><\/p>\n<div class=\"img-news-container\">\n<div class=\"img-news\"><img loading=\"lazy\" decoding=\"async\" class=\"innews\" title=\"Konstantin Heide a enregistr\u00e9 les victoires contre la France et l'Argentine !\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/12\/1701530593_414_LAllemagne-est-championne-du-monde-U17-\u2013-victoire-contre-la.jpg\" alt=\"Konstantin Heide a enregistr\u00e9 les victoires contre la France et l'Argentine !\" width=\"503\" height=\"282\"\/><\/div>\n<p>Konstantin Heide a enregistr\u00e9 les victoires contre la France et l&#8217;Argentine !<\/p>\n<\/p><\/div>\n<p>Pas de d\u00e9faite aux Championnats d&#8217;Europe, invaincu lors de cette Coupe du Monde en Indon\u00e9sie \u2013 une g\u00e9n\u00e9ration DFB pleine d&#8217;espoir a couronn\u00e9 son histoire passionnante avec un succ\u00e8s exub\u00e9rant c\u00e9l\u00e9br\u00e9 au stade Manahan.  La s\u00e9lection du s\u00e9lectionneur national W\u00fcck a d\u00e9montr\u00e9 une performance passionn\u00e9e contre la Grande Nation et a pu une fois de plus s&#8217;appuyer sur le talent individuel.  Pour la premi\u00e8re fois, un champion d&#8217;Europe est \u00e9galement devenu champion du monde.  \u00abJ&#8217;ai dit aux gar\u00e7ons de se rendre immortels.  &#8220;C&#8217;est un sentiment de bonheur incroyable&#8221;, a d\u00e9clar\u00e9 W\u00fcck sur &#8220;RTL&#8221; apr\u00e8s le dernier match que l&#8217;\u00e9quipe a jou\u00e9 ensemble dans cette constellation.<\/p>\n<p>                        <span><\/p>\n<p>                            Vers la page d&#8217;accueil                        <\/span><br \/>\n                        <span class=\"icon-doppelpfeil-weiss\"> <\/span><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/deutschland-ist-u17-weltmeister-sieg-gegen-frankreich-nach-elfmeterschiessen\/view\/news\/430814\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Titre de la premi\u00e8re Les footballeurs allemands U17 sont champions du monde ! L&#8217;\u00e9quipe DFB dirig\u00e9e par l&#8217;entra\u00eeneur Christian W\u00fcck a remport\u00e9 la finale contre la France aux tirs au but apr\u00e8s un match nul 2-2 dans le temps r\u00e9glementaire. Il s&#8217;agit du premier titre de Coupe du monde dans cette tranche d&#8217;\u00e2ge pour l&#8217;Allemagne. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1043341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[24594,1646,27405,217614,841,154296,40,2720,69985,218180,27243,3076,218181,1056,188924,2886,121550,372,218179,24598,2559],"class_list":["post-1043340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-allemagne-u17","tag-alors","tag-championne","tag-constantin-heath","tag-contre","tag-coupe-du-monde-u17-2023","tag-est","tag-france","tag-france-u17","tag-gagnants-osawe","tag-inferiorite","tag-lallemagne","tag-mathis-amougou","tag-monde","tag-noah-darvich","tag-numerique","tag-paris-bruner","tag-quelle","tag-saimon-bouabre","tag-u17","tag-victoire"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1043340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1043340"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1043340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1043341"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1043340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1043340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1043340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}