{"id":1015413,"date":"2023-11-13T23:43:37","date_gmt":"2023-11-14T01:43:37","guid":{"rendered":"https:\/\/teknomers.com\/fr\/apres-sa-demission-a-marseille-villarreal-ramene-lentraineur-marcelino\/"},"modified":"2023-11-13T23:43:41","modified_gmt":"2023-11-14T01:43:41","slug":"apres-sa-demission-a-marseille-villarreal-ramene-lentraineur-marcelino","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/apres-sa-demission-a-marseille-villarreal-ramene-lentraineur-marcelino\/","title":{"rendered":"Apr\u00e8s sa d\u00e9mission \u00e0 Marseille : Villarreal ram\u00e8ne l&#8217;entra\u00eeneur Marcelino"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Sur un ancien lieu de travail <\/p>\n<p>Le Villarreal FC a recrut\u00e9 pour une longue dur\u00e9e son ancien entra\u00eeneur Marcelino, qui a d\u00e9missionn\u00e9 de l&#8217;Olympique de Marseille en septembre.  Lundi, les Espagnols ont annonc\u00e9 la signature du joueur de 48 ans jusqu&#8217;en 2026. Mardi, l&#8217;entra\u00eeneur, qui a \u00e9t\u00e9 actif avec l&#8217;\u00e9quipe de Castello entre 2013 et 2016, terminera son premier entra\u00eenement et se pr\u00e9sentera lors d&#8217;une conf\u00e9rence de presse.<\/p>\n<p><\/p>\n<p>A Marseille, Marcelino n&#8217;a pris la rel\u00e8ve qu&#8217;en d\u00e9but de saison, mais s&#8217;est retrouv\u00e9 dans l&#8217;incapacit\u00e9 de poursuivre son travail.  Le contexte \u00e9tait l&#8217;hostilit\u00e9 des cercles de supporters qui ont accueilli les dirigeants sportifs lors d&#8217;une r\u00e9union lundi.  On parlait d&#8217;une \u00ab guerre \u00bb qui serait men\u00e9e jusqu&#8217;\u00e0 la d\u00e9mission des responsables du club (selon le rapport des archives de TM).<\/p>\n<p><\/p>\n<p>                        <span><\/p>\n<p>                            Vers la page d&#8217;accueil                        <\/span><br \/>\n                        <span class=\"icon-doppelpfeil-weiss\"> <\/span><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/nach-rucktritt-in-marseille-trainer-marcelino-unterschreibt-erneut-bei-villarreal\/view\/news\/430150\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur un ancien lieu de travail Le Villarreal FC a recrut\u00e9 pour une longue dur\u00e9e son ancien entra\u00eeneur Marcelino, qui a d\u00e9missionn\u00e9 de l&#8217;Olympique de Marseille en septembre. Lundi, les Espagnols ont annonc\u00e9 la signature du joueur de 48 ans jusqu&#8217;en 2026. Mardi, l&#8217;entra\u00eeneur, qui a \u00e9t\u00e9 actif avec l&#8217;\u00e9quipe de Castello entre 2013 et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1015414,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[271,425,6401,1126,63087,6478,1509,1794,1897],"class_list":["post-1015413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-apres","tag-demission","tag-la-ligue","tag-lentraineur","tag-marcelino","tag-marseille","tag-ramene","tag-villarreal","tag-villarreal-fc"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1015413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1015413"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1015413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1015414"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1015413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1015413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1015413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}