{"id":1009681,"date":"2023-11-09T20:47:44","date_gmt":"2023-11-09T22:47:44","guid":{"rendered":"https:\/\/teknomers.com\/fr\/le-real-trop-fort-pour-virtus-ca-termine-100-74-pour-les-champions-deurope\/"},"modified":"2023-11-09T20:47:47","modified_gmt":"2023-11-09T22:47:47","slug":"le-real-trop-fort-pour-virtus-ca-termine-100-74-pour-les-champions-deurope","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/le-real-trop-fort-pour-virtus-ca-termine-100-74-pour-les-champions-deurope\/","title":{"rendered":"Le Real trop fort pour Virtus : \u00e7a termine 100-74 pour les champions d&#8217;Europe"},"content":{"rendered":"\n<p><h2 class=\"is-subtitle\">Les Espagnols d\u00e9samorcent l&#8217;attaque \u00e9milienne, qui paie trop de revirements et de terribles pourcentages \u00e0 trois points<\/h2>\n<\/p>\n<div>\n<p>  Trop de Real Madrid pour Virtus.  L&#8217;\u00e9quipe de Banchi, protagoniste d&#8217;un excellent d\u00e9but d&#8217;Euroligue, s&#8217;est rendue au Wizink Center devant les champions en titre.  Bologne est arriv\u00e9e au match le plus difficile apr\u00e8s cinq victoires cons\u00e9cutives, mais s&#8217;est effondr\u00e9e apr\u00e8s un premier quart-temps jou\u00e9 \u00e0 la perfection sous les coups de Campazzo et Tavares.  L&#8217;\u00e9quipe de Mateo d\u00e9samorce compl\u00e8tement l&#8217;attaque des Virtussi, qui paie les trop nombreux turnovers (12 en premi\u00e8re mi-temps, 18 en fin de match) et les terribles pourcentages \u00e0 trois points (6 sur 25).  Le score final est de 100-74, Madrid se r\u00e9v\u00e8le \u00eatre l&#8217;\u00e9quipe la plus forte et continue son invincibilit\u00e9 en Euroligue. <\/p>\n<\/div>\n<div>\n<h2 class=\"is-h5 is-inline is-uppercase\">COMMENCER NE SUFFIT PAS<\/h2>\n<p>\u2014  <\/p>\n<p> Le d\u00e9but de course de Virtus frise la perfection.  Des pourcentages en attaque tr\u00e8s \u00e9lev\u00e9s, une d\u00e9fense agressive malgr\u00e9 un Tavares difficile \u00e0 contenir, une excellente phase offensive aussi bien en transition qu&#8217;en d\u00e9fense d\u00e9ploy\u00e9e.  Cordinier et ses co\u00e9quipiers maintiennent le rythme tr\u00e8s \u00e9lev\u00e9 m\u00eame lorsque le Real multiplie les tirs, et le jeu \u00e0 trois points de Hackett \u00e0 deux secondes de la fin donne l&#8217;avantage \u00e0 Bologne 27-26 \u00e0 la premi\u00e8re sir\u00e8ne.  Tout ce que l&#8217;\u00e9quipe de Banchi avait construit de bon a \u00e9t\u00e9 litt\u00e9ralement balay\u00e9 au deuxi\u00e8me quart-temps : Campazzo a rappel\u00e9 \u00e0 tout le monde qu&#8217;il \u00e9tait l&#8217;un des meilleurs meneurs de jeu d&#8217;Europe, faisant ce qu&#8217;il voulait avec le ballon dans les mains.  16 points et 5 passes d\u00e9cisives pour l&#8217;Argentin en premi\u00e8re mi-temps (il a termin\u00e9 avec un double double, 18 plus 11), en plus des 15 de Tavares avec 5 rebonds (17 et 7 \u00e0 la fin).  Les champions d&#8217;Europe augmentent leur physique en d\u00e9fense et forcent Virtus \u00e0 effectuer 12 revirements, r\u00e9alisant une s\u00e9rie de 27-10 et prenant une avance de 53-37 \u00e0 la mi-temps.<\/p>\n<\/div>\n<div>\n<h2 class=\"is-h5 is-inline is-uppercase\">ACAD\u00c9MIE <\/h2>\n<p>\u2014  <\/p>\n<p> Deck et Musa ouvrent le feu \u00e0 partir de trois et le Real atteint le plus 20. Pour Virtus, la montagne \u00e0 gravir devient trop haute, et une s\u00e9rie de fautes et d&#8217;erreurs ralentissent le rythme du match, qui baisse d\u00e9finitivement en tirs.  Madrid, qui a l&#8217;avantage, joue avec arrogance et s&#8217;autorise un peu trop de luxe, mais l&#8217;attaque bolognaise est compl\u00e8tement d\u00e9samorc\u00e9e : le troisi\u00e8me quart-temps se termine 68-51, mais l&#8217;\u00e9quipe de Mateo d\u00e9branche trop t\u00f4t.  Belinelli est le dernier \u00e0 abandonner et ram\u00e8ne Virtus \u00e0 douze, mais Yabusele r\u00e9tablit la distance.  Au final Bologne se rend, les Merengues se sont \u00e9cart\u00e9s dans les derni\u00e8res minutes, fermant \u00e0 plus 26, avec six joueurs \u00e0 deux chiffres. <\/p>\n<\/div>\n<div>\n<p><b>Real Madrid: <\/b>Campazzo 18, Tavares 17, Yabusele 16 <br \/><b>Virtus Bologne :<\/b> Belinelli 15, Shengelia 12, Dunston 9<\/p>\n<\/div>\n<div>\n<div class=\"bck-copyright\">\n<p class=\"is-above-copyright\"><time datetime=\"2023-11-09T23:13:33+01:00\"><\/p>\n<p>            9 novembre &#8211; 23h13<br \/>\n          <\/time><\/p>\n<p class=\"is-copyright\">\u00a9 TOUS DROITS R\u00c9SERV\u00c9S<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Basket\/Eurolega\/09-11-2023\/eurolega-virtus-bologna-ko-madrid-100-74-il-real-4701612525140.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-4<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Espagnols d\u00e9samorcent l&#8217;attaque \u00e9milienne, qui paie trop de revirements et de terribles pourcentages \u00e0 trois points Trop de Real Madrid pour Virtus. L&#8217;\u00e9quipe de Banchi, protagoniste d&#8217;un excellent d\u00e9but d&#8217;Euroligue, s&#8217;est rendue au Wizink Center devant les champions en titre. Bologne est arriv\u00e9e au match le plus difficile apr\u00e8s cinq victoires cons\u00e9cutives, mais s&#8217;est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1009682,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[4772,1601,721,3144,4773,5228,65,185,1532,1527,10096,3425,2103,16386],"class_list":["post-1009681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-basket-ball","tag-ca","tag-champions","tag-deurope","tag-euroligue","tag-fort","tag-les","tag-pour","tag-real","tag-real-madrid","tag-reel","tag-termine","tag-trop","tag-virtus"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1009681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1009681"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1009681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1009682"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1009681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1009681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1009681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}