{"id":1009593,"date":"2023-11-09T19:26:41","date_gmt":"2023-11-09T21:26:41","guid":{"rendered":"https:\/\/teknomers.com\/fr\/topi-keskinen-a-acquis-un-tresor-du-jeu-europeen-cetait-ma-boutique-fifa\/"},"modified":"2023-11-09T19:26:45","modified_gmt":"2023-11-09T21:26:45","slug":"topi-keskinen-a-acquis-un-tresor-du-jeu-europeen-cetait-ma-boutique-fifa","status":"publish","type":"post","link":"https:\/\/teknomers.com\/fr\/topi-keskinen-a-acquis-un-tresor-du-jeu-europeen-cetait-ma-boutique-fifa\/","title":{"rendered":"Topi Keskinen a acquis un tr\u00e9sor du jeu europ\u00e9en : &#8220;C&#8217;\u00e9tait ma boutique Fifa&#8221;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>HJK a mis le million d\u2019\u00e9quipages dans une situation difficile.<\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:66.66666666666666%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/11\/1699565201_803_Topi-Keskinen-a-acquis-un-tresor-du-jeu-europeen.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/fr\/wp-content\/uploads\/2023\/11\/1699565201_803_Topi-Keskinen-a-acquis-un-tresor-du-jeu-europeen.jpg\"\/><meta itemprop=\"width\" content=\"2304\"\/><meta itemprop=\"height\" content=\"1536\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Topi Keskinen harmitteli hukattua maalipaikkaa. \"\/><span class=\"caption-text\" itemprop=\"description\">Topi Keskinen a regrett\u00e9 le but manqu\u00e9. <!-- --> <\/span><span class=\"media-source\">Jussi Eskola<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">Le HJK s&#8217;est lav\u00e9 le visage apr\u00e8s le squat 0-6 en Conference League.<\/p>\n<p class=\"paragraph\">La d\u00e9faite \u00e9crasante du tour pr\u00e9c\u00e9dent \u00e0 Francfort a \u00e9t\u00e9 effac\u00e9e de l&#8217;esprit lorsque le Club s&#8217;est battu \u00e0 \u00e9galit\u00e9 avec l&#8217;Eintracht sur son propre gazon synth\u00e9tique.<\/p>\n<p class=\"paragraph\">Les invit\u00e9s avaient besoin du joueur de l&#8217;\u00e9quipe nationale alg\u00e9rienne pour gagner <strong>Far\u00e8s Cha\u00efbin<\/strong> un v\u00e9ritable pari hollywoodien.  Laituri a envoy\u00e9 un canon en spirale dans le coin le plus arri\u00e8re \u00e0 la 31e minute du match.<\/p>\n<p class=\"paragraph\">Un gardien qui a excellemment jou\u00e9 <strong>Niki Maenpa\u00e4<\/strong> ne pouvait suivre la trajectoire du ballon qu&#8217;avec ses yeux.<\/p>\n<p class=\"paragraph\">&#8211; Peut-\u00eatre que vous comprenez pourquoi d&#8217;autres paient des millions pour cet objectif, d\u00e9\u00e7u <strong>Haut au milieu<\/strong> commenc\u00e9<\/p>\n<p class=\"paragraph\">&#8211; Oui, curieusement, ces grandes \u00e9quipes savent comment r\u00e9soudre ces matchs, quelle que soit la pression que nous subissons.<\/p>\n<p class=\"paragraph\">Le HJK a mis l&#8217;adversaire dans les cordes avec plusieurs budgets, quand \u00e0 la fin il a lanc\u00e9 ses attaques vers les veskari de l&#8217;\u00e9quipe nationale <strong>par Kevin Trapp<\/strong> objectif gard\u00e9.<\/p>\n<p class=\"paragraph\">Keskinen a rendu visite \u00e0 Trapp apr\u00e8s le match et lui a offert un maillot pour sa collection.<\/p>\n<p class=\"paragraph\">&#8211; C&#8217;\u00e9tait mon Fifa (jeu console) la saison derni\u00e8re.  Sacr\u00e9ment bon.<\/p>\n<h3 class=\"subheadline\">&#8220;Ridicule&#8221;<\/h3>\n<p class=\"paragraph\">Avec plus de chance, le r\u00e9sultat aurait pu se transformer en match nul, voire en victoire.  Apr\u00e8s le match, la situation dans laquelle <strong>Miro Tenho<\/strong> a dirig\u00e9 le ballon avec puissance dans le toit du but.<\/p>\n<p class=\"paragraph\"><em>L&#8217;histoire continue apr\u00e8s la photo<\/em><\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/img.ilcdn.fi\/3p_aBRYr7p7bFycubhjGb5uwGQo=\/full-fit-in\/920x0\/img-s3.ilcdn.fi\/cad1b55733bbe35d8dcd159bf2a2e495cd0374d2d76ba820c8c21a352d9db538.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2002\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Roope Riski sai kiitoksen p\u00e4\u00e4valmentaja Toni Korkeakunnakselta. \"\/><span class=\"caption-text\" itemprop=\"description\">Roope Riski a re\u00e7u un remerciement de l&#8217;entra\u00eeneur-chef Toni Korkeakunnas. <!-- --> <\/span><span class=\"media-source\">Jussi Eskola<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">arbitre fran\u00e7ais <strong>Pierre Gaillouse<\/strong> cependant, il avait r\u00e9ussi \u00e0 faire exploser le match quelques secondes auparavant.<\/p>\n<p class=\"paragraph\">La raison n\u2019a jamais \u00e9t\u00e9 d\u00e9couverte.<\/p>\n<p class=\"paragraph\">&#8211; Je ne comprends pas pourquoi il a siffl\u00e9.  C&#8217;\u00e9tait ridicule.  J&#8217;ai demand\u00e9 la raison \u00e0 l&#8217;arbitre et il voulait me donner un avertissement, entra\u00eeneur-chef <strong>Toni Korkeakunnas<\/strong> parlerait.<\/p>\n<p class=\"paragraph\">L&#8217;UEFA enregistr\u00e9 dans les minutes <strong>Hassane Banden<\/strong> une erreur, m\u00eame si au vu des ralentissements, il semble que la loi burkinab\u00e8 soit plut\u00f4t viol\u00e9e dans la situation.<\/p>\n<p class=\"paragraph\">&#8211; C&#8217;est toujours le cas lorsque nous jouons contre les grands.  Celles-ci ne sont jamais jug\u00e9es en notre faveur.  J&#8217;ai \u00e9t\u00e9 extr\u00eamement surpris que la situation n&#8217;ait m\u00eame pas \u00e9t\u00e9 v\u00e9rifi\u00e9e \u00e0 partir de la vid\u00e9o var.<\/p>\n<h3 class=\"subheadline\">&#8220;La volont\u00e9 de r\u00e9ussir&#8221;<\/h3>\n<p class=\"paragraph\">Korkeakunnas a appris apr\u00e8s le dernier match europ\u00e9en qu&#8217;un Espagnol inexp\u00e9riment\u00e9 serait engag\u00e9 pour le remplacer <strong>Ferran Sibila<\/strong>.  &#8220;Toke&#8221; peut laisser la t\u00eate haute au HJK pour son successeur.  La prestation de jeudi a \u00e9galement redonn\u00e9 de la cr\u00e9dibilit\u00e9 \u00e0 l&#8217;entra\u00eeneur.<\/p>\n<p class=\"paragraph\">\u2013 \u00c9tait-ce le premier virage o\u00f9 nous avons sauv\u00e9 deux fois sur la ligne ?  Cela a montr\u00e9 la volont\u00e9 de se battre et la capacit\u00e9 de s\u2019\u00e9tirer.  Et puis \u00e0 la fin, nous avons eu une \u00e9quipe de ce niveau pour squatter.  Nous \u00e9tions vraiment sous pression.  Ensemble, ils racontent \u00e0 quel point les gar\u00e7ons \u00e9taient charg\u00e9s aujourd&#8217;hui.<\/p>\n<p class=\"paragraph\">&#8211; Ils voulaient r\u00e9ussir.<\/p>\n<p class=\"paragraph\"><em>L&#8217;histoire continue apr\u00e8s la photo<\/em><\/p>\n<div class=\"article-image gallery center\" itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\"><meta itemprop=\"url\" content=\"https:\/\/img.ilcdn.fi\/_X7xMk8Yw9LMklWe9gQx9TaLrdY=\/full-fit-in\/920x0\/img-s3.ilcdn.fi\/eb9e619e1687eebfbc5a6257b0515b594563bc0d13f89ca39d267fc37b43c18a.jpg\"\/><meta itemprop=\"width\" content=\"2304\"\/><meta itemprop=\"height\" content=\"1536\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Hassane Band\u00e9n kasvoilta voi lukea pettymyksen. \"\/><span class=\"caption-text\" itemprop=\"description\">La d\u00e9ception se lit sur le visage de Hassane Band\u00e9. <!-- --> <\/span><span class=\"media-source\">Jussi Eskola<\/span><\/p>\n<\/div>\n<p class=\"paragraph\">La d\u00e9faite 0-1 signifiait que la saison europ\u00e9enne du HJK se terminait en phase de groupes.  L\u2019\u00e9quipe n\u2019est m\u00eame plus math\u00e9matiquement capable de se classer parmi les deux premiers du groupe.<\/p>\n<p class=\"paragraph\">Il reste encore un match \u00e0 domicile contre Aberdeen et un match \u00e0 l&#8217;ext\u00e9rieur en Gr\u00e8ce.<\/p>\n<p class=\"paragraph\">&#8211; Le PAOK est un match difficile, mais je crois que nous pouvons encore gagner cet automne.  Nous avons un assez gros match \u00e0 domicile, a soulign\u00e9 Keskinen en soulignant le gazon artificiel de la T\u00f6l\u00f6l\u00e4 Arena.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/jalkapallo\/a\/774863c7-f593-4f93-b1ad-3ee87a2af793\" rel=\"nofollow noopener\" target=\"_blank\">ttn-fr-49<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HJK a mis le million d\u2019\u00e9quipages dans une situation difficile. Topi Keskinen a regrett\u00e9 le but manqu\u00e9. Jussi Eskola Le HJK s&#8217;est lav\u00e9 le visage apr\u00e8s le squat 0-6 en Conference League. La d\u00e9faite \u00e9crasante du tour pr\u00e9c\u00e9dent \u00e0 Francfort a \u00e9t\u00e9 effac\u00e9e de l&#8217;esprit lorsque le Club s&#8217;est battu \u00e0 \u00e9galit\u00e9 avec l&#8217;Eintracht sur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1009594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[12884,33089,166,573,1168,3354,4850,91,412,17862,14983,154392,14568,77688,17697],"class_list":["post-1009593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-24-heures","tag-acquis","tag-boutique","tag-cetait","tag-europeen","tag-exercice-et-sport","tag-fifa","tag-football","tag-jeu","tag-joueurs-de-football","tag-joueurs-de-football-hommes","tag-keskinen","tag-sports-bases-sur-le-football","tag-topi","tag-tresor"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1009593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/comments?post=1009593"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/posts\/1009593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media\/1009594"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/media?parent=1009593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/categories?post=1009593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/fr\/wp-json\/wp\/v2\/tags?post=1009593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}