{"id":998158,"date":"2023-10-14T22:34:07","date_gmt":"2023-10-14T22:34:07","guid":{"rendered":"https:\/\/teknomers.com\/es\/barzagli-marchisio-y-una-velada-en-blanco-y-negro-la-juve-mania-en-el-festival-del-deporte\/"},"modified":"2023-10-14T22:34:11","modified_gmt":"2023-10-14T22:34:11","slug":"barzagli-marchisio-y-una-velada-en-blanco-y-negro-la-juve-mania-en-el-festival-del-deporte","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/barzagli-marchisio-y-una-velada-en-blanco-y-negro-la-juve-mania-en-el-festival-del-deporte\/","title":{"rendered":"Barzagli, Marchisio y una velada en blanco y negro: la Juve-man\u00eda en el Festival del Deporte"},"content":{"rendered":"\n<div>\n<p><h2 class=\"is-subtitle\">Los dos ex grandes hablaron de los muchos recuerdos de estos a\u00f1os de victorias con Conte y Allegri en el banquillo, Del Piero, Pogba, Buffon y otros campeones como compa\u00f1eros.<\/h2>\n<\/p>\n<div class=\"content not-selectable-js\">\n<p class=\"is-author\">De nuestra corresponsal Alessandra Bocci<\/p>\n<p>        <time class=\"article-date\" datetime=\"2023-10-14\" content=\"2023-10-14T23:26:00+02:00\">14 de octubre<\/p>\n<p>            <span class=\"from-location\">&#8211; TRENT<\/span><\/time><\/p>\n<\/div>\n<div class=\"content \" id=\"m6870-6869-6871\">\n<p class=\"paragraph\" spellcheck=\"true\">Una velada entre amigos que concluye con una cata de vinos que se convierte en un divertido cuestionario.  Vinos tintos y obviamente blancos, aunque el tema sea siempre Bianconeri.  Andrea Barzagli y Claudio Marchisio, por riguroso orden alfab\u00e9tico, merecieron m\u00e1s aplausos por sus recuerdos que por degustar botellas disfrazadas (Barzagli es productor y Marchisio recordaba los tiempos en que su padre lo llevaba a cosechar).  Pero el tema era obviamente su Juve, el equipo que al ganar nueve campeonatos consecutivos rompi\u00f3 r\u00e9cords anteriores.  Empezando por Conte y siguiendo por Allegri, que sum\u00f3 dos finales de Champions a sus campeonatos.  \u201cAntonio lleg\u00f3 con las ideas claras.  Con el ADN de la Juve que llevaba dentro como ex capit\u00e1n\u201d, afirma Marchisio.  Y Barzagli: &#8220;El equipo sali\u00f3 de dos s\u00e9ptimos puestos, pero hubo una serie de desacuerdos que fueron dictados por las ideas de todos, el entusiasmo y el trabajo duro que Conte nos hizo hacer. No \u00e9ramos los m\u00e1s fuertes ese a\u00f1o, pero Somos los mejores.&#8221;<\/p>\n<\/div>\n<p><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml]@ --><!--@ESI generic --><\/p>\n<div class=\"content content-paragraph \" id=\"m6894-6893-6895\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m6974-6973-6975\">LA BBC Y EL ADI\u00d3S DE ALEX<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Era la temporada del nacimiento de la BBC: Giorgio Chiellini apareci\u00f3 en pantalla en un mensaje de v\u00eddeo durante la reuni\u00f3n conducida por Fabiana Della Valle, quien pidi\u00f3 recuerdos de los distintos cambios t\u00e1cticos del equipo.  \u201cContra el Napoli Conte quer\u00eda jugar al espejo con Mazzarri.  Se le ocurri\u00f3 la idea de hacer un tr\u00edo.  Fue duro, ese partido no sali\u00f3 muy bien porque empatamos pero se cre\u00f3 la combinaci\u00f3n adecuada.  Con Buffon en la porter\u00eda\u201d, dijo Barzagli.  Y Marchisio: \u201cHubo muchos cambios importantes en ese a\u00f1o.  Tambi\u00e9n probamos el 4-2-4 y en el trofeo Berlusconi el Mil\u00e1n nos lo hizo pasar as\u00ed.  Con la llegada de Pirlo y Vidal otros cambios y una nueva solidez.  El equipo con esos tres atr\u00e1s ten\u00eda equilibrio&#8221;.  Y luego se sum\u00f3 Paul Pogba.  \u201cNos tom\u00f3 48 horas entender que \u00e9l era fuerte.  Nada m\u00e1s llegar entr\u00f3 al campo para ocupar su lugar.  A veces yo tambi\u00e9n estaba en el banquillo para dejarle jugar: Historias de la Juve, historias de la Juve.  Una velada especial fue la que combin\u00f3 las celebraciones del scudetto con la despedida de Del Piero, que Barzagli cont\u00f3 en tono de broma, a partir de un penalti que no quiso ejecutar.  \u201cUn a\u00f1o m\u00e1gico, si adem\u00e1s anotara\u2026\u201d.  Y Marchisio: \u201cNadie quer\u00eda jugar ese partido, hab\u00edamos tenido una velada el d\u00eda anterior para celebrar a Del Piero.  S\u00f3lo Del Piero y Manninger quer\u00edan jugar, nos escondimos mientras Antonio hac\u00eda la formaci\u00f3n en la pizarra.  Est\u00e1bamos celebrando el campeonato despu\u00e9s de mucho tiempo, pero todos est\u00e1bamos emocionados por la despedida de Ale.  Un momento que nunca olvidar\u00e9.&#8221;<\/p>\n<\/div>\n<div class=\"content content-paragraph \" id=\"m6915-6914-6916\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m6983-6982-6984\">campeones del dolor<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Scudetti, scudetti que vienen de serie, pero tambi\u00e9n se habl\u00f3 de las dos finales de Champions perdidas.  Barzagli: \u201cAmbos fueron dif\u00edciles de aceptar.  Una victoria en Europa habr\u00eda cerrado el c\u00edrculo.  Encontramos dos equipos m\u00e1s fuertes, muchos los recordar\u00e1n a lo largo de la historia.  El sabor amargo permanece.  Pero en esos a\u00f1os en Italia hicimos algo importante en la dificultad de demostrar siempre que \u00e9ramos los m\u00e1s fuertes.  La gran fuerza de aquella Juventus era el esp\u00edritu del club, un presidente que nunca estaba satisfecho, casi nos creamos problemas para cambiar las cosas.  Volver a ganar es lo m\u00e1s dif\u00edcil.  El ambiente nunca estuvo saciado.  Si ganas nueve a\u00f1os seguidos significa que has construido una mentalidad perfecta&#8221;.  Marchisio: \u201cSi todos vamos en la misma direcci\u00f3n, junto al talento se crean ciclos ganadores\u201d.<\/p>\n<\/div>\n<div class=\"content is-partner-link\">\n<p><a rel=\"nofollow noopener\" class=\"is-partner-link\" href=\"https:\/\/prf.hn\/click\/camref:1101l47LU\/creativeref:1101l112108\" target=\"_blank\">Mira toda la Serie A TIM y muchos otros deportes en DAZN.  Activar ahora.<\/a><\/p>\n<\/div>\n<div class=\"content content-paragraph \" id=\"m6931-6930-6932\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m6992-6991-6993\">DUSAN MEJOR QUE LA GRAN ROM<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Del pasado al presente, con una caricia de Barzagli para Vlahovic: \u201cEn perspectiva, tiene m\u00e1s que Lukaku, que es muy dif\u00edcil de marcar en este momento.  D\u00e9mosle tiempo&#8221;.  Y Marchisio tambi\u00e9n se muestra optimista sobre el futuro de la Juventus, aunque con reservas.  \u201cEl equipo no empez\u00f3 mal.  No ha encontrado su forma definitiva, pero ahora depende del estado f\u00edsico de Vlahovic y Chiesa.  Sin embargo, tambi\u00e9n ahora existen otros problemas, despu\u00e9s de los del a\u00f1o pasado.  Es cierto que la Juve tiene la piel dura, pero tenemos que hacer una limpieza total y darle una nueva cara a este equipo&#8221;.  Ni que decir tiene que del abarrotado Auditorio Santa Chiara surgieron aplausos, a\u00fan m\u00e1s fuertes si cabe.<\/p>\n<\/div>\n<div class=\"container-last-content-desktop\">\n<div class=\"content not-selectable-js\">\n<div class=\"bck-copyright\">\n<p class=\"is-above-copyright\">\n            <time datetime=\"2023-10-14T23:26:00+02:00\">14 de octubre &#8211; 23.26 h<\/time>\n        <\/p>\n<p class=\"is-copyright\">\u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/p><\/div>\n<\/div>\n<p>                                        <!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/taboola\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/taboola\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/taboola\/default.shtml]@ --><!--@ESI generic --><br \/>\n                                        <!-- include virtual=\"$SERVICE_PATH\/taboola\/default.shtml\" --><\/p>\n<p>                                        <!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;EXT_COMMENTS=xalok&amp;path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;EXT_COMMENTS=xalok&amp;path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml]@ --><!--@ESI generic --><br \/>\n                                        <!-- include virtual=\"$SSI_PATH\/components\/comments\/list\/default.shtml\" --><\/p><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/festival-sport-trento\/14-10-2023\/barzagli-marchisio-e-una-serata-tutta-bianconera-al-festival-dello-sport-e-juve-mania.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los dos ex grandes hablaron de los muchos recuerdos de estos a\u00f1os de victorias con Conte y Allegri<\/p>\n","protected":false},"author":1,"featured_media":998159,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[188733,1016,38,735,579,210199,63195,1703,158,1964],"class_list":["post-998158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-barzagli","tag-blanco","tag-del","tag-deporte","tag-festival","tag-juvemania","tag-marchisio","tag-negro","tag-una","tag-velada"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/998158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=998158"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/998158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/998159"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=998158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=998158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=998158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}