{"id":998125,"date":"2023-10-14T21:53:50","date_gmt":"2023-10-14T21:53:50","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-seleccionador-aleman-julian-nagelsmann-debuta-con-una-victoria-sobre-estados-unidos-y-dos-jugadores-del-psv\/"},"modified":"2023-10-14T21:53:54","modified_gmt":"2023-10-14T21:53:54","slug":"el-seleccionador-aleman-julian-nagelsmann-debuta-con-una-victoria-sobre-estados-unidos-y-dos-jugadores-del-psv","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-seleccionador-aleman-julian-nagelsmann-debuta-con-una-victoria-sobre-estados-unidos-y-dos-jugadores-del-psv\/","title":{"rendered":"El seleccionador alem\u00e1n Julian Nagelsmann debuta con una victoria sobre Estados Unidos y dos jugadores del PSV"},"content":{"rendered":"\n<div>\n\t\t\t\t\t\t\t\t<!-- Articles default Live football blog header --><\/p>\n<header class=\"article__header\">\n<p class=\"article__intro\">\n<p>\t\t\t\t\t\t\t\t\t\tJulian Nagelsmann ha comenzado bien su etapa como seleccionador de Alemania.  El sucesor del despedido Hansi Flick vio a su equipo ganar el s\u00e1bado un partido de pr\u00e1ctica contra Estados Unidos en East Hartford: 1-3.  En el americano participaron los jugadores del PSV Sergi\u00f1o Dest (jugador titular) y Ricardo Pepi (suplente).<\/p>\n<\/header>\n<p>\n\t<span class=\"article__source\"><br \/>\n\t\t<span itemprop=\"name\">editorial deportiva<\/span><br \/>\n\t<\/span><br \/>\n\t<time class=\"article__time\" datetime=\"14-10-23, 23:15\">14-10-23, 23:15<\/time><\/p>\n<p>\t<span class=\"article__update\"><\/p>\n<p>\t<\/span><br \/>\n\t<span class=\"article__credit\"><\/p>\n<p>\t<\/span>\n<\/p>\n<p><meta itemprop=\"datePublished\" content=\"2023-10-14T23:15:38.076+02:00\"\/><br \/>\n<span><br \/>\n\t<span><br \/>\n\t\t<meta content=\"https:\/\/statics.ad.nl\/img\/brand-logo-1c231bf304.png\"\/><br \/>\n\t\t<meta content=\"90\"\/><br \/>\n\t\t<meta content=\"90\"\/><br \/>\n\t<\/span><br \/>\n\t<meta content=\"AD\"\/><br \/>\n<\/span><\/p>\n<p>\t\t\t\t\t\t\t\t<!-- includes\/general\/sharing.html --><\/p>\n<p><!-- \/ includes\/general\/sharing.html --><\/p>\n<div class=\"article__body fjs-login-gate fjs-load-remaining-content\" data-remaining-content-url=\"\/article\/remaining-content\/~a9135487\">\n<div class=\"article-login-gate fjs-article-login-gate\">\n<p class=\"article-login-gate__title fjs-article-login-gate__title\">\n<p>\t\t\u00bfAcceso ilimitado y gratuito a Showbytes?  \u00a1Qu\u00e9 puede!\n\t<\/p>\n<p>\t<span class=\"article-login-gate__info fjs-article-login-gate__info\"><\/p>\n<p>\t\tInicia sesi\u00f3n o crea una cuenta y no te pierdas nada de las estrellas.<br \/>\n\t<\/span><\/p>\n<p class=\"article-login-gate__buttonholder\">\n<p>\t\t\t<span class=\"button__text fjs-article-login-gate__button\">S\u00ed, quiero acceso ilimitado y gratuito.<\/span><\/p>\n<\/div>\n<p>\t\t\t\t\t\t\t\t\t<!-- includes\/advertising\/fixed-slot.html --><\/p>\n<p><!-- \/ includes\/advertising\/fixed-slot.html --><\/p><\/div>\n<footer class=\"article__footer\">\n<\/footer><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ad.nl\/buitenlands-voetbal\/duitse-bondscoach-julian-nagelsmann-debuteert-met-zege-op-vs-en-twee-psvers~a9135487\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-43<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Julian Nagelsmann ha comenzado bien su etapa como seleccionador de Alemania. El sucesor del despedido Hansi Flick vio<\/p>\n","protected":false},"author":1,"featured_media":998126,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2882,99,11069,38,740,4003,3973,26205,20278,5686,4210,131,158,4004,2242],"class_list":["post-998125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-aleman","tag-con","tag-debuta","tag-del","tag-dos","tag-estados","tag-jugadores","tag-julian","tag-nagelsmann","tag-psv","tag-seleccionador","tag-sobre","tag-una","tag-unidos","tag-victoria"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/998125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=998125"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/998125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/998126"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=998125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=998125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=998125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}