{"id":1885635,"date":"2026-07-14T23:32:33","date_gmt":"2026-07-14T23:32:33","guid":{"rendered":"https:\/\/teknomers.com\/es\/atentado-de-niza-no-nos-abandonen-el-mensaje-fuerte-de-las-asociaciones-de-victimas-10-anos-despues\/"},"modified":"2026-07-14T23:32:43","modified_gmt":"2026-07-14T23:32:43","slug":"atentado-de-niza-no-nos-abandonen-el-mensaje-fuerte-de-las-asociaciones-de-victimas-10-anos-despues","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/atentado-de-niza-no-nos-abandonen-el-mensaje-fuerte-de-las-asociaciones-de-victimas-10-anos-despues\/","title":{"rendered":"Atentado de Niza: \u00abNo nos abandonen\u00bb, el mensaje fuerte de las asociaciones de v\u00edctimas 10 a\u00f1os despu\u00e9s"},"content":{"rendered":"\n<p>VALERY HACHE \/ AFP<\/p>\n<p>Emmanuel Macron, durante la ceremonia de conmemoraci\u00f3n del 10\u00ba aniversario del atentado que dej\u00f3 86 muertos y m\u00e1s de 400 heridos, en Niza, el 14 de julio de 2026.<\/p>\n<h2>Diez A\u00f1os Despu\u00e9s del Atentado en Niza<\/h2>\n<p>El 14 de julio de 2026, Niza rindi\u00f3 homenaje a las v\u00edctimas del atentado que, hace diez a\u00f1os, caus\u00f3 la muerte de 86 personas y dej\u00f3 m\u00e1s de 400 heridos en la Promenade des Anglais. Esa noche fat\u00eddica, Mohamed Lahouaiej-Bouhlel condujo un cami\u00f3n de 19 toneladas a toda velocidad, atropellando a la multitud que hab\u00eda disfrutado de los fuegos artificiales.<\/p>\n<h3>Un Desfile de Recuerdo y Controversia<\/h3>\n<p>La jornada comenz\u00f3 con un desfile republicano en la plaza Massena, un lugar tradicional para celebraciones. La presencia de Marine Le Pen, invitada por el alcalde \u00c9ric Ciotti, gener\u00f3 cr\u00edticas de la izquierda local, as\u00ed como de un editorial del diario <em>Nice-Matin<\/em> que cuestion\u00f3 su oportunismo en un d\u00eda de duelo.<\/p>\n<h2>Ceremonia Conmemorativa<\/h2>\n<p>La tarde culmin\u00f3 con una ceremonia que reuni\u00f3 a varias figuras pol\u00edticas, incluido el presidente Emmanuel Macron y sus predecesores, Fran\u00e7ois Hollande y Nicolas Sarkozy. Durante el evento, se present\u00f3 un conmovedor montaje de testimonios de personas que vivieron el atentado. 43 ni\u00f1os y 43 miembros de los servicios de emergencia depositaron ramas de olivo sobre 86 sillas azules, simbolizando a cada v\u00edctima.<\/p>\n<h3>Mensajes de Esperanza y Unidad<\/h3>\n<p>Entre los oradores estuvo St\u00e9phane Erbs, de la asociaci\u00f3n &#8216;Promenade des anges&#8217;, quien lanz\u00f3 un emotivo mensaje: <em>\u00abNo nos abandonen\u00bb<\/em>. Este llamado a la memoria y la justicia reson\u00f3 en el coraz\u00f3n de los presentes.<\/p>\n<h2>Un Homenaje Inolvidable<\/h2>\n<p>Emmanuel Macron tambi\u00e9n tom\u00f3 la palabra, recordando que las v\u00edctimas est\u00e1n <em>\u00abpara siempre en nuestra memoria colectiva\u00bb<\/em>. Reconoci\u00f3 el dolor y la p\u00e9rdida, destacando que, aunque el 14 de julio de 2016 nunca tendr\u00e1 sentido, debemos dar significado a los d\u00edas que han seguido, promoviendo la memoria, la justicia y la fraternidad.<\/p>\n<h3>Frente a la Amenaza del Terrorismo<\/h3>\n<p>El presidente subray\u00f3 que Niza ha sido v\u00edctima de otros atentados en los \u00faltimos a\u00f1os, todos bajo la misma ideolog\u00eda extremista que busca dividir y sembrar el miedo. A pesar de estos ataques, Niza ha mostrado unidad y resiliencia, protegiendo a todos sus ciudadanos, independientemente de su religi\u00f3n.<\/p>\n<h2>Recordando a las V\u00edctimas<\/h2>\n<p>La velada culmin\u00f3 con un espect\u00e1culo de 2016 drones en el cielo, simbolizando la dignidad y la unidad. Tambi\u00e9n se iluminaron 86 haces de luz azules a las 22:34, la hora en que se detuvo el cami\u00f3n asesino.<\/p>\n<p>Este acto de conmemoraci\u00f3n no s\u00f3lo recuerda el dolor, sino que tambi\u00e9n celebra la fortaleza y resistencia de una comunidad unida frente al terrorismo. El mensaje de <em>\u00abno nos abandonen\u00bb<\/em> resuena en cada coraz\u00f3n, recordando que la memoria y la justicia son fundamentales para seguir adelante.<\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/teknomers.com\/es\/category\/general\/\" rel=\"dofollow\">General<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VALERY HACHE \/ AFP Emmanuel Macron, durante la ceremonia de conmemoraci\u00f3n del 10\u00ba aniversario del atentado que dej\u00f3<\/p>\n","protected":false},"author":1,"featured_media":1885636,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[10146,205,5350,4914,420979,755,38214,453,314531,246,2078,47397,2245,2300,435557,1759],"class_list":["post-1885635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-abandonen","tag-anos","tag-asociaciones","tag-atentado","tag-attentat-de-nice","tag-despues","tag-france","tag-fuerte","tag-hommage","tag-las","tag-mensaje","tag-nice","tag-niza","tag-nos","tag-promenade-des-anglais","tag-victimas"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1885635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1885635"}],"version-history":[{"count":1,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1885635\/revisions"}],"predecessor-version":[{"id":1885637,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1885635\/revisions\/1885637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1885636"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1885635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1885635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1885635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}