{"id":1464703,"date":"2024-11-30T12:00:37","date_gmt":"2024-11-30T12:00:37","guid":{"rendered":"https:\/\/teknomers.com\/es\/janique-vive-justo-al-lado-del-campo-de-lirios-y-esta-muy-preocupada-por-la-cantidad-de-veneno-agricola\/"},"modified":"2024-11-30T12:00:43","modified_gmt":"2024-11-30T12:00:43","slug":"janique-vive-justo-al-lado-del-campo-de-lirios-y-esta-muy-preocupada-por-la-cantidad-de-veneno-agricola","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/janique-vive-justo-al-lado-del-campo-de-lirios-y-esta-muy-preocupada-por-la-cantidad-de-veneno-agricola\/","title":{"rendered":"Janique vive justo al lado del campo de lirios y est\u00e1 muy preocupada por la cantidad de veneno agr\u00edcola."},"content":{"rendered":"\n<p>La preocupaci\u00f3n es grande entre la gente que vive en el distrito de Stokhoek en Sint-Michielsgestel, justo al lado de un campo donde se cultivan bulbos de lirio. Para ello se utiliza mucho veneno agr\u00edcola. La ministra de Agricultura, Wiersma, prometi\u00f3 esta semana que investigar\u00e1 si son necesarias &#8220;zonas libres de fumigaciones&#8221;. Pero los residentes no tienen mucha confianza en esto de antemano.<\/p>\n<div>\n<p>Una de esas residentes es Janique Huijbregts. El domingo ser\u00e1 invitada al programa de entrevistas KRAAK. de Omroep Brabante. Vive a cien metros del campo de lirios. Este verano estuvo en el interior a 28 grados porque la GGD aconseja mantener las ventanas y puertas cerradas al fumigar. <\/p>\n<p>Y hay mucha fumigaci\u00f3n. El cultivo de bulbos de lirio requiere muchos m\u00e1s pesticidas que, por ejemplo, el ma\u00edz o las patatas: aproximadamente 140 kilos por hect\u00e1rea. <\/p>\n<p><strong>Antigua tierra de ma\u00edz utilizada para el cultivo de lirios <\/strong><br \/>En los \u00faltimos a\u00f1os, el n\u00famero de hect\u00e1reas de cultivo de lirios en Brabante ha ido creciendo constantemente y actualmente se estima en unas 1.000 hect\u00e1reas. El cultivo es intensivo gracias a las frecuentes fumigaciones, pero con los bulbos tambi\u00e9n se gana mucho dinero. Impulsada por la disminuci\u00f3n de la ganader\u00eda, gran parte de la tierra dedicada al cultivo de ma\u00edz se utiliza ahora para el cultivo de lirios.  <\/p>\n<p>En todos los Pa\u00edses Bajos existe preocupaci\u00f3n por los kilos de veneno necesarios para el cultivo. Faltan pruebas cient\u00edficas s\u00f3lidas, pero existen sospechas de que este veneno puede provocar enfermedades como el Parkinson, el Alzheimer y la ELA en humanos. Janique cuenta en KRAAK. que en una casa cercana a ella se encontraron residuos de once pesticidas diferentes. <\/p>\n<p><strong>Supervisi\u00f3n por experto <\/strong><br \/>Este verano, un grupo de cuarenta personas intent\u00f3 detener al cultivador de lirios. Pero el juez no pudo hacer nada porque cumpli\u00f3 con los requisitos legales. Se acord\u00f3 que un experto controlar\u00e1 por parte de los residentes qu\u00e9 productos se roc\u00edan. <\/p>\n<p>En m\u00e1s lugares del pa\u00eds, el cultivo de lirios provoca conflictos. La provincia de Brabante no ha concedido permiso para cultivar tierras que alquila desde hace alg\u00fan tiempo. A principios de este mes se adopt\u00f3 una moci\u00f3n del SP para investigar si es posible una prohibici\u00f3n total. <\/p>\n<p>Este malestar tambi\u00e9n ha llegado a La Haya. Los partidos de izquierda como PvdA-GroenLinks preferir\u00edan prohibir completamente el cultivo de lirios. Por lo tanto, el Ministro Wiersma se limita por el momento a realizar un estudio sobre las zonas libres de fumigaciones. <\/p>\n<p>Los habitantes de Sint-Michielsgestel tienen una ventaja: despu\u00e9s de este cultivo se liberan temporalmente de los lirios, ya que el suelo debe recuperarse durante siete a\u00f1os despu\u00e9s de la cosecha. &#8220;Pero, por supuesto, los productores empezar\u00e1n a buscar nuevos lugares&#8221;, afirma Janique Huijbregts. <\/p>\n<p><strong>M\u00e1s adelante en Kraak.:<\/strong><br \/>El presidente de la junta directiva, Jos Kusters, de Ons Middelbaar Onderwijs (OMO), sobre el endurecimiento de la pol\u00edtica en La Haya. \u00c9l ve c\u00f3mo esto tambi\u00e9n tiene un impacto en las aulas. Escribi\u00f3 una carta abierta al Primer Ministro Dick Schoof en la que le pide que asuma su responsabilidad. <\/p>\n<p>Y: Koen Frijns y Ruben den Brok forman el d\u00fao teatral Frino de Eindhoven. El verano pasado actuaron en el festival de teatro Parade con su espect\u00e1culo absurdo &#8216;Opteffen&#8217;. A finales de octubre ganaron con su Brabohop el premio de incentivo del municipio de Eindhoven.<\/p>\n<p>GRIETA. Se transmite en vivo todos los domingos a las 12 del mediod\u00eda y luego se repite. El programa tambi\u00e9n puede verse a trav\u00e9s de Brabant+. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.omroepbrabant.nl\/nieuws\/4601314\/janique-woont-pal-naast-lelieveld-grote-zorgen-om-hoeveelheid-landbouwgif\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-32<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La preocupaci\u00f3n es grande entre la gente que vive en el distrito de Stokhoek en Sint-Michielsgestel, justo al<\/p>\n","protected":false},"author":1,"featured_media":1464704,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3913,26756,3525,7130,38,97,265559,5018,1633,22865,1390,231,8445,26366,1384],"class_list":["post-1464703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-agricola","tag-agricultura-y-ganaderia","tag-campo","tag-cantidad","tag-del","tag-esta","tag-janique","tag-justo","tag-lado","tag-lirios","tag-muy","tag-por","tag-preocupada","tag-veneno","tag-vive"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1464703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1464703"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1464703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1464704"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1464703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1464703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1464703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}