{"id":1439673,"date":"2024-11-13T23:53:28","date_gmt":"2024-11-13T23:53:28","guid":{"rendered":"https:\/\/teknomers.com\/es\/jordan-klepper-no-pudo-ocultar-su-sorpresa-ante-quien-eligio-donald-trump-para-ser-secretario-de-seguridad-nacional\/"},"modified":"2024-11-13T23:53:33","modified_gmt":"2024-11-13T23:53:33","slug":"jordan-klepper-no-pudo-ocultar-su-sorpresa-ante-quien-eligio-donald-trump-para-ser-secretario-de-seguridad-nacional","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/jordan-klepper-no-pudo-ocultar-su-sorpresa-ante-quien-eligio-donald-trump-para-ser-secretario-de-seguridad-nacional\/","title":{"rendered":"Jordan Klepper no pudo ocultar su sorpresa ante qui\u00e9n eligi\u00f3 Donald Trump para ser secretario de Seguridad Nacional"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div data-module=\"subbuzz-text\">\n<p>&#8220;\u00bfEst\u00e1s bromeando?&#8221; Klepper dijo con incredulidad. \u201cSe supone que ella debe controlar la frontera. Ni siquiera pod\u00eda entrenar a su perro\u201d. <\/p>\n<p>Noem comparti\u00f3 en su libro publicado a principios de este a\u00f1o que le dispar\u00f3 a su perro de 14 meses, Cricket, en un pozo de grava porque sent\u00eda que el cachorro era \u201cmenos que in\u00fatil\u201d e \u201cincapaz de entrenar\u201d.  <\/p>\n<p>El gobernador de Dakota del Sur no es la \u00fanica elecci\u00f3n cuestionable de Trump. Klepper mostr\u00f3 a los dem\u00e1s y luego revel\u00f3 lo que tienen en com\u00fan con los videos de cada uno ofreciendo elogios exagerados al presidente electo. <\/p>\n<p>&#8220;Estas personas le est\u00e1n besando el trasero a Trump con tanta fuerza que tienen bronceador en la nariz&#8221;, dijo. \u201cY s\u00ed, se lo pone ah\u00ed abajo\u201d. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.buzzfeed.com\/edmazza\/jordan-klepper-donald-trump-kristi-noem\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-65<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u00bfEst\u00e1s bromeando?&#8221; Klepper dijo con incredulidad. \u201cSe supone que ella debe controlar la frontera. Ni siquiera pod\u00eda entrenar<\/p>\n","protected":false},"author":1,"featured_media":1439674,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[596,242,7654,235774,20914,249973,1647,212988,20874,54533,18,4066,1321,1232,3128,42,1067,6444,3669,243],"class_list":["post-1439673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-ante","tag-donald","tag-eligio","tag-huffpost-sindicado","tag-jordan","tag-klepper","tag-nacional","tag-noticias-de-tendencia","tag-ocultar","tag-oportuno","tag-para","tag-programas-de-television","tag-pudo","tag-quien","tag-secretario","tag-seguridad","tag-ser","tag-sorpresa","tag-televisor","tag-trump"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1439673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1439673"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1439673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1439674"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1439673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1439673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1439673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}