{"id":1432821,"date":"2024-11-09T02:47:31","date_gmt":"2024-11-09T02:47:31","guid":{"rendered":"https:\/\/teknomers.com\/es\/carlo-ancelotti-hablo-antes-del-partido-contra-osasuna-para-empezar-por-endrick-o-arda\/"},"modified":"2024-11-09T02:47:39","modified_gmt":"2024-11-09T02:47:39","slug":"carlo-ancelotti-hablo-antes-del-partido-contra-osasuna-para-empezar-por-endrick-o-arda","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/carlo-ancelotti-hablo-antes-del-partido-contra-osasuna-para-empezar-por-endrick-o-arda\/","title":{"rendered":"Carlo Ancelotti habl\u00f3 antes del partido contra Osasuna: Para empezar por Endrick o Arda&#8230;"},"content":{"rendered":"\n<div id=\"\">&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>Ancelotti compareci\u00f3 en rueda de prensa antes del partido de ma\u00f1ana ante Osasuna en casa en la jornada 13 de LaLiga.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El t\u00e9cnico italiano afirm\u00f3 que todos en el Real Madrid, incluido el club, cuerpo t\u00e9cnico y jugadores, est\u00e1n desmoralizados tras perder los dos \u00faltimos partidos de Liga y Champions, pero cree que han encontrado una soluci\u00f3n para salir de esta situaci\u00f3n. .<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Al se\u00f1alar que espera que el equipo muestre la reacci\u00f3n necesaria en el campo ma\u00f1ana, Ancelotti dijo: &#8220;Siempre dije que encontr\u00e9 la soluci\u00f3n, lo pens\u00e1bamos, pero qued\u00f3 en la teor\u00eda. Tenemos que demostrarlo tambi\u00e9n en la pr\u00e1ctica&#8221;. &#8220;El equipo es consciente de lo que est\u00e1 pasando. El problema ha sido identificado, est\u00e1 muy claro y quiero ver la reacci\u00f3n en el campo ma\u00f1ana&#8221;. dijo.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Respondiendo a una pregunta sobre el nuevo fichaje del Real Madrid del futbolista brasile\u00f1o Endrick, de 18 a\u00f1os, que no ha jugado en los \u00faltimos 5 partidos, Ancelotti subray\u00f3 que el futbolista nacional Arda G\u00fcler se encuentra en la misma situaci\u00f3n y utiliz\u00f3 las siguientes declaraciones:<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#8220;Creo que Endrick est\u00e1 listo para jugar entre los primeros 11. Lo est\u00e1 haciendo muy bien. Nos muestra su calidad en los entrenamientos. Lo mismo tengo que decir de Arda. Ambos son jugadores j\u00f3venes y crean presi\u00f3n dentro del equipo. Sin embargo , nuestra prioridad es salir de la situaci\u00f3n actual lo m\u00e1s r\u00e1pido posible, si Endrick o empezar con Arda, creo que s\u00ed, es posible, pero d\u00e9jame decirlo una vez m\u00e1s, nuestra prioridad no es darle m\u00e1s tiempo a eso o. Ese futbolista.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Destacando que todos en el equipo est\u00e1n en el mismo barco, que los jugadores saben lo que tienen que hacer, que son como una familia, Ancelotti dijo sobre los problemas vividos en defensa: &#8220;Sacrificio, concentraci\u00f3n y trabajo colectivo. El sacrificio es necesario para Para ser un equipo compacto, es necesaria concentraci\u00f3n para estar en el lugar correcto y en el momento correcto, colectivo &#8220;El juego es necesario para defender juntos. Lo hicimos la temporada pasada y podemos hacerlo ahora&#8221;. hizo su valoraci\u00f3n.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#8220;Ahora es el momento de demostrarlo en el campo, no s\u00f3lo hablar, sino actuar&#8221;. Dijo Ancelotti, y se\u00f1al\u00f3 que aunque est\u00e1n un poco atrasados \u200b\u200bcon las derrotas, tienen plena fe en luchar por la Liga y el campeonato de Champions.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Ancelotti respondi\u00f3 a las preguntas sobre el futbolista franc\u00e9s Kylian Mbapp\u00e9, que lleg\u00f3 como gran fichaje antes de la temporada pero que hasta ahora no ha mostrado el rendimiento esperado: &#8220;Est\u00e1 bien en los entrenamientos. Est\u00e1 pasando por un per\u00edodo dif\u00edcil como todos los dem\u00e1s. El problema que est\u00e1 viviendo es un problema de todos. No podemos alcanzar nuestra mejor versi\u00f3n. Esto es dif\u00edcil&#8221;. Creo que superar\u00e1 el proceso. Puedo decir lo mismo de Vinicius, Rodrygo y Bellingham. Este es un momento dif\u00edcil para todos. Tenemos que aceptar eso en tiempos de derrota. &#8220;No puedes doblarte. Al contrario, debes mantenerte erguido. Ahora estamos m\u00e1s unidos que nunca&#8221;. respondi\u00f3.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El Real Madrid (24 puntos), que est\u00e1 a 9 puntos del l\u00edder Barcelona (33 puntos) en La Liga a falta de un partido para el final, se enfrentar\u00e1 ma\u00f1ana a las 16:00 horas en el estadio Santiago Bernab\u00e9u al quinto clasificado Osasuna (21 puntos).<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n                <\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.fotomac.com.tr\/ispanyalaliga\/2024\/11\/08\/carlo-ancelotti-osasuna-maci-oncesi-konustu-endrick-veya-arda-ile-baslamak-gerekirse\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-7<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#13; &#13; &#13; Ancelotti compareci\u00f3 en rueda de prensa antes del partido de ma\u00f1ana ante Osasuna en casa<\/p>\n","protected":false},"author":1,"featured_media":1432822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[7070,899,2297,6053,5477,205927,110,38,1220,122640,262146,3249,7260,4335,297,20146,208977,18,475,231,1288],"class_list":["post-1432821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-ancelotti","tag-antes","tag-arda","tag-arda-guler","tag-carlo","tag-carlo-ancelot","tag-contra","tag-del","tag-empezar","tag-endrick","tag-endrick-felipe","tag-hablo","tag-kylian-mbappe","tag-la-liga","tag-liga-de-campeones","tag-osasuna","tag-osaun","tag-para","tag-partido","tag-por","tag-real-madrid"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1432821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1432821"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1432821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1432822"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1432821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1432821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1432821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}