{"id":1432536,"date":"2024-11-08T21:55:32","date_gmt":"2024-11-08T21:55:32","guid":{"rendered":"https:\/\/teknomers.com\/es\/estados-unidos-alega-que-un-irani-fue-contratado-para-planear-el-asesinato-de-trump\/"},"modified":"2024-11-08T21:55:37","modified_gmt":"2024-11-08T21:55:37","slug":"estados-unidos-alega-que-un-irani-fue-contratado-para-planear-el-asesinato-de-trump","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/estados-unidos-alega-que-un-irani-fue-contratado-para-planear-el-asesinato-de-trump\/","title":{"rendered":"Estados Unidos alega que un iran\u00ed fue contratado para planear el asesinato de Trump"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Desbloquee el bolet\u00edn White House Watch de forma gratuita<\/p>\n<p class=\"article__content-sign-up-topic-description\">Su gu\u00eda sobre lo que significan las elecciones estadounidenses de 2024 para Washington y el mundo<\/p>\n<p><iframe class=\"article__content-sign-up-iframe close\" scrolling=\"no\" id=\"signUpIframe\" data-prev-url=\"\/register\/in-article-sign-up?ft-content-uuid=5580f4f2-9808-4488-9c0b-da730396d452&amp;newsletter-id=65b8fec772badb00166eafc6\"><\/iframe><\/div>\n<div id=\"article-body\">\n<p>Fiscales estadounidenses acusaron el viernes al gobierno de Ir\u00e1n de contratar a un hombre para poner en marcha complots para asesinar a supuestos enemigos del r\u00e9gimen, incluido el presidente electo Donald Trump. <\/p>\n<p>En septiembre, el Cuerpo de la Guardia Revolucionaria Isl\u00e1mica orden\u00f3 a Farhad Shakeri, uno de sus activos, que vigilara a Trump y elaborara un plan para matarlo, seg\u00fan un documento no sellado. <a rel=\"nofollow noopener\" href=\"https:\/\/www.justice.gov\/opa\/media\/1376516\/dl\" data-trackable=\"link\" target=\"_blank\">denuncia penal<\/a> el viernes. Dijo que en una reuni\u00f3n a principios de octubre le dijeron que presentara un plan de asesinato en un plazo de siete d\u00edas; de lo contrario, el intento tendr\u00eda que esperar hasta despu\u00e9s de las elecciones, que supon\u00edan que perder\u00eda.<\/p>\n<p>Shakeri, que es iran\u00ed, dijo al FBI en una entrevista que no ten\u00eda intenci\u00f3n de hacerlo, seg\u00fan documentos judiciales. <\/p>\n<p>Shakeri, que sigue pr\u00f3fugo y se cree que se encuentra en Ir\u00e1n, fue acusado de asesinato a sueldo junto con dos presuntos c\u00f3mplices (ambos de Nueva York) en relaci\u00f3n con un plan dirigido a otro ciudadano estadounidense de origen iran\u00ed que se opone a la rep\u00fablica isl\u00e1mica. Los dos coacusados \u200b\u200bde Shakeri comparecieron por primera vez ante el tribunal en Manhattan el jueves y fueron detenidos en espera de juicio.<\/p>\n<p>&#8220;Hay pocos actores en el mundo que representen una amenaza tan grave para la seguridad nacional de Estados Unidos como lo hace Ir\u00e1n&#8221;, dijo el fiscal general de Estados Unidos, Merrick Garland.<\/p>\n<p>A principios de este a\u00f1o, funcionarios estadounidenses recibieron informaci\u00f3n sobre una amenaza iran\u00ed a Trump, lo que llev\u00f3 al Servicio Secreto a aumentar la seguridad a su alrededor. <\/p>\n<p>La campa\u00f1a presidencial de 2024, que culmin\u00f3 con la victoria electoral de Trump el martes, se ha visto empa\u00f1ada por amenazas e incidentes de violencia, as\u00ed como por esfuerzos de gobiernos extranjeros, incluidos Ir\u00e1n y Rusia, para interferir con la votaci\u00f3n. <\/p>\n<p>Trump enfrent\u00f3 dos atentados fallidos contra su vida durante la campa\u00f1a, y amenazas de bomba que parec\u00edan provenir de dominios de correo electr\u00f3nico rusos interrumpieron brevemente la votaci\u00f3n en algunos distritos electorales en estados cruciales. <\/p>\n<p>El director del FBI, Christopher Wray, dijo: \u201cLos cargos anunciados hoy exponen los continuos y descarados intentos de Ir\u00e1n de atacar a ciudadanos estadounidenses, incluido el presidente electo Donald Trump, otros l\u00edderes gubernamentales y disidentes que critican el r\u00e9gimen de Teher\u00e1n\u201d.<\/p>\n<p>La campa\u00f1a de Trump no respondi\u00f3 de inmediato a una solicitud de comentarios. La misi\u00f3n de Ir\u00e1n ante la ONU declin\u00f3 hacer comentarios.<\/p>\n<p>Cuando se le pidi\u00f3 que se concentrara en asesinar a Trump, Shakeri le dijo a un funcionario del IRGC que costar\u00eda una \u201cenorme\u201d cantidad de dinero, a lo que el oficial respondi\u00f3: \u201cya hemos gastado mucho dinero. . .[s]o el dinero no es un problema\u201d, seg\u00fan la denuncia.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/5580f4f2-9808-4488-9c0b-da730396d452\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desbloquee el bolet\u00edn White House Watch de forma gratuita Su gu\u00eda sobre lo que significan las elecciones estadounidenses<\/p>\n","protected":false},"author":1,"featured_media":1432537,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[86579,1319,24583,4003,244,7691,18,49208,243,4004],"class_list":["post-1432536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-alega","tag-asesinato","tag-contratado","tag-estados","tag-fue","tag-irani","tag-para","tag-planear","tag-trump","tag-unidos"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1432536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1432536"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1432536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1432537"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1432536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1432536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1432536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}