{"id":1432533,"date":"2024-11-08T21:54:31","date_gmt":"2024-11-08T21:54:31","guid":{"rendered":"https:\/\/teknomers.com\/es\/yibbi-jansen-mejor-jugador-del-mundo-jeroen-delmee-mejor-entrenador\/"},"modified":"2024-11-08T21:54:36","modified_gmt":"2024-11-08T21:54:36","slug":"yibbi-jansen-mejor-jugador-del-mundo-jeroen-delmee-mejor-entrenador","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/yibbi-jansen-mejor-jugador-del-mundo-jeroen-delmee-mejor-entrenador\/","title":{"rendered":"Yibbi Jansen mejor jugador del mundo; Jeroen Delm\u00e9e mejor entrenador"},"content":{"rendered":"\n<p>Yibbi Jansen de Gemonde ha sido nombrado el mejor jugador de hockey del mundo. Y Jeroen Delm\u00e9e de Boxtel fue elegido mejor entrenador del mundo. Ambos debieron su elecci\u00f3n al oro ol\u00edmpico del verano pasado en Par\u00eds. As\u00ed lo anunci\u00f3 la Federaci\u00f3n Internacional de Hockey (FIH) el viernes por la noche durante una gala en el estado asi\u00e1tico de Om\u00e1n.<\/p>\n<div>\n<p>Yibbi Jansen tiene 24 a\u00f1os y viene de Gemonde. En junio gan\u00f3 la Pro League con la selecci\u00f3n holandesa y el oro en los Juegos Ol\u00edmpicos en agosto. Yibbi es hija de Ronald Jansen, quien tuvo mucho \u00e9xito como portero de hockey. La jugadora, que comenz\u00f3 su carrera en Den Bosch, este a\u00f1o impresion\u00f3 principalmente como especialista en corner corto.<\/p>\n<p>La atacante del SCHC debut\u00f3 con la selecci\u00f3n holandesa en enero de 2018 durante un partido contra Estados Unidos. Holanda gan\u00f3 7-2 y Yibbi anot\u00f3 inmediatamente. En los m\u00e1s de ochenta partidos internacionales que ha disputado desde entonces, ya ha marcado 71 goles. En la final ol\u00edmpica logr\u00f3 el importante 1-1, tras el cual gan\u00f3 el equipo del seleccionador nacional Paul van Ass. <em>tiroteos<\/em> tom\u00f3 oro. Yibbi se convirti\u00f3 en el m\u00e1ximo goleador del torneo en la capital francesa con nueve goles. En la Pro League marc\u00f3 diecinueve goles.<\/p>\n<p><strong>LEA TAMBI\u00c9N:<\/strong>  El protagonismo de Brabante en el oro del hockey: Yibbi Jansen anot\u00f3 el empate<\/p>\n<p>La precedieron Lidewij Welten, Maartje Paumen, Minke Booij y Mijntje Donners, entre otros.<\/p>\n<p>Yibbi pronto partir\u00e1 hacia la India para participar en la Hockey India League (HIL). El jugador de hockey fue subastado por m\u00e1s de treinta mil euros. Esto convierte al mejor jugador de hockey en el no indio mejor pagado de todos los jugadores de hockey de la competici\u00f3n india.<\/p>\n<p><strong>LEA TAMBI\u00c9N:<\/strong>  La estrella del hockey Yibbi Jansen subastada por una cantidad considerable en India<\/p>\n<p>Jeroen Delm\u00e9e (51) llev\u00f3 al equipo masculino holand\u00e9s al premio principal en los Juegos de Verano. Se convirti\u00f3 en el primer holand\u00e9s en ganar el oro ol\u00edmpico como jugador (1996 y 2000) y como entrenador. Delm\u00e9e jug\u00f3 activamente como jugadora en Tilburg, Den Bosch y Oranje Zwart. <\/p>\n<p>Fue seleccionador nacional de B\u00e9lgica y Francia antes de ser nombrado por la Real Asociaci\u00f3n Holandesa de Hockey. El a\u00f1o pasado se proclam\u00f3 campe\u00f3n de Europa y llev\u00f3 al equipo al bronce en el Mundial.<\/p>\n<p>Para la categor\u00eda masculina fue Joep de Mol, de Berkel-Enschot, uno de los pilares de Delm\u00e9e. Sin embargo, no obtuvo el t\u00edtulo.<\/p>\n<p><strong>TAMBI\u00c9N TE PUEDE ENCONTRAR ESTO INTERESANTE:<\/strong><\/p>\n<p>  La medalla dorada de hockey calma la resaca de Jeroen Delmee al levantarse<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.omroepbrabant.nl\/nieuws\/4588238\/yibbi-jansen-beste-speelster-van-de-wereld-jeroen-delmee-beste-coach\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-32<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yibbi Jansen de Gemonde ha sido nombrado el mejor jugador de hockey del mundo. Y Jeroen Delm\u00e9e de<\/p>\n","protected":false},"author":1,"featured_media":1432534,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[38,123663,735,752,14594,12441,2783,1927,340,244799],"class_list":["post-1432533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-del","tag-delmee","tag-deporte","tag-entrenador","tag-jansen","tag-jeroen","tag-jugador","tag-mejor","tag-mundo","tag-yibbi"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1432533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1432533"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1432533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1432534"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1432533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1432533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1432533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}