{"id":1422529,"date":"2024-11-01T14:24:38","date_gmt":"2024-11-01T14:24:38","guid":{"rendered":"https:\/\/teknomers.com\/es\/holanda-septentrional-encuentra-refugio-para-10-000-solicitantes-de-asilo-se-necesitan-mas\/"},"modified":"2024-11-01T14:24:44","modified_gmt":"2024-11-01T14:24:44","slug":"holanda-septentrional-encuentra-refugio-para-10-000-solicitantes-de-asilo-se-necesitan-mas","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/holanda-septentrional-encuentra-refugio-para-10-000-solicitantes-de-asilo-se-necesitan-mas\/","title":{"rendered":"Holanda Septentrional encuentra refugio para 10.000 solicitantes de asilo; se necesitan m\u00e1s"},"content":{"rendered":"\n<div>\n<p>Muchos municipios indican que a\u00fan no saben d\u00f3nde recibir\u00e1n a los solicitantes de asilo. Esto afecta, por ejemplo, a una gran parte de los municipios de Frisia occidental. Por ejemplo, el municipio de Enkhuizen dice que tiene un lugar en mente, pero no informar\u00e1 al consejo municipal d\u00f3nde est\u00e1 ese lugar hasta mediados de diciembre. <\/p>\n<h3>2. \u00bfSeguir\u00e1 existiendo una ley de reparto para arrestar a los municipios?<\/h3>\n<p>La ley de distribuci\u00f3n est\u00e1 en peligro. La ministra de Asilo y Migraci\u00f3n del PVV, Faber, ya ha indicado varias veces que le gustar\u00eda deshacerse de \u00e9l lo antes posible. En los informes publicados hoy, los comisionados del Rey le pidieron conjuntamente que mantuviera la ley hasta que existiera una alternativa para distribuir a los solicitantes de asilo por todo el pa\u00eds. <\/p>\n<p>Al mismo tiempo, las provincias necesitan que el gabinete haga cumplir las normas. Ellos mismos no tienen capacidad para imponer coerci\u00f3n a los municipios. <\/p>\n<h3>3. \u00bfQu\u00e9 municipios no cumplen la meta? <\/h3>\n<p>Zandvoort se fue <strong>el verano pasado<\/strong> Ya sabemos que no quiere conseguir plazas mientras la ley de distribuci\u00f3n est\u00e9 en la mira. El informe de hoy confirma esta imagen: Zandvoort s\u00f3lo crear\u00e1 refugios si el gabinete cambia de opini\u00f3n y dice que quiere continuar con la ley de dispersi\u00f3n. Hasta entonces, el municipio no har\u00e1 nada.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nhnieuws.nl\/nieuws\/342271\/noord-holland-vindt-onderdak-voor-10000-asielzoekers-meer-nodig\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-55<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchos municipios indican que a\u00fan no saben d\u00f3nde recibir\u00e1n a los solicitantes de asilo. Esto afecta, por ejemplo,<\/p>\n","protected":false},"author":1,"featured_media":1422530,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[9492,5194,2463,16,5452,18,11073,6164,19396],"class_list":["post-1422529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-asilo","tag-encuentra","tag-holanda","tag-mas","tag-necesitan","tag-para","tag-refugio","tag-septentrional","tag-solicitantes"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1422529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1422529"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1422529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1422530"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1422529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1422529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1422529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}