{"id":1418123,"date":"2024-10-29T16:03:04","date_gmt":"2024-10-29T16:03:04","guid":{"rendered":"https:\/\/teknomers.com\/es\/muere-la-estrella-del-culturismo-johanna-perez-de-35-anos\/"},"modified":"2024-10-29T16:03:09","modified_gmt":"2024-10-29T16:03:09","slug":"muere-la-estrella-del-culturismo-johanna-perez-de-35-anos","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/muere-la-estrella-del-culturismo-johanna-perez-de-35-anos\/","title":{"rendered":"Muere la estrella del culturismo Johanna P\u00e9rez, de 35 a\u00f1os"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>La familia P\u00e9rez present\u00f3 un deseo de vivienda en el funeral.<\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:63.24999999999999%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1730217784_146_Muere-la-estrella-del-culturismo-Johanna-Perez-de-35-anos.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1730217784_146_Muere-la-estrella-del-culturismo-Johanna-Perez-de-35-anos.jpg\"\/><meta itemprop=\"width\" content=\"1200\"\/><meta itemprop=\"height\" content=\"759\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Johanna P\u00e9rez oli poikkeuksellisen menestynyt panamalainen naiskehonrakentaja.\"\/><span class=\"caption-text\" itemprop=\"description\">Johanna P\u00e9rez fue una culturista paname\u00f1a excepcionalmente exitosa.<!-- --> <\/span><span class=\"media-source\">Captura de pantalla: Instagram<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\">Culturista paname\u00f1o e influencer de las redes sociales <strong>johanna perez<\/strong>de 35 a\u00f1os, ha fallecido. Entre otras cosas, la noticia cubri\u00f3 el asunto. <a rel=\"nofollow noopener\" href=\"https:\/\/fitnessvolt.com\/female-bodybuilding-influencer-dies-35\/\" target=\"_blank\">Sitio web de Fitness Volt<\/a>.<\/p>\n<p class=\"paragraph\">P\u00e9rez <a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/p\/DBGlph2Ozdc\/?img_index=2\" target=\"_blank\">c\u00e9lebre<\/a> en su cumplea\u00f1os a principios de octubre. Se desconoce la causa de la muerte.<\/p>\n<p class=\"paragraph\">El mundo del fitness y el culturismo lament\u00f3 el tr\u00e1gico destino de la joven. Se dice que la partida fue una completa sorpresa.<\/p>\n<p class=\"paragraph\">P\u00e9rez public\u00f3 un video en su cuenta de Instagram apenas una semana antes de su muerte. En el video comparti\u00f3 consejos de dieta con sus seguidores.<\/p>\n<p class=\"paragraph\">Unos d\u00edas despu\u00e9s, su familia public\u00f3 en la cuenta una invitaci\u00f3n al funeral de P\u00e9rez. La familia pidi\u00f3 que los invitados no vistieran de negro. Con la solicitud se esperaba que se respetara la alegr\u00eda y energ\u00eda de P\u00e9rez.<\/p>\n<p class=\"paragraph\">P\u00e9rez fue la primera culturista paname\u00f1a en ser vista en el escenario de una competencia.<\/p>\n<p class=\"paragraph\">Tiene m\u00e1s de 46.000 seguidores en su cuenta de Instagram.<\/p>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/fitnessvoimailu\/a\/64c2f7dd-834d-42be-851a-ee8dadd38d5f\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-49<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La familia P\u00e9rez present\u00f3 un deseo de vivienda en el funeral. Johanna P\u00e9rez fue una culturista paname\u00f1a excepcionalmente<\/p>\n","protected":false},"author":1,"featured_media":1418124,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[84803,205,201590,108601,38,3819,85199,486,25686,255,23335,1879,1546],"class_list":["post-1418123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-24-horas","tag-anos","tag-cuestiones-sociales","tag-culturismo","tag-del","tag-ejercicio-y-deportes","tag-estilo-de-vida-y-tiempo-libre","tag-estrella","tag-johanna","tag-muere","tag-perez","tag-relaciones-interpersonales","tag-sociedad"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1418123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1418123"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1418123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1418124"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1418123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1418123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1418123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}