{"id":1415056,"date":"2024-10-27T11:03:39","date_gmt":"2024-10-27T11:03:39","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-mayor-grupo-petrolero-de-hungria-ataca-la-hipocresia-occidental-sobre-la-energia-rusa\/"},"modified":"2024-10-27T11:03:44","modified_gmt":"2024-10-27T11:03:44","slug":"el-mayor-grupo-petrolero-de-hungria-ataca-la-hipocresia-occidental-sobre-la-energia-rusa","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-mayor-grupo-petrolero-de-hungria-ataca-la-hipocresia-occidental-sobre-la-energia-rusa\/","title":{"rendered":"El mayor grupo petrolero de Hungr\u00eda ataca la &#8220;hipocres\u00eda&#8221; occidental sobre la energ\u00eda rusa"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Desbloquea el Editor&#8217;s Digest gratis<\/p>\n<p class=\"article__content-sign-up-topic-description\"><span>Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/span><\/p>\n<p><iframe class=\"article__content-sign-up-iframe close\" scrolling=\"no\" id=\"signUpIframe\" data-prev-url=\"\/register\/in-article-sign-up?ft-content-uuid=1515df8f-1ef6-4e4f-9c1c-78d5e1a13725\"><\/iframe><\/div>\n<div id=\"article-body\">\n<p>Un alto ejecutivo de la principal compa\u00f1\u00eda de petr\u00f3leo y gas de Hungr\u00eda ha defendido la dependencia del pa\u00eds de la energ\u00eda rusa, se\u00f1alando la &#8220;hipocres\u00eda&#8221; entre sus aliados occidentales que est\u00e1n comprando combustibles &#8220;reenvasados&#8221; de Turqu\u00eda o India.<\/p>\n<p>\u201cNadie dice que los productos petrol\u00edferos refinados en Turqu\u00eda o India a partir de crudo ruso no puedan entrar en Europa. Nadie protesta y su papel sigue creciendo\u201d, afirm\u00f3 en una entrevista Gy\u00f6rgy Bacsa, director de operaciones de Mol, sobre la relaci\u00f3n de la compa\u00f1\u00eda con la naci\u00f3n productora de petr\u00f3leo.<\/p>\n<p>Mol contin\u00faa comprando petr\u00f3leo crudo ruso \u2013 disfrutando de una exenci\u00f3n indefinida de la prohibici\u00f3n de la UE sobre las importaciones de crudo de Rusia \u2013 incluso interviniendo como administrador del petr\u00f3leo que atraviesa Ucrania despu\u00e9s de que Kiev prohibiera a Lukoil usar su tramo del oleoducto Druzhba en julio. Bacsa dijo que la compa\u00f1\u00eda habl\u00f3 con Ucrania y Rusia para garantizar el flujo de petr\u00f3leo que sigue siendo vital para la regi\u00f3n.<\/p>\n<p>Budapest ha sido criticada por mantener las importaciones de energ\u00eda rusa incluso despu\u00e9s de la invasi\u00f3n de Ucrania, y los v\u00ednculos de Mol con Rusia han sido objeto de un renovado escrutinio despu\u00e9s de que Espa\u00f1a vet\u00f3 una oferta de 600 millones de euros de un consorcio h\u00fangaro por el fabricante de trenes Talgo el mes pasado. <\/p>\n<figure class=\"n-content-image n-content-image--full\" data-component=\"image-set\"><picture><source media=\"(min-width: 700px)\"  width=\"1459\" height=\"809\"\/><source media=\"(max-width: 490px)\"  width=\"626\" height=\"903\"\/><\/picture><\/figure>\n<p>Bacsa tambi\u00e9n preside el consorcio h\u00fangaro Ganz-M\u00e1vag. Espa\u00f1a bloque\u00f3 el acuerdo por temor a que Budapest pudiera interrumpir las exportaciones de piezas vitales a Ucrania y los v\u00ednculos del consorcio con Mol. <\/p>\n<p>Los funcionarios espa\u00f1oles creen que Ganz-M\u00e1vag est\u00e1 controlado en \u00faltima instancia por el grupo petrolero h\u00fangaro, mientras que varios estados miembros de la UE han estado preocupados por los v\u00ednculos de Mol con Rusia. <\/p>\n<p>Bacsa, que critic\u00f3 a Espa\u00f1a por ignorar las libertades b\u00e1sicas de la UE al vetar la candidatura, tambi\u00e9n culp\u00f3 a Bruselas por no garantizar alternativas energ\u00e9ticas para pa\u00edses sin litoral como Hungr\u00eda, como hizo con las vacunas. <\/p>\n<p>&#8220;Estamos abandonados a nuestra suerte, y algunos pa\u00edses no pueden expulsar el petr\u00f3leo y el gas rusos, mientras que otros caen en la hipocres\u00eda de comprar productos reenvasados \u200b\u200by disfrutar de los beneficios&#8221;, afirm\u00f3.<\/p>\n<p>El objetivo de las sanciones no era obligar a los pa\u00edses europeos a arrodillarse, sino poner fin a la guerra, afirm\u00f3. \u201cNo podemos permitir que los pa\u00edses de la UE que imponen sanciones se debiliten por sus propias decisiones. Eso no ser\u00eda una sanci\u00f3n. Ser\u00eda un gol en propia meta fatal\u201d.<\/p>\n<p>Bacsa defendi\u00f3 al gobierno amigo de Rusia de Orb\u00e1n, se\u00f1alando que no estaba en deuda con Mosc\u00fa. Budapest incluso ayud\u00f3 a Mol a comprar la participaci\u00f3n de los propietarios rusos. Poco despu\u00e9s de asumir el cargo de primer ministro en 2010, Orb\u00e1n inici\u00f3 la recompra de una participaci\u00f3n del 21,2 por ciento en Mol a la rusa Surgutneftegaz, una empresa que ha tenido estrechos v\u00ednculos con el Kremlin, por 1.900 millones de euros. <\/p>\n<p>&#8220;Defendimos nuestros intereses contra el intento hostil de adquisici\u00f3n ruso en un momento en que el resto de Europa hac\u00eda cola para recibir inversiones rusas&#8221;, dijo Bacsa.<\/p>\n<figure class=\"n-content-image n-content-image--full\" data-component=\"image-set\"><picture><source media=\"(min-width: 700px)\"  width=\"2244\" height=\"1496\"\/><source media=\"(max-width: 490px)\"  width=\"1526\" height=\"1526\"\/><img decoding=\"async\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/El-mayor-grupo-petrolero-de-Hungria-ataca-la-hipocresia-occidental.jpg\" alt=\"Los tanques de almacenamiento se encuentran en la refiner\u00eda de petr\u00f3leo de Duna, operada por Mol en Szazhalombatta, Hungr\u00eda.\" data-image-type=\"image\" width=\"2244\" height=\"1496\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>Las refiner\u00edas de Mol se construyeron para procesar la mezcla rusa de los Urales, y se necesitar\u00edan al menos dos a\u00f1os m\u00e1s para cambiar las instalaciones para refinar otros grados de crudo de diferentes productores.<\/span><span> <!-- -->\u00a9 Akos Stiller\/Bloomberg<\/span><\/figcaption><\/figure>\n<p>Mientras tanto, Turqu\u00eda ha aumentado sus importaciones de crudo ruso y exportado productos refinados a clientes occidentales, seg\u00fan un informe del Financial Times a principios de este a\u00f1o. El Centro de Investigaci\u00f3n sobre Energ\u00eda y Aire Limpio, con sede en Finlandia, tambi\u00e9n ha <a rel=\"nofollow noopener\" href=\"https:\/\/energyandcleanair.org\/publication\/sanctions-hypocrisy-g7-imports-eur-1-8-bn-of-turkish-oil-products-made-from-russian-crude\/\" data-trackable=\"link\" target=\"_blank\">prevenido<\/a> de pa\u00edses occidentales que de hecho evaden las sanciones.<\/p>\n<p>Una de las barreras para importar crudo de otros exportadores es que las refiner\u00edas de Mol fueron construidas para manejar la mezcla rusa de los Urales, y se necesitar\u00edan al menos dos a\u00f1os m\u00e1s para modernizar las instalaciones para refinar otros grados de crudo de diferentes productores. <\/p>\n<p>Tambi\u00e9n tendr\u00eda que importar crudo de otros productores a trav\u00e9s de un oleoducto en el sur y construir una infraestructura de refinaci\u00f3n separada que costar\u00eda alrededor de 500 millones de d\u00f3lares, dijo Bacsa.<\/p>\n<p>Se\u00f1al\u00f3 que el operador croata de oleoductos Janaf estaba aprovechando su posici\u00f3n como \u00fanica ruta para llevar crudo mar\u00edtimo a Europa central y la \u00fanica alternativa al ruso Druzhba, para aumentar los precios. Bacsa afirm\u00f3 que Janaf era &#8220;una de las empresas m\u00e1s rentables de Croacia&#8221;. <\/p>\n<p>El presidente de Janaf, Stjepan Adani\u0107, ha negado tales afirmaciones, afirmando que <a rel=\"nofollow noopener\" href=\"https:\/\/janaf.hr\/news\/1954#0\" data-trackable=\"link\" target=\"_blank\">mes pasado<\/a> el oleoducto era capaz de abastecer a las refiner\u00edas h\u00fangara y eslovaca de Mol a precios mutuamente acordados que &#8220;disminuyen a medida que aumentan las cantidades de petr\u00f3leo transportado, y viceversa&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/1515df8f-1ef6-4e4f-9c1c-78d5e1a13725\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desbloquea el Editor&#8217;s Digest gratis Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/p>\n","protected":false},"author":1,"featured_media":1415057,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4397,2476,2386,47517,2270,1826,4592,9972,2777,131],"class_list":["post-1415056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-ataca","tag-energia","tag-grupo","tag-hipocresia","tag-hungria","tag-mayor","tag-occidental","tag-petrolero","tag-rusa","tag-sobre"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1415056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1415056"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1415056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1415057"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1415056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1415056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1415056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}