{"id":1399349,"date":"2024-10-14T14:19:28","date_gmt":"2024-10-14T14:19:28","guid":{"rendered":"https:\/\/teknomers.com\/es\/una-chispeante-comedia-sobre-el-conocido-y-real-miedo-de-la-directora-y-actriz-a-volar-con-un-reparto-perfecto-casi-exclusivamente-femenino\/"},"modified":"2024-10-14T14:19:34","modified_gmt":"2024-10-14T14:19:34","slug":"una-chispeante-comedia-sobre-el-conocido-y-real-miedo-de-la-directora-y-actriz-a-volar-con-un-reparto-perfecto-casi-exclusivamente-femenino","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/una-chispeante-comedia-sobre-el-conocido-y-real-miedo-de-la-directora-y-actriz-a-volar-con-un-reparto-perfecto-casi-exclusivamente-femenino\/","title":{"rendered":"Una chispeante comedia sobre el conocido y real miedo de la directora y actriz a volar, con un reparto perfecto, casi exclusivamente femenino"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><span class=\"first-letter\">EL<\/span>n transmitido esta noche en Prime TV <strong>a las 21.25 horas en Sky Cinema y en streaming AHORA, <em>Volar<\/em> es una comedia divertida de y con Margherita Buy,<\/strong> <strong>en su primera direcci\u00f3n<\/strong>. Una pel\u00edcula que explora con <strong>Autoiron\u00eda y profundidad el tema del miedo a volar.<\/strong>contando la historia de <strong>AnnaB\u00ec, una actriz cuya carrera est\u00e1 en ca\u00edda libre precisamente por esta fobia.<\/strong><\/p>\n<div id=\"wrapper_video_embed\" class=\"player_single_video_component\">\n<div id=\"divVideoPlayer\" class=\"video-sticky-box privacyAccettata\">\n<div class=\"video-sticky-box-inner\">\n<div class=\"video-sticky-box-frame-cont\">\n<div class=\"player player_video_rcs player_shortcode custom-video-sticky\" data-config=\"{&quot;newspaper&quot;:&quot;rcs&quot;,&quot;uuid&quot;:&quot;iodonna-0001988931&quot;,&quot;muted&quot;:true,&quot;blockAdv&quot;:false,&quot;ovlLogo&quot;:false,&quot;autoplay&quot;:true,&quot;watermark&quot;:false,&quot;scale&quot;:&quot;with-parent&quot;,&quot;poster&quot;:{&quot;pre&quot;:{&quot;type&quot;:&quot;bySelector&quot;,&quot;container&quot;:&quot;.player_preview&quot;,&quot;play&quot;:&quot;.play&quot;,&quot;playByContainer&quot;:true}},&quot;playerPage&quot;:&quot;tvSticky&quot;,&quot;tipo_video&quot;:&quot;articolo_ancorato&quot;}\">\n<div class=\"player_preview\">\n                                    <img decoding=\"async\" class=\"\" alt=\"Margherita Buy: \u00abMi hija Caterina, la nueva pel\u00edcula y por qu\u00e9 debemos apoyar a las mujeres iran\u00edes\u00bb\" title=\"Margherita Buy: \u00abMi hija Caterina, la nueva pel\u00edcula y por qu\u00e9 debemos apoyar a las mujeres iran\u00edes\u00bb\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/Una-chispeante-comedia-sobre-el-conocido-y-real-miedo-de.webp.webp\"\/>                                    <span class=\"player_button play\"\/>\n                                <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2><em>Volar<\/em>la trama de la pel\u00edcula de Margherita Buy en Sky Cinema<\/h2>\n<p><strong>ana<\/strong> <strong>betini<\/strong>tambi\u00e9n conocida como AnnaB\u00ec <strong>(Margherita Buy), es una exitosa actriz de televisi\u00f3n que sufre de aviofobia, o miedo a volar.<\/strong>. Por este problema tuyo, Anna. <strong>A menudo tuvo que renunciar a papeles importantes, entre ellos uno en una pel\u00edcula coreana.<\/strong> de donde viene <strong>reemplazada por su rival Elena Sofia Ricci<\/strong> (como ella misma).<\/p>\n<article class=\"id-vda-article box_ed_hp_02-article eltdf-item-space hentry-pos-i hentry-home_section-i post-iiiii post type-post status-publish format-standard hentry\">\n<\/article>\n<p>Un d\u00eda<strong>su hija Serena (<\/strong><a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/catedeangeliss\/?hl=en\" target=\"_blank\" data-wpel-link=\"external\">Caterina De Angelis<\/a>en realidad hija de la actriz-directora)<strong> ella revela que ha sido aceptada en la Universidad de Stanford en San Francisco<\/strong>pero que no se lo confi\u00f3 antes precisamente por su miedo a volar. Esperando una respuesta negativa (y algo anhel\u00e1ndola), <strong>Anna le pregunta a su hija si le gustar\u00eda que la acompa\u00f1ara a California. La ni\u00f1a acepta felizmente. <\/strong><\/p>\n<p><strong>Anna no quiso retractarse de la propuesta y se inscribi\u00f3 en un curso para superar la aviofobia: curso celebrado en el aeropuerto de Fiumicino.<\/strong> por un comandante, Eugenio (<a rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/fra_colella\/?hl=en\" target=\"_blank\" data-wpel-link=\"external\">Francesco Colella<\/a>).<strong> El grupo de participantes es muy variado:<\/strong> desde la dentista (Euridice Axen) que quiere encontrar su gran amor en M\u00e9xico, hasta <strong>fan ac\u00e9rrima de Anna (Giulia Michielini) <\/strong>hasta el \u00e1cido y obstinado cr\u00edtico de cine (Roberto De Francesco). Todos juntos triunfar\u00e1n <strong>\u00bfSuperar su peor miedo?<\/strong><\/p>\n<div id=\"attachment_2273960\" data-thumbnail_id=\"2273960\" class=\"wp-caption aligncenter\" style=\"width:1034px\"><picture class=\"lozad\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"\/><\/source><\/picture>\n<p class=\"wp-caption-text\">Margherita Buy en una escena de \u201cVolare\u201d. (Foto de Anna Camerlingo)<\/p>\n<\/div>\n<h2>el elenco de <em>Volar<\/em> con Caterina De Angelis<\/h2>\n<p>Haciendo su debut detr\u00e1s de la c\u00e1mara, <strong>Margherita Buy escribe y dirige una comedia que pone de relieve una conocida y real debilidad de la actriz<\/strong>jugando continuamente<strong> entre la realidad y la ficci\u00f3n<\/strong>.<\/p>\n<p><strong>No es la primera vez que Buy lleva sus neurosis reales a la pantalla<\/strong> (ver\u00e1s <strong>las numerosas pel\u00edculas rodadas con Nanni Moretti<\/strong> Y <a rel=\"nofollow noopener\" href=\"https:\/\/www.imdb.com\/title\/tt0104798\/\" target=\"_blank\" data-wpel-link=\"external\"><em>Maldito sea el d\u00eda que te conoc\u00ed<\/em><\/a>  de Carlo Verdone). Para su debut como director, l<strong>La actriz profundiza a\u00fan m\u00e1s en su vida privada<\/strong>dirigiendo un<strong> pel\u00edcula decididamente autobiogr\u00e1fica<\/strong>. <strong>No es casualidad que llame a su hija, Caterina De Angelis, para que asuma el papel de hija del protagonista.<\/strong> \u2212 nace de la uni\u00f3n con el cirujano Renato De Angelis.<\/p>\n<p><strong>A pesar de<\/strong> una presencia engorrosa de colocaci\u00f3n de productos de ITA-Airways, <strong><em>Volar<\/em> fluye con ligereza: lleno de agradables comentarios y con la cantidad justa de autoiron\u00eda<\/strong> Eso <strong>a menudo conduce al autoan\u00e1lisis<\/strong>. Toda la atenci\u00f3n est\u00e1 claramente puesta en ella. Sin embargo <strong>Margherita Buy elige cuidadosamente un reparto de excelentes actores secundarios<\/strong>desde Anna Bonaiuto hasta la chispeante Giulia Michielini, y no sacrifica a ninguna de ellas.<\/p>\n<p><strong>El resultado es una pel\u00edcula exitosa, aunque un poco desequilibrada.<\/strong>: Comprar parece <strong>Si\u00e9ntete c\u00f3modo detr\u00e1s de la c\u00e1mara.<\/strong> mientras parece <strong>un poco enjaulado por un personaje<\/strong> que riesgos en algunas escenas de <strong>conducir a la mota.<\/strong><\/p>\n<h2><em>Trifole \u2013 Las ra\u00edces olvidadas<\/em>: la nueva pel\u00edcula de Margherita Buy estar\u00e1 en el cine el 17 de octubre<\/h2>\n<p>A partir del 17 de octubre encontraremos a la actriz Margherita Buy en el cine con una pel\u00edcula dirigida por Gabriele Fabbro,<strong> filmado en Langhe en Piamonte <\/strong>y dedicado a<strong> culto a la trufa<\/strong>. La historia es la de <strong>una reuni\u00f3n familiar<\/strong> que presenta a los protagonistas <strong>El cazador de trufas Igor (Umberto Orsini) y su joven sobrina Dalia (Ydalie Turk)<\/strong> que vive en Londres pero viene <strong>enviada por su madre (Margherita Buy) para ayudar a su abuelo<\/strong> que se encuentra en dificultades econ\u00f3micas y de salud.<\/p>\n<p>Como declar\u00f3 el director hace unos d\u00edas en el portal <a rel=\"nofollow noopener\" href=\"https:\/\/torinocronaca.it\/news\/tempo-libero\/388215\/il-tartufo-debutta-in-sala-con-trifole.html\" target=\"_blank\" data-wpel-link=\"external\"><em>Noticias de Tur\u00edn<\/em><\/a>: \u00ab<strong>Mientras escrib\u00eda el gui\u00f3n, me di cuenta de que Margherita se parec\u00eda mucho a Ydalie Turk.<\/strong> \u2013a quien ya hab\u00eda elegido como protagonista de mi pel\u00edcula\u2013, por lo tanto <strong>Fue natural pensar en ella como madre.<\/strong>. Margherita era muy buena y <strong>Inmediatamente abraz\u00f3 el proyecto con pasi\u00f3n.<\/strong>\u00bb.<\/p>\n<p class=\"all-rights-reserved\">iO Donna \u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/p><\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.iodonna.it\/spettacoli\/tv\/2024\/10\/14\/volare-margherita-buy-film-trama-cast-prima-tv-sky-cinema-uno\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-13<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ELn transmitido esta noche en Prime TV a las 21.25 horas en Sky Cinema y en streaming AHORA,<\/p>\n","protected":false},"author":1,"featured_media":1399350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[5143,2432,68462,11604,99,5036,11861,27621,6068,1137,7909,1295,28420,131,158,4112],"class_list":["post-1399349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-actriz","tag-casi","tag-chispeante","tag-comedia","tag-con","tag-conocido","tag-directora","tag-exclusivamente","tag-femenino","tag-miedo","tag-perfecto","tag-real","tag-reparto","tag-sobre","tag-una","tag-volar"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1399349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1399349"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1399349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1399350"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1399349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1399349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1399349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}