{"id":1392034,"date":"2024-10-07T14:43:43","date_gmt":"2024-10-07T14:43:43","guid":{"rendered":"https:\/\/teknomers.com\/es\/israel-gaza-medio-oriente-como-cambio-todo\/"},"modified":"2024-10-07T14:43:50","modified_gmt":"2024-10-07T14:43:50","slug":"israel-gaza-medio-oriente-como-cambio-todo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/israel-gaza-medio-oriente-como-cambio-todo\/","title":{"rendered":"Israel, Gaza, Medio Oriente: c\u00f3mo cambi\u00f3 todo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>an\u00e1lisis<\/p>\n<h2 class=\"h16rff0y\"><span class=\"o1r6qsum t1ktg2ut\">Desde el 7 de octubre<\/span><span class=\"h12yzj33\">:<\/span><span class=\"tevc803 hhhtovw\">Israel, Gaza, Medio Oriente: c\u00f3mo cambi\u00f3 todo<\/span><\/h2>\n<div class=\"a37487b\">\n<div class=\"asoadbm\">\n<div class=\"a515ogu\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:1\/1\"><picture class=\"ak4rs7g slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source \/><\/picture><\/div>\n<\/div>\n<p><span class=\"m211382\">por Michael Rese\u00f1as<\/span><\/div>\n<\/div>\n<p class=\"i8d9m7i c1bdz7f4\">\u00bfC\u00f3mo cambi\u00f3 el 7 de octubre la situaci\u00f3n pol\u00edtica en Israel, Gaza y Cisjordania? \u00bfQu\u00e9 significa esto para la regi\u00f3n? Cinco preguntas, cinco respuestas.<\/p>\n<\/div>\n<div data-testid=\"text-module\">\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Personas abraz\u00e1ndose en un monumento conmemorativo\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">Desde los traum\u00e1ticos ataques terroristas de Ham\u00e1s, hemos observado la guerra, hemos conocido a personas en Israel y Gaza y hemos seguido sus destinos. <\/span><span class=\"m211382\">26 de septiembre de 2024 | 29:57 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">El 7 de octubre de 2023, Ham\u00e1s lanz\u00f3 un ataque coordinado e inesperado contra Israel. Los terroristas de Ham\u00e1s mataron indiscriminadamente a civiles, tomaron rehenes y torturaron y violaron a decenas de personas. Casi 100 rehenes siguen retenidos, muchos de los cuales probablemente ya est\u00e9n muertos.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Netanyahu ha declarado varias veces que quiere acabar con Ham\u00e1s. Gaza est\u00e1 cubierta de escombros y cenizas, dos millones de residentes han huido y decenas de miles han muerto. En el norte, la guerra de agresi\u00f3n de Hezbollah contra Israel ha escalado hasta convertirse en una conflagraci\u00f3n que amenaza con hundir a todo el Medio Oriente en el abismo.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Lo que ha sucedido desde el 7 de octubre de 2023 est\u00e1 cambiando toda la regi\u00f3n y m\u00e1s all\u00e1.<\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"katrin eigendorf\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">&#8220;Vivo Tel Aviv con gran tristeza&#8221;, dijo la reportera del ZDF Katrin Eigendorf.<\/span><span class=\"m211382\">7 de octubre de 2024 | 2:54 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span><strong>\u00bfQu\u00e9 quer\u00eda lograr Ham\u00e1s con su ataque terrorista del 7 de octubre?<\/strong><\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Hasta 2020, Israel s\u00f3lo hab\u00eda firmado tratados de paz con sus vecinos Egipto y Jordania. Desde 2020 se han firmado otros acuerdos con los Emiratos \u00c1rabes Unidos, Bahr\u00e9in, Sud\u00e1n y Marruecos en los llamados Acuerdos de Abraham. El proceso de paz con los palestinos, por otra parte, no s\u00f3lo se estanc\u00f3, sino que se paraliz\u00f3 por completo. Al mismo tiempo, Ham\u00e1s corr\u00eda el peligro de quedar en gran medida marginado pol\u00edticamente.<\/p>\n<p>Cuando Arabia Saudita estaba a punto de hacer la paz con Israel, Ham\u00e1s puso en pr\u00e1ctica su plan de larga data para atacar a Israel. El objetivo: impedir nuevos acuerdos de paz y forzar a la regi\u00f3n a una gran guerra contra Israel. Aunque Ham\u00e1s hoy est\u00e1 en gran medida derrotado militarmente en Gaza, las recientes escaladas han acercado a su l\u00edder Jahia Sinwar a su objetivo estrat\u00e9gico de incendiar toda la regi\u00f3n.<\/p>\n<\/div>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Jihia al-Sinwar, jefe del ala militar del grupo terrorista islamista Ham\u00e1s en la Franja de Gaza, foto de archivo\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">Jihia al-Sinwar es jefa de la oficina pol\u00edtica de Ham\u00e1s desde agosto. Conocido como el &#8220;Carnicero de Khan Yunis&#8221;, el autor intelectual del ataque del 7 de octubre sigui\u00f3 a Ismail Haniya.<\/span><span class=\"m211382\">6 de agosto de 2024 | 0:19 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span><strong>\u00bfC\u00f3mo han cambiado las consecuencias del 7 de octubre la situaci\u00f3n pol\u00edtica en Israel?<\/strong><\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>El 7 de octubre tambi\u00e9n marc\u00f3 un fracaso generalizado de las instituciones de seguridad de Israel, ya que los planes de ataque de Ham\u00e1s se conoc\u00edan con mucha antelaci\u00f3n y hab\u00eda repetidos indicios concretos de un ataque inminente. Sin embargo, todas las advertencias fueron descartadas por ser poco realistas. En realidad, el gobierno y los dirigentes de las fuerzas de seguridad deber\u00edan haber dimitido hace mucho tiempo. Sin embargo, la aceptaci\u00f3n del 7 de octubre ha quedado en suspenso en Israel debido a la guerra en curso. <\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Sin embargo, todos los l\u00edderes clave, el jefe de inteligencia militar y nacional, el jefe del Estado Mayor del ej\u00e9rcito y el ministro de Defensa han asumido la responsabilidad pol\u00edtica. Hasta ahora, s\u00f3lo el Primer Ministro Netanyahu se ha negado a aceptar la responsabilidad por los acontecimientos del 7 de octubre.<\/div>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Actos conmemorativos del 7 de octubre\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">Numerosas personas recuerdan hoy en Berl\u00edn a las v\u00edctimas del ataque terrorista de Ham\u00e1s contra Israel. Durante el aniversario se celebrar\u00e1n varios actos conmemorativos y tambi\u00e9n est\u00e1n previstas manifestaciones para ese d\u00eda.<\/span><span class=\"m211382\">7 de octubre de 2024 | 1:57 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>En general, la guerra polariz\u00f3 a\u00fan m\u00e1s a la sociedad israel\u00ed, que ya estaba dividida en la resistencia al gobierno israel\u00ed, a veces de extrema derecha. Se trata tambi\u00e9n de las cr\u00edticas al rumbo b\u00e9lico del gobierno, que se niega a hacer concesiones esenciales en las negociaciones con Ham\u00e1s para que los rehenes restantes puedan ser liberados. Cientos de miles de personas se manifiestan no s\u00f3lo por la liberaci\u00f3n de los rehenes, sino tambi\u00e9n contra el gobierno de turno y piden nuevas elecciones.<\/p>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span><strong>\u00bfFue la reacci\u00f3n de Israel proporcionada y conforme al derecho internacional?<\/strong><\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Para Israel, esta cuesti\u00f3n es m\u00e1s dif\u00edcil de evaluar que en el caso de Ham\u00e1s, que atac\u00f3, asesin\u00f3 y viol\u00f3 sistem\u00e1tica y deliberadamente a civiles y tom\u00f3 252 rehenes el 7 de octubre. Al mismo tiempo, Ham\u00e1s est\u00e1 utilizando sistem\u00e1ticamente a la poblaci\u00f3n civil palestina en Gaza como escudos humanos, lo que tambi\u00e9n es un crimen de guerra.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>En principio, seg\u00fan el derecho internacional humanitario, Israel puede atacar a Ham\u00e1s incluso si est\u00e1 escondido detr\u00e1s de civiles o en instalaciones civiles. Sin embargo, Israel debe respetar la proporcionalidad. Sin embargo, la forma de definirlo depende de cada caso concreto, por ejemplo, cu\u00e1ntas v\u00edctimas civiles se pueden aceptar en caso de un asesinato selectivo de combatientes o comandantes de Ham\u00e1s. <\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"protagonista\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">Los ni\u00f1os de Cisjordania est\u00e1n creciendo en una dura realidad. Todos los d\u00edas experimentan odio y violencia contra palestinos y jud\u00edos.<\/span><span class=\"m211382\">2 de octubre de 2024 | 43:33 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Israel afirma examinar cada ataque individual y calcular exactamente cu\u00e1ntas v\u00edctimas civiles son inevitables. Pero esto es dif\u00edcil o imposible de verificar. Especialmente al comienzo de la guerra, decenas o, a veces, m\u00e1s de 100 civiles murieron en cada ataque, por lo que surge la cuesti\u00f3n de la proporcionalidad. Seg\u00fan cifras israel\u00edes, de los 42.000 palestinos asesinados actualmente en Gaza, alrededor de 20.000 son combatientes de Ham\u00e1s. Estos son combatientes seg\u00fan el derecho internacional y, por lo tanto, objetivos leg\u00edtimos. Ninguno de los n\u00fameros puede verificarse de forma independiente.<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Al parecer, Israel est\u00e1 violando el derecho internacional al negarse a proporcionar suministros a la poblaci\u00f3n civil en las zonas que ha conquistado. Aunque Israel afirma que apoya las entregas de ayuda humanitaria, seg\u00fan el derecho internacional humanitario est\u00e1 obligado, como potencia ocupante de facto, a garantizar el suministro de alimentos y suministros m\u00e9dicos a la poblaci\u00f3n civil.<\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Ataques en Beirut \" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">En el aniversario, Hezbollah anunci\u00f3 que continuar\u00eda la lucha. Durante la noche, los cohetes cayeron sobre la ciudad de Haifa e Israel atac\u00f3 el L\u00edbano.<\/span><span class=\"m211382\">7 de octubre de 2024 | 0:24 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span> <strong>\u00bfC\u00f3mo se est\u00e1n posicionando los pa\u00edses vecinos en la regi\u00f3n?<\/strong><\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Los Estados \u00e1rabes vecinos se posicionan en general del lado de los palestinos, aunque los cr\u00edmenes de Ham\u00e1s no se mencionan en las declaraciones oficiales. <\/p>\n<p>Por otro lado, existe oposici\u00f3n a Ir\u00e1n, que controla a Ham\u00e1s en Gaza, a Hezbol\u00e1 en el L\u00edbano y a las milicias en Irak, Yemen y Siria. En los anteriores ataques de Ir\u00e1n contra Israel, se dice que Estados como Egipto, Jordania e incluso Arabia Saudita apoyaron la defensa contra los misiles iran\u00edes.<\/p>\n<\/div>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Estados Unidos respalda a Israel\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">Tras los ataques con misiles iran\u00edes contra Israel, el presidente estadounidense Biden ha prometido su pleno apoyo al gobierno israel\u00ed.<\/span><span class=\"m211382\">2 de octubre de 2024 | 1:29 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span> <strong>\u00bfC\u00f3mo ha cambiado la respuesta militar de Israel su relaci\u00f3n con Europa?<\/strong><\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Los aliados occidentales en Estados Unidos y Europa reconocen fundamentalmente el derecho de Israel a la autodefensa. Sin embargo, la conducci\u00f3n de la guerra por parte de Israel tambi\u00e9n ha provocado duras cr\u00edticas por parte de sus aliados, particularmente en lo que respecta a la proporcionalidad de las armas utilizadas. Mientras tanto, Estados Unidos incluso ha suspendido el lanzamiento de bombas pesadas. En la UE, el apoyo un\u00e1nime a la campa\u00f1a b\u00e9lica de Israel est\u00e1 disminuyendo. <\/p>\n<p>S\u00f3lo los EE.UU. tienen alguna influencia real en el rumbo del gobierno israel\u00ed. No han logrado ejercer una presi\u00f3n real sobre Israel, ni en t\u00e9rminos de negociaciones con Hamas ni en la planificaci\u00f3n de un acuerdo de posguerra para Gaza. A pesar de todas las cr\u00edticas a las pol\u00edticas del gobierno de Netanyahu, Estados Unidos y Alemania, en \u00faltima instancia, est\u00e1n incondicionalmente del lado de Israel.<\/p>\n<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p><em>Michael Bewerunge fue director del estudio extranjero en Tel Aviv hasta finales de septiembre de 2024.<\/em><\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.zdf.de\/nachrichten\/politik\/ausland\/israel-hamas-angriff-nahost-konflikt-faq-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-39<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>an\u00e1lisis Desde el 7 de octubre:Israel, Gaza, Medio Oriente: c\u00f3mo cambi\u00f3 todo por Michael Rese\u00f1as \u00bfC\u00f3mo cambi\u00f3 el<\/p>\n","protected":false},"author":1,"featured_media":1392035,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1571,440,51742,7753,2508,7999,339],"class_list":["post-1392034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-cambio","tag-como","tag-gaza","tag-israel","tag-medio","tag-oriente","tag-todo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1392034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1392034"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1392034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1392035"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1392034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1392034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1392034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}