{"id":1391900,"date":"2024-10-07T12:48:37","date_gmt":"2024-10-07T12:48:37","guid":{"rendered":"https:\/\/teknomers.com\/es\/kevin-kuhnert-dimite\/"},"modified":"2024-10-07T12:48:42","modified_gmt":"2024-10-07T12:48:42","slug":"kevin-kuhnert-dimite","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/kevin-kuhnert-dimite\/","title":{"rendered":"Kevin K\u00fchnert dimite"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div data-testid=\"text-module\">\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"byi3ftt\">\n<div class=\"r1f6k8yy\" style=\"--r1f6k8yy-0:16\/9\"><picture class=\"slrzex8\" style=\"--slrzex8-0:var(--surface-subtle)\"><source  \/><\/picture><\/div>\n<\/div>\n<p>Kevin K\u00fchnert dimite con efecto inmediato como secretario general del SPD: &#8220;Lamentablemente no estoy sano&#8221;.<\/p>\n<p>Fuente: dpa<\/p>\n<hr class=\"l1uat3jy d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>El secretario general del SPD, Kevin K\u00fchnert, ha anunciado su dimisi\u00f3n. En una declaraci\u00f3n personal adujo motivos de salud. De cara a las pr\u00f3ximas elecciones, el partido debe hacer &#8220;enormes esfuerzos&#8221;, escribi\u00f3. &#8220;Cada uno de nosotros debe superarse y lo har\u00e1 en esta campa\u00f1a&#8221;, escribi\u00f3 a los miembros de su partido. Y contin\u00faa: <\/p>\n<\/div>\n<div class=\"bbqjgdv c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r80o15e\">\n<figure>\n<blockquote class=\"b1speu17\">\n<p class=\"tosa0j6 hhhtovw\">No puedo crecer m\u00e1s all\u00e1 de m\u00ed en este momento porque desafortunadamente no estoy sano. <\/p>\n<\/blockquote><figcaption>\n<p class=\"aley63f m1lnp037\">Kevin K\u00fchnert, SPD<\/p>\n<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Kevin K\u00fchnert SPD\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">Los problemas del SPD federal no han disminuido, dice el secretario general del SPD, Kevin K\u00fchnert, pero tampoco han aumentado. <\/span><span class=\"m211382\">22 de septiembre de 2024 | 3:11 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>No habr\u00e1 m\u00e1s candidaturas al Bundestag<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>&#8220;Necesito la energ\u00eda necesaria para mi cargo y para una campa\u00f1a electoral en un futuro pr\u00f3ximo para recuperar la salud&#8221;, explic\u00f3 K\u00fchnert. &#8220;Por eso saco las conclusiones&#8221;.<\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">Hace unos d\u00edas inform\u00f3 a los l\u00edderes del SPD, Saskia Esken y Lars Klingbeil, que hoy dimitir\u00eda del cargo de secretario general del SPD. El a\u00f1o que viene no volver\u00e1 a presentarse como candidato al Bundestag. <\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>Esken y Klingbeil quieren comentar por la tarde. Tambi\u00e9n lo hizo el secretario general de la CDU, Carsten Linnemann.<\/p>\n<\/div>\n<div class=\"c1owvrps c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px;--c1owvrps-0:100%;--c1owvrps-1:100%\">\n<div style=\"--aspect-ratio:16\/9\" class=\"v1juetu9 c1b61q9f\" data-testid=\"player\"><picture class=\"pdq8aiy\"><source \/><img decoding=\"async\" loading=\"lazy\" alt=\"Kevin K\u00fchnert SPD | secretario general\" class=\"pei0kpe\"\/><\/picture>\n<figure class=\"p19vhib2\"\/><\/div>\n<p><span class=\"c1pbsmr2\">Tras el acuerdo sobre el sem\u00e1foro sobre el presupuesto, el secretario general del SPD, Kevin K\u00fchnert, pidi\u00f3 igualdad de derechos para los empleados. Hay que pensar en recortes de impuestos.<\/span><span class=\"m211382\">8 de julio de 2024 | 5:05 minutos<\/span><\/p>\n<hr class=\"d3s70gw d19t6vpa\"\/><\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>K\u00fchnert escribi\u00f3 que ambas decisiones le costaron mucha energ\u00eda y le perjudicaron. Sin embargo, los correctos son: <\/p>\n<\/div>\n<div class=\"bbqjgdv c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r80o15e\">\n<figure>\n<blockquote class=\"b1speu17\">\n<p class=\"tosa0j6 hhhtovw\">Soy responsable de m\u00ed mismo y del SPD.<\/p>\n<\/blockquote><figcaption>\n<p class=\"aley63f m1lnp037\">Kevin K\u00fchnert, SPD<\/p>\n<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>La mejor manera de que \u00e9l cumpla con su responsabilidad es concentrarse exclusivamente en su salud. <\/p>\n<\/div>\n<p><h2 class=\"t1rbo974 hhhtovw\"><span>La campa\u00f1a contra GroKo hizo famoso a K\u00fchnert<\/span><\/h2>\n<\/p>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<p>K\u00fchnert es secretario general de los socialdem\u00f3cratas desde 2021 y ese mismo a\u00f1o ingres\u00f3 al Bundestag. Anteriormente se hizo conocido en todo el pa\u00eds como presidente de los Jusos, entre otras cosas porque organiz\u00f3 una campa\u00f1a contra un GroKo formado por la Uni\u00f3n y el SPD. <\/p>\n<\/div>\n<div class=\"c10o8fzf\" style=\"--c10o8fzf-0:16px;--c10o8fzf-1:var(--vertical-content-padding) &#10;    max(var(--horizontal-content-padding), env(safe-area-inset-left), env(safe-area-inset-right));--c10o8fzf-2:720px\">\n<div class=\"r1nj4qn5\">En 2019 jug\u00f3 un papel decisivo cuando los izquierdistas del partido Saskia Esken y Norbert Walter-Borjans llegaron a la cima del SPD en la segunda vuelta electoral contra el actual canciller Olaf Scholz y Klara Geywitz. <\/div>\n<\/div>\n<p><span class=\"t1fikfz9 tsdggcs\">Fuente: <!-- -->ZDF, dpa<\/span><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.zdf.de\/nachrichten\/politik\/kuehnert-spd-ruecktritt-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-39<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kevin K\u00fchnert dimite con efecto inmediato como secretario general del SPD: &#8220;Lamentablemente no estoy sano&#8221;. Fuente: dpa El<\/p>\n","protected":false},"author":1,"featured_media":1391901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[11966,4828,91255],"class_list":["post-1391900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-dimite","tag-kevin","tag-kuhnert"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1391900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1391900"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1391900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1391901"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1391900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1391900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1391900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}