{"id":1390607,"date":"2024-10-06T11:16:32","date_gmt":"2024-10-06T11:16:32","guid":{"rendered":"https:\/\/teknomers.com\/es\/las-empresas-indias-entran-mientras-estados-unidos-excluye-a-china-de-su-industria-solar\/"},"modified":"2024-10-06T11:16:38","modified_gmt":"2024-10-06T11:16:38","slug":"las-empresas-indias-entran-mientras-estados-unidos-excluye-a-china-de-su-industria-solar","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/las-empresas-indias-entran-mientras-estados-unidos-excluye-a-china-de-su-industria-solar\/","title":{"rendered":"Las empresas indias entran mientras Estados Unidos excluye a China de su industria solar"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"article-body\">\n<p>Las empresas indias est\u00e1n tomando medidas para llenar el vac\u00edo dejado por la exclusi\u00f3n de las exportaciones chinas de la industria solar estadounidense de r\u00e1pido crecimiento, mientras Washington intensifica su represi\u00f3n contra los fabricantes con v\u00ednculos con Beijing.<\/p>\n<p>Sumant Sinha, director ejecutivo de ReNew, una de las mayores empresas de energ\u00edas renovables de la India, dijo al Financial Times que \u201chabr\u00e1 demanda\u201d de componentes solares de la India a medida que Washington reduzca su dependencia de los suministros chinos para su transici\u00f3n energ\u00e9tica.<\/p>\n<p>&#8220;Existe la necesidad de cierta diversificaci\u00f3n, y la India puede convertirse en el acompa\u00f1ante de China en lo que respecta a la cadena de suministro de tecnolog\u00eda verde&#8221;, afirm\u00f3 Sinha.<\/p>\n<p>A\u00f1adi\u00f3 que ReNew estaba considerando exportar a Estados Unidos desde sus f\u00e1bricas solares en India en espera de las normas arancelarias estadounidenses. \u201c[India] llenar\u00e1 el vac\u00edo\u201d.<\/p>\n<p>Washington est\u00e1 sopesando aranceles adicionales a las importaciones de energ\u00eda solar para proteger la industria nacional despu\u00e9s de que una avalancha de paneles producidos en China llev\u00f3 los precios mundiales a m\u00ednimos hist\u00f3ricos. <\/p>\n<p>La semana pasada, el Departamento de Comercio public\u00f3 estimaciones preliminares de aranceles de hasta el 293 por ciento para los exportadores de c\u00e9lulas solares en cuatro pa\u00edses del sudeste asi\u00e1tico, donde Estados Unidos obtiene la mayor parte de sus suministros solares, a menudo de empresas chinas.<\/p>\n<p>La inminente decisi\u00f3n ha llevado a los desarrolladores y fabricantes a mirar m\u00e1s all\u00e1 de la regi\u00f3n hacia mercados no sujetos a aranceles. Wood Mackenzie espera que la fabricaci\u00f3n de c\u00e9lulas en pa\u00edses fuera de los principales centros de China y el sudeste asi\u00e1tico se duplique con creces en los pr\u00f3ximos dos a\u00f1os, y que India represente el 40 por ciento de la nueva capacidad.<\/p>\n<p>&#8220;No hay ning\u00fan fabricante modular en la India que no est\u00e9 pensando en exportar&#8221;, dijo Subrahmanyam Pulipaka, director ejecutivo de la Federaci\u00f3n Nacional de Energ\u00eda Solar de la India, un grupo de presi\u00f3n que cuenta entre sus miembros con grandes desarrolladores como Adani Group, Tata Power y ReNew.<\/p>\n<p>Las importaciones estadounidenses de paneles y celdas indias superaron los 1.800 millones de d\u00f3lares el a\u00f1o pasado, frente a los 250 millones de d\u00f3lares del a\u00f1o anterior, seg\u00fan BloombergNEF. <\/p>\n<p>Los fabricantes indios tambi\u00e9n est\u00e1n invirtiendo en f\u00e1bricas estadounidenses tras la hist\u00f3rica Ley de Reducci\u00f3n de la Inflaci\u00f3n del presidente Joe Biden, que inclu\u00eda lucrativos subsidios para los productores nacionales, y Waaree y VSK Energy anunciaron compromisos de fabricaci\u00f3n por valor de al menos mil millones de d\u00f3lares cada uno el a\u00f1o pasado.<\/p>\n<p>&#8220;La principal ventaja es que no son chinos&#8221;, dijo Martin Pochtaruk, director ejecutivo de Heliene, que opera una f\u00e1brica de paneles solares en Minnesota. <\/p>\n<p>La empresa sol\u00eda obtener sus c\u00e9lulas de Vietnam y Malasia, pero ahora las compra principalmente a la India para protegerse de nuevos aranceles. En julio, Heliene anunci\u00f3 una empresa conjunta de 150 millones de d\u00f3lares con Premier Energies, el segundo mayor fabricante de c\u00e9lulas solares de la India, para construir una f\u00e1brica en Estados Unidos.<\/p>\n<p>La administraci\u00f3n Biden ha aumentado las protecciones contra las importaciones de energ\u00eda solar con v\u00ednculos con Beijing, duplicando la tasa de derechos para las c\u00e9lulas chinas, aplicando aranceles antielusi\u00f3n a las empresas chinas en el sudeste asi\u00e1tico y prohibiendo productos vinculados al trabajo forzoso en Xinjiang. La Casa Blanca tambi\u00e9n mantuvo los aranceles de la era Trump que se aplicaban a los productos solares de la mayor\u00eda de los pa\u00edses.<\/p>\n<p>A pesar de los esfuerzos, las importaciones estadounidenses de paneles se sit\u00faan en niveles r\u00e9cord. Varios fabricantes, incluido VSK Energy, han retrasado o descartado sus planes de fabricaci\u00f3n en Estados Unidos a pesar de la disponibilidad de cr\u00e9ditos fiscales federales.<\/p>\n<p>&#8220;Los aranceles no han funcionado&#8221;, dijo Pol Lezcano, analista senior de BloombergNEF.<\/p>\n<p>\u201cLos fabricantes no vienen a Estados Unidos. Realmente no encuentran el entorno empresarial y de cadena de suministro adecuado que necesitan para ampliar la fabricaci\u00f3n\u201d.<\/p>\n<p>La r\u00e1pida ca\u00edda de los precios de los paneles importados ha ayudado a transformar la energ\u00eda solar en la principal fuente de nueva energ\u00eda en la red estadounidense. La Administraci\u00f3n de Informaci\u00f3n Energ\u00e9tica espera que las instalaciones solares crezcan este a\u00f1o un 42 por ciento, alcanzando los 127 gigavatios. <\/p>\n<p>En abril, los mayores fabricantes de energ\u00eda solar de Estados Unidos, First Solar y Qcells, y otros presentaron una petici\u00f3n para que se aplicaran aranceles a las c\u00e9lulas en cuatro pa\u00edses del sudeste asi\u00e1tico con el fin de rescatar una industria nacional en dificultades.<\/p>\n<aside aria-labelledby=\"aside-label\" class=\"n-content-recommended--single-story n-content-recommended--inset\" data-component=\"recommended\">\n<p class=\"n-content-recommended__title\">Recomendado<\/p>\n<div class=\"o-teaser o-teaser--article o-teaser--small o-teaser--stacked o-teaser--has-image js-teaser\" data-id=\"4afdd319-230f-4763-8107-d8a43308dcfc\">\n<div class=\"o-teaser__image-container js-teaser-image-container\">\n<div class=\"o-teaser__image-placeholder\" style=\"aspect-ratio:2048\/1152\"><\/div>\n<\/div>\n<\/div>\n<\/aside>\n<p>Luigi Resta, presidente de la promotora rPlus Energies, advirti\u00f3 que las tarifas ralentizar\u00edan el ritmo de implementaci\u00f3n y aumentar\u00edan los precios para los consumidores. La empresa ha comenzado a abastecerse de Indonesia, otro mercado emergente de fabricaci\u00f3n de energ\u00eda solar, para protegerlo de los impactos comerciales. <\/p>\n<p>&#8220;La naturaleza de la industria es que tenemos que ser muy flexibles&#8221;, dijo Resta. La empresa ahora obtiene alrededor de 1 GW de paneles entre Indonesia y Vietnam.<\/p>\n<p>Ejecutivos y analistas de la industria expresaron su preocupaci\u00f3n de que los planes para construir l\u00edneas de producci\u00f3n en mercados exentos de aranceles puedan llevar al gobierno de Estados Unidos a jugar un juego de &#8220;Whac-A-Mole&#8221; con aranceles y multar a esos pa\u00edses en el futuro, arriesgando miles de millones en gastos de capital.<\/p>\n<p>&#8220;Si demasiada gente va a un lugar, eso arruina todo para todos&#8221;, dijo Jim Wood, director ejecutivo de SEG Solar. <\/p>\n<p>La semana pasada, la compa\u00f1\u00eda inici\u00f3 la construcci\u00f3n de una f\u00e1brica de 500 millones de d\u00f3lares cerca de Yakarta, que ayudar\u00e1 a suministrar c\u00e9lulas a su f\u00e1brica de paneles en Texas.<\/p>\n<div class=\"n-content-layout\" data-layout-name=\"card\" data-layout-width=\"full-width\">\n<div class=\"n-content-layout__container\">\n<h3 class=\"n-content-heading-3\">Capital clim\u00e1tica<\/h3>\n<div class=\"n-content-layout__slot\">\n<figure class=\"n-content-image n-content-image--full\" data-component=\"image-set\"><picture><source media=\"(min-width: 700px)\"  width=\"2048\" height=\"1152\"\/><img decoding=\"async\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/Las-empresas-indias-entran-mientras-Estados-Unidos-excluye-a-China.jpg\" alt=\"\" data-image-type=\"image\" width=\"2048\" height=\"1152\" loading=\"lazy\"\/><\/picture><\/figure>\n<\/div>\n<div class=\"n-content-layout__slot\">\n<p>Donde el cambio clim\u00e1tico se encuentra con los negocios, los mercados y la pol\u00edtica. Explore la cobertura del FT aqu\u00ed.<\/p>\n<p>\u00bfTiene curiosidad acerca de los compromisos de sostenibilidad ambiental del Financial Times? <a rel=\"nofollow noopener\" href=\"https:\/\/aboutus.ft.com\/company\/sustainability\" data-trackable=\"link\" target=\"_blank\">Obtenga m\u00e1s informaci\u00f3n sobre nuestros objetivos basados \u200b\u200ben la ciencia aqu\u00ed<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/78f52ebd-13ba-4a38-843a-c156f2415e8b\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las empresas indias est\u00e1n tomando medidas para llenar el vac\u00edo dejado por la exclusi\u00f3n de las exportaciones chinas<\/p>\n","protected":false},"author":1,"featured_media":1390608,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[73,3581,18975,4003,10478,12094,1343,246,3530,13164,4004],"class_list":["post-1390607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-china","tag-empresas","tag-entran","tag-estados","tag-excluye","tag-indias","tag-industria","tag-las","tag-mientras","tag-solar","tag-unidos"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390607"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390608"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}