{"id":1390602,"date":"2024-10-06T11:13:28","date_gmt":"2024-10-06T11:13:28","guid":{"rendered":"https:\/\/teknomers.com\/es\/corriendo-mas-de-200-kilometros-guido-participa-en-el-mundial-backyard-ultra-running\/"},"modified":"2024-10-06T11:13:34","modified_gmt":"2024-10-06T11:13:34","slug":"corriendo-mas-de-200-kilometros-guido-participa-en-el-mundial-backyard-ultra-running","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/corriendo-mas-de-200-kilometros-guido-participa-en-el-mundial-backyard-ultra-running\/","title":{"rendered":"Corriendo m\u00e1s de 200 kil\u00f3metros: Guido participa en el Mundial &#8216;Backyard Ultra running&#8217;"},"content":{"rendered":"\n<div>\n<p>El deportista alterna distancias cortas con largas durante su entrenamiento. Est\u00e1 convencido de que una carrera ultra es principalmente una batalla mental. &#8220;Es bastante divertido durante las primeras 10, 20, 30 horas y luego se vuelve cada vez m\u00e1s dif\u00edcil&#8221;. <\/p>\n<p>Los 15 corredores holandeses compiten por dos t\u00edtulos. Como equipo, pueden convertirse en los mejores del mundo sumando tantos puntos como sea posible. Cada vuelta de 6,7 kil\u00f3metros completada dentro del tiempo otorga un punto. El \u00faltimo holand\u00e9s que quede en pie podr\u00e1 proclamarse campe\u00f3n de Holanda y participar en el torneo individual en Am\u00e9rica el pr\u00f3ximo a\u00f1o. <\/p>\n<h2>4,5 d\u00edas de carrera<\/h2>\n<p>&#8220;Pero todav\u00eda no puedo hacerlo&#8221;, se r\u00ede Guido. Principalmente quiere sorprenderse a s\u00ed mismo durante su primer Mundial. El atleta quiere mejorar su r\u00e9cord personal &#8220;comiendo lo suficiente, manteniendo una actitud positiva, socializando para distraerse y descansando un poco por la noche&#8221; durante la competici\u00f3n.<\/p>\n<p>El actual r\u00e9cord mundial lo ostenta el estadounidense Harvey Lewis (48). Corri\u00f3 724 kil\u00f3metros en 4,5 d\u00edas. Guido sue\u00f1a con alg\u00fan d\u00eda batir ese r\u00e9cord. \u00c9l cree que la mentalidad correcta es la clave del \u00e9xito. &#8220;Si te lo propones, llegar\u00e1s m\u00e1s lejos de lo que crees&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nhnieuws.nl\/nieuws\/341346\/meer-dan-200-kilometer-hardlopen-guido-doet-mee-aan-het-wk-backyard-ultra-running\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-55<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El deportista alterna distancias cortas con largas durante su entrenamiento. Est\u00e1 convencido de que una carrera ultra es<\/p>\n","protected":false},"author":1,"featured_media":1390603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[44556,21836,22570,11979,16,2282,13832,10186,10873],"class_list":["post-1390602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-backyard","tag-corriendo","tag-guido","tag-kilometros","tag-mas","tag-mundial","tag-participa","tag-running","tag-ultra"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390602"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390603"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}