{"id":1390441,"date":"2024-10-06T08:03:29","date_gmt":"2024-10-06T08:03:29","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-premio-groninger-de-arquitectura-2024-es-para-el-promotor-asser-los-creditos-son-para-el-arquitecto-y-el-contratista\/"},"modified":"2024-10-06T08:03:35","modified_gmt":"2024-10-06T08:03:35","slug":"el-premio-groninger-de-arquitectura-2024-es-para-el-promotor-asser-los-creditos-son-para-el-arquitecto-y-el-contratista","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-premio-groninger-de-arquitectura-2024-es-para-el-promotor-asser-los-creditos-son-para-el-arquitecto-y-el-contratista\/","title":{"rendered":"El Premio Groninger de Arquitectura 2024 es para el promotor Asser: &#8216;Los cr\u00e9ditos son para el arquitecto y el contratista&#8217;"},"content":{"rendered":"\n<div __component=\"api.api-text\" type=\"text\" id=\"da78873e-e749-470b-b6b4-a98cd5ce3170\" data-v-4f5883d4=\"\" data-v-26349d05=\"\">\n<p>Una fachada aut\u00e9ntica, 29 apartamentos, todos \u00fanicos, y adyacentes a un patio monumental. Todo eso en el coraz\u00f3n de Groningen. Fue suficiente para que un jurado profesional concediera el Premio Groninger de Arquitectura 2024 al nuevo Werkmanhof, que inclu\u00eda un estudio de Wibra, Scapino y textiles. Y ese premio es para el desarrollador de proyectos RE-Z Development de Assen. &#8220;Pero esto nunca hubiera sido posible sin el arquitecto y el contratista&#8221;, afirma la clienta Ellen van Acht de Assen.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"5f012e66-0513-4d6d-8bf9-0d07e0e60fe7\" data-v-4f5883d4=\"\" data-v-26349d05=\"\">\n<p>Cada a\u00f1o, un jurado cambiante elige un edificio que pueda grabar el premio en su fachada. Para ello, primero se elabora una lista corta. Este a\u00f1o consta de nueve proyectos de construcci\u00f3n. Es especial que el premio sea para el desarrollador de Asser. &#8220;En Groningen se est\u00e1n construyendo muchos buenos proyectos&#8221;, afirma Van Acht.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"505e50e5-0832-464c-9e52-350b6f67e2cc\" data-v-4f5883d4=\"\" data-v-26349d05=\"\">\n<p>A\u00fan as\u00ed, el premio fue para el Werkmanhof. Seg\u00fan el informe oficial del jurado, porque el proyecto &#8220;irradia calidad y artesan\u00eda&#8221;. Adem\u00e1s, ninguno de los 29 apartamentos del edificio es igual. Son &#8216;hogares especiales en un lugar especial&#8217;. El jurado tambi\u00e9n opina que el edificio seguir\u00e1 siendo hermoso incluso despu\u00e9s de 100 a\u00f1os. No s\u00f3lo porque la fachada encaja perfectamente en el edificio existente, sino tambi\u00e9n por el entorno de vida interior.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"efec5662-dcd7-444f-8739-4bb50f5eb91a\" data-v-4f5883d4=\"\" data-v-26349d05=\"\">\n<p><em>La historia contin\u00faa debajo de las fotos de las obras del Werkmanhof<\/em><\/p>\n<p> <!----><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rtvdrenthe.nl\/nieuws\/16885802\/groninger-architectuurprijs-2024-naar-asser-ontwikkelaar-credits-zijn-voor-architect-en-aannemer\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-41<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una fachada aut\u00e9ntica, 29 apartamentos, todos \u00fanicos, y adyacentes a un patio monumental. Todo eso en el coraz\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":1390442,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[27712,18220,14458,6603,29820,14812,257052,36580,36,14131,18,2761,257053,14833,1932],"class_list":["post-1390441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-arquitecto","tag-arquitectura","tag-asser","tag-cenizas","tag-contratista","tag-creditos","tag-elena-de-ocho","tag-groninger","tag-los","tag-municipio-de-assen","tag-para","tag-premio","tag-premio-de-arquitectura-groninger-2024","tag-promotor","tag-son"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390441"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390442"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}