{"id":1390394,"date":"2024-10-06T07:16:33","date_gmt":"2024-10-06T07:16:33","guid":{"rendered":"https:\/\/teknomers.com\/es\/siempre-tuve-miedo-de-la-bomba-alivio-entre-los-holandeses-en-un-vuelo-de-repatriacion-desde-el-libano\/"},"modified":"2024-10-06T07:16:39","modified_gmt":"2024-10-06T07:16:39","slug":"siempre-tuve-miedo-de-la-bomba-alivio-entre-los-holandeses-en-un-vuelo-de-repatriacion-desde-el-libano","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/siempre-tuve-miedo-de-la-bomba-alivio-entre-los-holandeses-en-un-vuelo-de-repatriacion-desde-el-libano\/","title":{"rendered":"&#8220;Siempre tuve miedo de la bomba&#8221;: alivio entre los holandeses en un vuelo de repatriaci\u00f3n desde el L\u00edbano"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"has-drop-cap\">El s\u00e1bado por la tarde, a las nueve menos cuarto, Abdallah Alawa (39), del sur de Rotterdam, recibe un mensaje de su cu\u00f1ado: han aterrizado. Pero no en el aeropuerto de Eindhoven, donde ahora espera con su esposa en la sala de llegadas, que de otro modo estar\u00eda bastante vac\u00eda. El vuelo de repatriaci\u00f3n en el que el gobierno trajo a los holandeses desde el L\u00edbano, con sus suegros y su cu\u00f1ado a bordo, est\u00e1 en tierra en la base a\u00e9rea de Eindhoven. Eso es algo diferente.<\/p>\n<p>Entonces regresan por las puertas giratorias y entran en los coches. \u00c9l en casa del suegro, ella en su propio coche. Google Maps tambi\u00e9n los env\u00eda mal. Hay que retroceder un poco, dice un agente en una caseta cerca de las barreras. Luego gira a la izquierda y contin\u00faa recto hasta llegar all\u00ed.<\/p>\n<p>Y esta semana ya fue &#8220;estresante&#8221;, dice Alawa. Sus suegros volaron al L\u00edbano hace m\u00e1s de tres semanas, antes de que comenzara \u201ctodo ese drama\u201d. Se refiere a las crecientes tensiones entre Hezbollah e Israel, donde Israel &#8211; adem\u00e1s de una operaci\u00f3n terrestre en el sur del pa\u00eds &#8211; lleva a cabo intensos ataques a\u00e9reos contra objetivos en el L\u00edbano.<\/p>\n<h2 class=\"gn4-crosshead wp-block-heading article-heading\" data-styled=\"false\">Vuelos programados cancelados<\/h2>\n<p>La idea era pasar unas vacaciones con la familia en la ciudad costera de Qalamoun, justo debajo de Tr\u00edpoli y a una hora en coche de la capital, Beirut. Pero el vuelo de regreso, previsto para el mi\u00e9rcoles pasado, fue cancelado. Tambi\u00e9n probaron un nuevo vuelo regular y el viaje en barco tur\u00edstico entre Tr\u00edpoli y Turqu\u00eda, que luego reservaron a toda prisa. Los llamaba mucho y le mandaban mensajes. \u201cQue oyeron cohetes\u201d, dice Alawa, \u201cy que no sab\u00edan si podr\u00edan regresar\u201d.<\/p>\n<p>Tiene ojeras y est\u00e1 visiblemente cansado. &#8220;Bastante dif\u00edcil&#8221;, dice.<\/p>\n<p>Despu\u00e9s de que el Ministerio de Asuntos Exteriores anunciara dos vuelos de repatriaci\u00f3n a principios de esta semana, la familia de Alawa dio a conocer inmediatamente. Esperaban poder unirse a nosotros el viernes, cuando despegara el primer vuelo. \u201cPero no los llamaron. Primero te tienen que llamar para confirmar que tu solicitud est\u00e1 en orden, y eso no sucedi\u00f3\u201d. Eso no sucedi\u00f3 hasta el s\u00e1bado por la ma\u00f1ana. &#8220;Realmente de \u00faltimo minuto&#8221;.<\/p>\n<p><dmt-icon class=\"dmt-article-suggestion__icon\" name=\"ic-forward\"\/><\/p>\n<div class=\"dmt-article-suggestion__text\">\n<p>\t\t\t\tLea tambi\u00e9n\n\t\t\t<\/p>\n<p><span>El gobierno sigue expulsando a los holandeses del L\u00edbano, bajo presi\u00f3n de la oposici\u00f3n<\/span>\n<\/div>\n<p>Su esposa ha caminado hacia la cinta azul, m\u00e1s tarde caminar\u00e1n detr\u00e1s de ella. En el vest\u00edbulo esperan varias decenas de personas, algunas con un ramo de flores en la mano. Hay caf\u00e9 y t\u00e9, galletas y un mostrador con empleados detr\u00e1s con chalecos fluorescentes y con la palabra \u201cMunicipio\u201d escrita en may\u00fasculas en la espalda.<\/p>\n<p>\u00bfAlawa todav\u00eda est\u00e1 nervioso ahora? No, dice, ahora todo estar\u00e1 bien.<\/p>\n<h2 class=\"gn4-crosshead wp-block-heading article-heading\" data-styled=\"false\">Sudadera roja con capucha<\/h2>\n<p>El Ministerio de Asuntos Exteriores decidi\u00f3 el martes &#8220;ayudar activamente a los holandeses&#8221; a salir del L\u00edbano. Dos vuelos de repatriaci\u00f3n con un Airbus A330 de la OTAN, uno el viernes y otro el s\u00e1bado. Quienes quisieran participar pod\u00edan inscribirse en el Ministerio de Asuntos Exteriores hasta el viernes por la tarde. El primer vuelo aterriz\u00f3 en Eindhoven el viernes por la noche con 185 personas a bordo. Otras 170 personas fueron trasladadas en avi\u00f3n desde Beirut a Eindhoven el s\u00e1bado. En ambas ocasiones fueron algo m\u00e1s de cien personas las que acudieron a la llamada y pudieron acreditar que son holandeses o que viajar\u00edan con un holand\u00e9s como pareja o hijo.<\/p>\n<p>El resto de pasajeros fueron repatriados a petici\u00f3n de otros pa\u00edses: belgas, irlandeses y finlandeses acompa\u00f1ados el viernes, franceses, belgas, espa\u00f1oles y austriacos el s\u00e1bado. \u201cOtros pa\u00edses tienen sus propios vuelos\u201d, explic\u00f3 el s\u00e1bado por la ma\u00f1ana un portavoz del ministerio, \u201cpero tambi\u00e9n existe cooperaci\u00f3n internacional. As\u00ed es como funciona. Queremos hacer un uso \u00f3ptimo de la capacidad\u201d. En el segundo vuelo tambi\u00e9n viajaban el periodista belga Robin Ramaekers y su camar\u00f3grafo Stijn De Smet; Estaban en el L\u00edbano para VTM News y resultaron heridos en Beirut a principios de esta semana.<\/p>\n<blockquote class=\"dmt-quote dmt-quote--type-streamer\" data-styled=\"false\">\n<p>El s\u00e1bado tambi\u00e9n estuvieron a bordo el periodista belga Robin Ramaekers y su camar\u00f3grafo Stijn De Smet; resultaron heridos en Beirut esta semana<\/p>\n<footer class=\"dmt-quote__attribution\">\n<\/footer>\n<\/blockquote>\n<p>Entre los primeros en entrar a la sala desde el avi\u00f3n se encuentra un beb\u00e9, de no m\u00e1s de unos d\u00edas de nacido, vestido con un traje de oso blanco y una manta. La madre que recientemente dio a luz es francesa y el personal del aeropuerto r\u00e1pidamente intenta conseguirle una silla de ruedas.<\/p>\n<p>Luego: una familia de cinco personas con un carrito de aeropuerto lleno de maletas. El hijo mayor habla algo de ingl\u00e9s. <em>\u201cVinimos aqu\u00ed por la guerra\u201d<\/em>les dice a la gente detr\u00e1s del mostrador. Les gustar\u00eda ir a Amsterdam. \u00bfPorque tienen familia all\u00ed? As\u00ed que llama a un taxi. No, los empleados entienden despu\u00e9s de cierta confusi\u00f3n ling\u00fc\u00edstica, a pesar de que hay un int\u00e9rprete conectado: ahora no hay familiares ni conocidos a quienes puedan acudir. Entonces tienen que ser alojados en alg\u00fan lugar esta noche. El Hotel Pullman podr\u00eda ser posible aqu\u00ed en Eindhoven.<\/p>\n<p><dmt-image-wrapper class=\"vorm__article-content-positioned\"><\/p>\n<figure data-captionposition=\"auto\" data-fadein=\"false\" data-fadeinduration=\"0.5\" data-variant=\"article\"><picture><source  type=\"image\/webp\"\/><img alt=\"\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728179857_8_Alli-no-habia-comida-ni-gasolina-ni-electricidad-alivio-para.jpg\" src-webp=\"https:\/\/images.nrc.nl\/KV89W0sSa45HHQR4w5WaByCc0DA=\/1920x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/wp-content\/uploads\/2024\/10\/06030502\/ANP-510171859.jpg\" data-lightbox-zoom=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728179857_8_Alli-no-habia-comida-ni-gasolina-ni-electricidad-alivio-para.jpg\" data-lightbox-zoom-webp=\"https:\/\/images.nrc.nl\/KV89W0sSa45HHQR4w5WaByCc0DA=\/1920x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/wp-content\/uploads\/2024\/10\/06030502\/ANP-510171859.jpg\" data-open-in-lightbox=\"\" decoding=\"async\" height=\"3669\" loading=\"lazy\"  width=\"5500\"\/><\/picture><figcaption class=\"description\">Una familia de cinco miembros el s\u00e1bado por la tarde tras la llegada del vuelo de repatriaci\u00f3n procedente del L\u00edbano a la base a\u00e9rea de Eindhoven.<\/figcaption><figcaption class=\"credit\">Foto Rob Engelaar \/ ANP <\/figcaption><\/figure>\n<p><\/dmt-image-wrapper><\/p>\n<p>&#8220;\u00bfTienes fr\u00edo?&#8221; \u2014le pregunta otra mujer con chaleco a la m\u00e1s joven del grupo, una ni\u00f1a de unos seis a\u00f1os. Ella solo usa pantalones cortos y una camisa delgada de color azul claro. &#8220;\u00bfQuieres algo caliente?&#8221; Ella consigue una sudadera con capucha roja descolorida de Levi&#8217;s, su hermano una gris negra con un estampado. <em>Colosos: Campamento de los Gigantes<\/em>una monta\u00f1a rusa de madera en Heide-Park Soltau, Alemania.<\/p>\n<p>La familia de Abdallah Alawa y su esposa est\u00e1n en el \u00faltimo grupo en entrar al sal\u00f3n. Lo graba con su tel\u00e9fono y luego le da tres besos en la mejilla a su madre. Abraza a su suegro, dos fuertes palmadas en el om\u00f3plato.<\/p>\n<p>\u201cSiempre tuve miedo de la bomba que hab\u00eda all\u00ed\u201d, dice el suegro, Mohammed Alawa (57), cuando terminan los saludos. &#8220;All\u00ed no hab\u00eda comida, ni gas, ni electricidad&#8221;. Sus padres y su hermano, que viven en el L\u00edbano, todav\u00eda est\u00e1n all\u00ed. No tienen pasaporte holand\u00e9s.<\/p>\n<p>\u00bfY ahora? \u00bfC\u00f3mo se siente?<\/p>\n<p>&#8220;\u00bfAhora? \u00bfAqu\u00ed?&#8221; Se\u00f1ala el suelo con ambos dedos \u00edndices. &#8220;Aliviado.&#8221;<\/p>\n<p><dmt-icon class=\"dmt-article-suggestion__icon\" name=\"ic-forward\"\/><\/p>\n<div class=\"dmt-article-suggestion__text\">\n<p>\t\t\t\tLea tambi\u00e9n\n\t\t\t<\/p>\n<p><span>Una vez huyeron al L\u00edbano. Ahora los sirios huyen a su devastado pa\u00eds debido a una nueva guerra.<\/span>\n<\/div>\n<p><img decoding=\"async\" alt=\"Mantas sobre un coche de personas que huyen del L\u00edbano y regresan a Siria, en el paso fronterizo de Masnaa. El paso fronterizo fue bombardeado por Israel el viernes por la ma\u00f1ana.   \" class=\"dmt-article-suggestion__image\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/10\/1728179857_762_Alli-no-habia-comida-ni-gasolina-ni-electricidad-alivio-para.jpg\"\/><\/p>\n<p><dmt-util-bar article=\"4868312\" headline=\"\u2018Steeds was ik bang voor de bom\u2019: opluchting onder Nederlanders op repatri\u00ebringsvlucht uit Libanon\" url=\"https:\/\/www.nrc.nl\/nieuws\/2024\/10\/06\/steeds-was-ik-bang-voor-de-bom-opluchting-onder-nederlanders-op-repatrieringsvlucht-uit-libanon-a4868312\"><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"share\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">para compartir<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-share-web\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"contact\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Env\u00ede un correo electr\u00f3nico al editor<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-email\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<\/dmt-util-bar> <\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2024\/10\/06\/steeds-was-ik-bang-voor-de-bom-opluchting-onder-nederlanders-op-repatrieringsvlucht-uit-libanon-a4868312\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado por la tarde, a las nueve menos cuarto, Abdallah Alawa (39), del sur de Rotterdam, recibe<\/p>\n","protected":false},"author":1,"featured_media":1390189,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12748,2613,2479,372,7879,33279,36,1137,42178,221,14688,2509],"class_list":["post-1390394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-alivio","tag-bomba","tag-desde","tag-entre","tag-holandeses","tag-libano","tag-los","tag-miedo","tag-repatriacion","tag-siempre","tag-tuve","tag-vuelo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1390394"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1390394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1390189"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1390394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1390394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1390394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}